{"id":9824,"date":"2013-09-27T04:44:36","date_gmt":"2013-09-27T03:44:36","guid":{"rendered":"http:\/\/www.emiliosilveravazquez.com\/blog\/?p=9824"},"modified":"2013-09-27T04:44:36","modified_gmt":"2013-09-27T03:44:36","slug":"sabemos-como-evoluciona-el-universo-observando-las-estrellas","status":"publish","type":"post","link":"https:\/\/www.emiliosilveravazquez.com\/blog\/2013\/09\/27\/sabemos-como-evoluciona-el-universo-observando-las-estrellas\/","title":{"rendered":"Sabemos c\u00f3mo evoluciona el Universo, observando las estrellas"},"content":{"rendered":"<p style=\"text-align: justify;\">Hace alg\u00fan tiempo que sali\u00f3 la noticia en los medios: &#8220;Un equipo de cient\u00edficos europeos, entre ellos investigadores del Instituto de Astrof\u00edsica de Canarias (IAC), ha hecho p\u00fablicos los resultados de 30 a\u00f1os de investigaci\u00f3n sobre la estrella hipergigante HR 8752, que han revelado el eslab\u00f3n perdido en la evoluci\u00f3n de este tipo de astros.Concretamente, han descubierto que, la regi\u00f3n inestable conocida como Vac\u00edo Evolutivo Amarillo, puede cambiar profundamente la evoluci\u00f3n de una estrella ya que, en estas tres d\u00e9cadas, HR 8752 ha aumentado de forma espectacular su temperatura superficial en 3.000 Kelvin (K) a su paso por esta regi\u00f3n.&#8221;<\/p>\n<p style=\"text-align: justify;\">Los resultados obtenidos ven\u00edan a desvelar algunos misterios que antes, no ten\u00edan explicaci\u00f3n.<\/p>\n<div id=\"foto_prensa\" style=\"text-align: justify;\"><img decoding=\"async\" src=\"http:\/\/www.iac.es\/img\/resultados\/resultados103_108.jpg\" alt=\"Imagen ampliada\" \/><\/div>\n<div style=\"text-align: justify;\">La estrella hipergigante HR 8752 atravesando el Vac\u00edo Evolutivo Amarillo (YEV, por sus siglas en ingl\u00e9s) en una recreaci\u00f3n art\u00edstica. La gr\u00e1fica muestra el aumento de temperatura que ha sufrido la superficie de la estrella en las \u00faltimas d\u00e9cadas. \/\u00a9 A.Lobel-ROB. SRON.<\/div>\n<div style=\"text-align: justify;\">Informaron sobre el hallazgo y dieron los detalles: &#8220;Las hipergigantes &#8211;de las que solo se conocen 12 en la V\u00eda L\u00e1ctea&#8211;son las estrellas m\u00e1s luminosas que se conocen en la actualidad en el universo. Pueden llegar a ser hasta millones de veces m\u00e1s brillantes que el <a title=\"Sol\" href=\"http:\/\/noticias.lainformacion.com\/juan-cruz-sol\/P_5WrMHjW4sOHyrtfGkIEXs6\/\"><strong>Sol<\/strong><\/a> y tener un tama\u00f1o de varios cientos de radios solares, con temperaturas superficiales de entre los 3.500 K y los 35.000 K. En concreto, HR 8752 es unas 250.000 veces m\u00e1s luminosa que el Sol y puede ser observada con prism\u00e1ticos en la constelaci\u00f3n del hemisferio norte de <a title=\"Casiopea\" href=\"http:\/\/noticias.lainformacion.com\/casiopea\/P_H14YSVQQt8uvVIBWaN8aG1\/\"><strong>Casiopea<\/strong><\/a>.&#8221;<\/div>\n<div style=\"text-align: justify;\"><img decoding=\"async\" loading=\"lazy\" src=\"http:\/\/upload.wikimedia.org\/wikipedia\/commons\/thumb\/f\/fe\/Sun_and_VY_Canis_Majoris.svg\/800px-Sun_and_VY_Canis_Majoris.svg.png\" alt=\"File:Sun and VY Canis Majoris.svg\" width=\"800\" height=\"500\" \/><\/div>\n<div style=\"text-align: justify;\">\u00a0\u00a0\u00a0\u00a0 Comparaci\u00f3n entre los tama\u00f1os del <a title=\"Sol\" href=\"http:\/\/es.wikipedia.org\/wiki\/Sol\">Sol<\/a> y <a title=\"VY Canis Majoris\" href=\"http:\/\/es.wikipedia.org\/wiki\/VY_Canis_Majoris\">VY Canis Majoris<\/a>, una hipergigante. Se trata de la estrella roja m\u00e1s grande conocida. Cuando miramos la rese\u00f1a de este tipo de estrellas, en casi cualquier sitio que podamos mirar nos dicen algo parecido a esto:<\/div>\n<blockquote>\n<div style=\"text-align: justify;\">&#8220;Una <strong>hipergigante<\/strong> (<em>hypergiant<\/em> en ingl\u00e9s) es una <a title=\"Estrella\" href=\"http:\/\/es.wikipedia.org\/wiki\/Estrella\">estrella<\/a> excepcionalmente grande y masiva, incluso mayor que una <a title=\"Supergigante\" href=\"http:\/\/es.wikipedia.org\/wiki\/Supergigante\">supergigante<\/a>. Su masa puede ser de hasta 1000 veces la masa de nuestro <a title=\"Sol\" href=\"http:\/\/es.wikipedia.org\/wiki\/Sol\">Sol<\/a>, pr\u00f3xima al l\u00edmite m\u00e1ximo te\u00f3rico, el cual establece que la cantidad de masa en una estrella no puede exceder las 120\u00a0<a title=\"Masa solar\" href=\"http:\/\/es.wikipedia.org\/wiki\/Masa_solar\">M<sub>\u2609<\/sub> (masas solares)<\/a>. Este l\u00edmite en masa est\u00e1 asociado a la <a title=\"L\u00edmite de Eddington\" href=\"http:\/\/es.wikipedia.org\/wiki\/L%C3%ADmite_de_Eddington\">luminosidad de Eddington<\/a>, por el que estrellas m\u00e1s masivas simplemente no pueden estar en equilibrio al vencer la <a title=\"Presi\u00f3n de radiaci\u00f3n\" href=\"http:\/\/es.wikipedia.org\/wiki\/Presi%C3%B3n_de_radiaci%C3%B3n\">presi\u00f3n de radiaci\u00f3n<\/a> interna a la <a title=\"Gravedad\" href=\"http:\/\/es.wikipedia.org\/wiki\/Gravedad\"><a href=\"#\" onclick=\"referencia('fuerza gravitacional',event); return false;\">fuerza gravitacional<\/a><\/a>: producir\u00edan tanta energ\u00eda que se desprender\u00edan de la masa en exceso de las 120\u00a0M<sub>\u2609<\/sub>. Aun as\u00ed, algunas hipergigantes aparentan tener m\u00e1s de 100\u00a0M<sub>\u2609<\/sub> e, inclusive, haber tenido, inicialmente, entre 200 y 250\u00a0M<sub>\u2609<\/sub>, al contrario de lo que predicen las teor\u00edas actuales sobre la <a title=\"Formaci\u00f3n estelar\" href=\"http:\/\/es.wikipedia.org\/wiki\/Formaci%C3%B3n_estelar\">formaci\u00f3n<\/a> y <a title=\"Evoluci\u00f3n estelar\" href=\"http:\/\/es.wikipedia.org\/wiki\/Evoluci%C3%B3n_estelar\">evoluci\u00f3n estelar<\/a>.&#8221;<\/div>\n<\/blockquote>\n<div style=\"text-align: justify;\"><img decoding=\"async\" loading=\"lazy\" id=\"il_fi\" src=\"http:\/\/apod.nasa.gov\/apod\/image\/0603\/etacar_hst.jpg\" alt=\"\" width=\"640\" height=\"480\" \/><\/div>\n<div style=\"text-align: justify;\">Lo que m\u00e1s arriba se explica, es decir, que cuando una estrella tiene m\u00e1s de 120 masas solares, su propia radiaci\u00f3n la podr\u00eda destruir y, para evitarlo, eyecta material estelar al espacio evitando su propia destrucci\u00f3n.<\/div>\n<div style=\"text-align: justify;\">Eta Carinae podr\u00eda estar a punto de explotar. Pero nadie sabe cu\u00e1ndo -lo mismo podr\u00eda ser ma\u00f1ana que tardar cientos de miles o millones de a\u00f1os- Eta Carinae es una de edsas estrellas masiva\u00a0 &#8211; aproximadamente 100 veces mayor que nuestro Sol &#8211; hace que sea un excelente candidato para una supernova que sembrar\u00e1 el espacio interestelar de gas y polvo y materiales complejos del que, de nuevo, volver\u00e1n a surgir estrellas y mundos. Los registros hist\u00f3ricos muestran que hace unos 150 a\u00f1os Eta Carinae sufri\u00f3 una explosi\u00f3n inusual que la convirti\u00f3 en una de las estrellas m\u00e1s brillantes del cielo austral.<\/div>\n<div style=\"text-align: justify;\">Eta Carinae, en la Nebulosa Keyhole, es la \u00fanica estrella en la que actualmente se han detectado emisiones de luz LASER de manera natural. La imagen de arriba fue tomada en 1996, fue resultado de sofisticadas combinaciones de procesamiento de im\u00e1genes y los procedimientos dise\u00f1ados para llevar a cabo nuevos detalles de la nebulosa que rodea a esta inusual estrella perdida entre las brumas del material que eyecta para evitar su muerte. Ahora son claramente visibles dos l\u00f3bulos, una regi\u00f3n central caliente, y extra\u00f1as rayas radiales. Los l\u00f3bulos est\u00e1n llenos de carriles de gas y polvo que absorben la luz azul y ultravioleta emitida cerca del centro. Las rayas siguen sin explicaci\u00f3n. \u00bfEstos indicios nos dicen c\u00f3mo se form\u00f3 la nebulosa? \u00bf Sabremos alg\u00fan d\u00eda cuando Eta Carinae explotar\u00e1?<\/div>\n<div style=\"text-align: justify;\"><img decoding=\"async\" loading=\"lazy\" title=\"\" src=\"http:\/\/ep01.epimg.net\/sociedad\/imagenes\/2010\/07\/21\/actualidad\/1279663206_850215_0000000000_noticia_normal.jpg\" alt=\"\" width=\"560\" height=\"190\" \/><\/div>\n<div style=\"text-align: justify;\">Debajo de estas im\u00e1genes, en la prensa se pudio leer: &#8220;Descubierta una estrella monstruosa con 300 veces la masa del Sol, el astro rompe todos los r\u00e9cords y previsiones te\u00f3ricas. Una estrella de 300 veces la masa de nuestro Sol es algo no s\u00f3lo nunca visto hasta ahora sino tambi\u00e9n completamente inesperado para los astr\u00f3nomos, que estimaban el l\u00edmite m\u00e1ximo de masa en unas 150 veces la solar. Pero la han encontrado. Todav\u00eda se la conoce s\u00f3lo por su anodino nombre oficial, R136a, y la han localizado unos cient\u00edficos en la nebulosa Tar\u00e1ntula, de la galaxia vecina Gran Nube de Magallanes, a unos 165.000 a\u00f1os luz de distancia de la Tierra. &#8220;La existencia de un monstruo as\u00ed, millones de veces m\u00e1s luminoso que el Sol, y perdiendo peso por los intensos vientos estelares, puede ayudarnos a responder una pregunta clave. \u00bfC\u00f3mo de masivas pueden ser las estrellas?&#8221;.<\/div>\n<div style=\"text-align: justify;\"><img decoding=\"async\" loading=\"lazy\" id=\"il_fi\" src=\"http:\/\/www.elpais.com\/recorte\/20100721elpepusoc_4\/XXLCO\/Ies\/Tamanos_estelares.jpg\" alt=\"\" width=\"738\" height=\"415\" \/><\/div>\n<div style=\"text-align: justify;\">Una estrella <a href=\"#\" onclick=\"referencia('enana roja',event); return false;\">enana roja<\/a> que son las m\u00e1s abundantes del Universo y las que tienen mayor edad. Otra estrella como nuestro Sol, una estrella celeste claro supermasiva y otra \u00faltima de dimensiones inconmensurables. Las estrellas que han sido profundamente estudiadas en todas sus variantes, formas y colores, tienen a\u00fan algunos secretos que tenenos que desvelar.<\/div>\n<div style=\"text-align: justify;\">Alguna vez me he referido aqu\u00ed a R. Leporis, que es un capricho estelar. En el espacio existen muchas estrellas que, de poder saber de ellas nos dejar\u00edan sumidos en el mayor de los asombros. Las hay de Carbobo como R. Lepori, de Circonio, de Litio, de Manganeso, de estroncio, de Helio, de bario, de manganeso-mercurio, de metales pesados, de silicio, de tecnecio, de <a href=\"#\" onclick=\"referencia('neutron',event); return false;\">neutrones<\/a>, y&#8230; \u00bfpor qu\u00e9 no podr\u00eda incluso existir algunas de Quarks?<\/div>\n<div style=\"text-align: justify;\">\n<p><img decoding=\"async\" loading=\"lazy\" src=\"http:\/\/3.bp.blogspot.com\/_9Bhzk6QTrKI\/TKficGNlB0I\/AAAAAAAAAAM\/YjTGrfyZGbc\/s1600\/enana+roja.jpg\" alt=\"\" width=\"435\" height=\"295\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Aqu\u00ed tenemos a R Leporis, una estrella de Carbono a la que se puso el nombre de la \u201cEstrella Carmes\u00ed\u201d, o, la \u201cGota de Sangre\u201d.<\/p>\n<p><strong>R Leporis<\/strong> (R Lep \/ HD 31996 \/ HR 1607) es una <a title=\"Estrella variable\" href=\"http:\/\/es.wikipedia.org\/wiki\/Estrella_variable\">estrella variable<\/a> de la <a title=\"Constelaci\u00f3n\" href=\"http:\/\/es.wikipedia.org\/wiki\/Constelaci%C3%B3n\">constelaci\u00f3n<\/a> de <a title=\"Lepus (constelaci\u00f3n)\" href=\"http:\/\/es.wikipedia.org\/wiki\/Lepus_%28constelaci%C3%B3n%29\">Lepus<\/a>, cerca del l\u00edmite con <a title=\"Eridanus\" href=\"http:\/\/es.wikipedia.org\/wiki\/Eridanus\">Eridanus<\/a>. Visualmente es una estrella de un color rojo v\u00edvido, cuyo brillo var\u00eda entre <a title=\"Magnitud aparente\" href=\"http:\/\/es.wikipedia.org\/wiki\/Magnitud_aparente\">magnitud aparente<\/a> +5,5 y +11,7. Descubierta por <a title=\"John Russell Hind\" href=\"http:\/\/es.wikipedia.org\/wiki\/John_Russell_Hind\">John Russell Hind<\/a> en <a title=\"1845\" href=\"http:\/\/es.wikipedia.org\/wiki\/1845\">1845<\/a>, es tambi\u00e9n conocida como <strong>Estrella carmes\u00ed de Hind<\/strong>.<\/p>\n<\/div>\n<div style=\"text-align: justify;\">A una distancia aproximada de 1100 <a title=\"A\u00f1o luz\" href=\"http:\/\/es.wikipedia.org\/wiki\/A%C3%B1o_luz\">a\u00f1os luz<\/a>, R Leporis pertenece a la rara clase de <a title=\"Estrella de carbono\" href=\"http:\/\/es.wikipedia.org\/wiki\/Estrella_de_carbono\">estrellas de carbono<\/a>, siendo su <a title=\"Tipo espectral\" href=\"http:\/\/es.wikipedia.org\/wiki\/Tipo_espectral\">tipo espectral<\/a> C6. En estas estrellas, los compuestos de carbono no permiten pasar la luz azul, por lo que tienen un color rojo intenso. En R Leporis la relaci\u00f3n <a title=\"Carbono\" href=\"http:\/\/es.wikipedia.org\/wiki\/Carbono\">carbono<\/a>&#8211;<a title=\"Ox\u00edgeno\" href=\"http:\/\/es.wikipedia.org\/wiki\/Ox%C3%ADgeno\">ox\u00edgeno<\/a> estimada es 1,2, m\u00e1s del doble que la existente en el <a title=\"Sol\" href=\"http:\/\/es.wikipedia.org\/wiki\/Sol\">Sol<\/a>. Tiene un <a title=\"Radio (geometr\u00eda)\" href=\"http:\/\/es.wikipedia.org\/wiki\/Radio_%28geometr%C3%ADa%29\">radio<\/a> entre 480 y 535 veces m\u00e1s grande que el <a title=\"Radio solar\" href=\"http:\/\/es.wikipedia.org\/wiki\/Radio_solar\">radio solar<\/a>, equivalente a 2,2 \u2013 2,5 <a title=\"Unidad astron\u00f3mica\" href=\"http:\/\/es.wikipedia.org\/wiki\/Unidad_astron%C3%B3mica\">UA<\/a>. Si estuviese en el centro del <a title=\"Sistema Solar\" href=\"http:\/\/es.wikipedia.org\/wiki\/Sistema_Solar\">Sistema Solar<\/a>, su superficie se extender\u00eda m\u00e1s all\u00e1 de la <a title=\"\u00d3rbita\" href=\"http:\/\/es.wikipedia.org\/wiki\/%C3%93rbita\">\u00f3rbita<\/a> de <a title=\"Marte (planeta)\" href=\"http:\/\/es.wikipedia.org\/wiki\/Marte_%28planeta%29\">Marte<\/a>. Su temperatura superficial, extremadamente baja para una estrella, est\u00e1 comprendida entre 2050 y 2290 <a title=\"Kelvin\" href=\"http:\/\/es.wikipedia.org\/wiki\/Kelvin\">K<\/a>. Brilla con una <a title=\"Luminosidad\" href=\"http:\/\/es.wikipedia.org\/wiki\/Luminosidad\">luminosidad<\/a> entre 5200 y 7000 veces superior a la del Sol, siendo la mayor parte de la energ\u00eda radiada como <a title=\"Radiaci\u00f3n infrarroja\" href=\"http:\/\/es.wikipedia.org\/wiki\/Radiaci%C3%B3n_infrarroja\">radiaci\u00f3n infrarroja.<\/a><\/div>\n<div style=\"text-align: justify;\"><img decoding=\"async\" loading=\"lazy\" id=\"il_fi\" src=\"http:\/\/i686.photobucket.com\/albums\/vv228\/elevenmoons\/14.jpg?t=1255975043\" alt=\"\" width=\"631\" height=\"473\" \/><\/div>\n<div style=\"text-align: justify;\">En la imagen podemos contemplar como algo que nos parece tan enorme como el Sol, puede quedar empeque\u00f1ecido al lado de otros astros de cuya inmensidad ni pod\u00edamos imaginar que pudieran existir. Arriba Betelgeuse se exhibe presumida al lado de las otras estrellas que, siendo grandes y muy grandes, no piueden compararse a grandiosidad. Sin embargo, a\u00fan las hay mucho m\u00e1sa grandes que ella.<\/div>\n<div style=\"text-align: justify;\"><img decoding=\"async\" loading=\"lazy\" src=\"http:\/\/eliastor.files.wordpress.com\/2009\/07\/p318e.jpg\" alt=\"\" width=\"480\" height=\"337\" \/><\/div>\n<div style=\"text-align: justify;\">\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Ahora es Antares la que se puede pavonear ante las dem\u00e1s<\/div>\n<div>\n<p style=\"text-align: justify;\">Del grupo destaca Antares, una supergigante M 1,5, 10 000 veces m\u00e1s luminosa que el Sol y con un di\u00e1metro que es probablemente m\u00e1s de 500 veces el del Sol. Nos contempla desde 520 a.l. de distancia y tiene una compa\u00f1era enana. Su color es el rojo intenso.<\/p>\n<p style=\"text-align: justify;\">Aldebaran, la estrella Alfa Tauri, es una Gigante K5. Aparentemente forma parte del grupo de estrella de las Hyades, aunque en realidad s\u00f3lo est\u00e1 a 60 a.l., aprpoximadamente la mitad de la distancia del c\u00famulo.<\/p>\n<p style=\"text-align: justify;\">Betelgeuse, la estrella Alfa Orionis, la d\u00e9cima m\u00e1s brillante del cielo, es una gigante tipo M2 que es una variable semirregular. Se dice que est\u00e1 a unos 400 a.l. de la Tierra y su luminosidad es 5000 veces superior a la del Sol pero, si se encuentra a la misma distancia de la Asociaci\u00f3n de Ori\u00f3n (como algunos postulan), la luminosidad verdadera ser\u00eda de 50 000 veces la del Sol. Su di\u00e1metro es cientos de veces el del Sol. Su brillo var\u00eda a medida que se expande y contrae en tama\u00f1o.<\/p>\n<p style=\"text-align: justify;\">Arthurus es la estrella Alfa Bo\u00f6tis, magnitu -o,o4, la estrella m\u00e1s brillante al norte del ecuador celeste y la cuarta m\u00e1s brillante de todo el cielo. Es una gigante K 1 situada a 35 a.l.<\/p>\n<p style=\"text-align: justify;\">Rigel, la estrella Beta Orionis de magnitud o,12 es una gigante B 8 siatuada a 1 400 a.l., su luminosidad es de unas 150 000 veces la del Sol, tiene una compa\u00f1era de magnitud 6,8, que es a su vez una binaria espectrosc\u00f3pica.<\/p>\n<p style=\"text-align: justify;\">Al lado de estas gigantes, el Sol y otras estrellas resultan min\u00fasculos como podemos ver en la imagen y, sin embargo, ya sabemos todos la importancia que nuestro Sol tiene para hacer posible la vida en la Tierra.<\/p>\n<p style=\"text-align: justify;\">\u00a1No por peque\u00f1o se es insignificante! Ya sab\u00e9is: \u00a1Todo lo grande est\u00e1 hecho de cosas peque\u00f1as!<\/p>\n<p style=\"text-align: justify;\"><img decoding=\"async\" loading=\"lazy\" id=\"cboxPhoto\" src=\"http:\/\/estaticos.20minutos.es\/img\/2006\/12\/12\/539743.jpg\" alt=\"\" width=\"400\" height=\"644\" \/><\/p>\n<p style=\"text-align: justify;\">\u00a0\u00a0\u00a0\u00a0\u00a0 El grupo de tres estrellas gigantes Pismis 24-1 (C<a href=\"http:\/\/www.emiliosilveravazquez.com\/blog\/2012\/05\/04\/la-fascinacion-de-algunas-estrellas\/\"><a href=\"#\" onclick=\"referencia('unidades del si',event); return false;\">SI<\/a><\/a>C).<\/p>\n<p style=\"text-align: justify;\">Mucho antes de que Russell descubriera la estrella carmes\u00ed y Johannes Hevelius quedara fascinado por Mira, la estrella maravillosa, los astr\u00f3nomos \u00e1rabes se fijaron en una estrella de la constelaci\u00f3n de Perseo que cambiaba de brillo cada tres d\u00edas, con una pauta muy regular y acentuada. Los \u00e1rabes escribieron una de las escasas p\u00e1ginas destacadas de la astronom\u00eda medieval, paliando de alguna manera la importante decadencia que sufri\u00f3 esta ciencia en ese per\u00edodo en Europa y el Mediterr\u00e1neo en el periodo comprendido entre Ptolomeo y Cop\u00e9rnico, que dur\u00f3 un milenio y medio.<\/p>\n<p style=\"text-align: justify;\">Bueno, hablar aqu\u00ed de las estrellas que conocemos bien y de sus historias resulta entretenido y nos ense\u00f1a un poco de la historia estelar en objetos individuales y determinados que, por una u otra raz\u00f3n tienen destacadas razones para que los astr\u00f3nomos se fijaran en ellos. Por ejemplo, de Eta Carinae (antes mencionada y cuya imagen ten\u00e9is arriba), es una variable irregular hipergigante, que lleg\u00f3 a ser la segunda estrella m\u00e1s brillante del cielo. Es una variable azul luminosa con magnitud absoluta de -10, y es clasificada oficialmente como una estrella S Doradus. Se encuentra dentro de un c\u00famulo de estrellas masivas y una masa estimada en 100 masas solares, en tiempos se lleg\u00f3 a creer que era la estrella m\u00e1s masiva de la Galaxia. El \u00fanico espectro visible es el de la Nebulosa del Hom\u00fanculo que la rodea. Eta Carinae es una intensa fuente infrarroja y su importante p\u00e9rdida de masa (alrededor de 0,1 masas solares por a\u00f1o) tiene asociadas energ\u00edas pr\u00f3ximas a las de algunas supernovas y, teni\u00e9ndola a unos 8000 a\u00f1os-luz, lo mejor ser\u00e1 estar vigilante, ya que, aunque son distancias inmensas\u2026Nunca se sabe lo que un monstruo de ese calibre nos podr\u00eda enviar.<\/p>\n<p style=\"text-align: justify;\">Estrellas masivas como Eta Carionae, Betegeuse, Arthurus, Antares y tantas otras que ahora sabemos que existen nos llevan a saber que, cuando mueren, se pueden convertir en otros objetos distintos como, por ejemplo:<\/p>\n<p style=\"text-align: justify;\">Estrellas de Neutrones<\/p>\n<p style=\"text-align: justify;\"><img decoding=\"async\" loading=\"lazy\" src=\"http:\/\/3.bp.blogspot.com\/_KbVMQlF0iZo\/S8ccEpQLM_I\/AAAAAAAACmo\/4XcLJVP3-9Q\/s1600\/Estrella+Neutrones.jpg\" alt=\"\" width=\"600\" height=\"480\" \/><\/p>\n<p style=\"text-align: justify;\">Estrellas que se forman a partir de estrellas amasivas (2-3 masas solares) cuando al final de sus vidas, agotado el combustible nuclear de fusi\u00f3n, quedan a merced de la Gravedad que no se ve frenada por la fusi\u00f3n nuclear, y, en ese momento, la estrella comienza a contraerse bajo su propio peso, de forma tal que, los <a href=\"http:\/\/www.emiliosilveravazquez.com\/blog\/2012\/05\/04\/la-fascinacion-de-algunas-estrellas\/\">protones<\/a> y <a href=\"http:\/\/www.emiliosilveravazquez.com\/blog\/2012\/05\/04\/la-fascinacion-de-algunas-estrellas\/\">electrones<\/a>\u00a0 se funden y se convierten en <a href=\"http:\/\/www.emiliosilveravazquez.com\/blog\/2012\/05\/04\/la-fascinacion-de-algunas-estrellas\/\">neutrones<\/a> que, al verse comprimidos tan violentamente, y, no pudiendo permitirlo por el principio de esclusi\u00f3n de Pauli, se degeneran y y hacen frente a la fuerza gravitatoria, consiguiendo as\u00ed el equilibrio de lo que conocemos como estrella de nweutrones de intensom campo electromagn\u00e9tico y r\u00e1pida rotaci\u00f3n. Estos objetos, despu\u00e9s de los Agujeros Negros, son los m\u00e1s densos que se conocen en el Universo, y, su masa podr\u00eda pesar 10<sup>17<\/sup> Kg\/m<sup>3.<\/sup><\/p>\n<p style=\"text-align: justify;\">\u00bfEstrella de Quarks?<\/p>\n<p style=\"text-align: justify;\"><img decoding=\"async\" loading=\"lazy\" src=\"http:\/\/img.seti.cl\/i08-33-quarkstar.jpg\" alt=\"\" width=\"581\" height=\"450\" \/><\/p>\n<p style=\"text-align: justify;\">Es hipot\u00e9tica, a\u00fan no se ha observado ninguna pero se cree que pueden estar por ah\u00ed, y, si es as\u00ed, ser\u00edan mucho m\u00e1s densas que las de <a href=\"http:\/\/www.emiliosilveravazquez.com\/blog\/2012\/05\/04\/la-fascinacion-de-algunas-estrellas\/\">neutrones<\/a>, ya que, ni la degeneraci\u00f3n de los <a href=\"http:\/\/www.emiliosilveravazquez.com\/blog\/2012\/05\/04\/la-fascinacion-de-algunas-estrellas\/\">neutrones<\/a> podr\u00eda parar la Fuerza de la Gravedad que ser\u00eda frenada por los Quarks que tambi\u00e9n, son <a href=\"#\" onclick=\"referencia('fermion',event); return false;\">fermiones<\/a>.<\/p>\n<p style=\"text-align: justify;\">Si la estrella no es masiva, y tiene una masa como la del Sol, su final ser\u00e1 la de convertirse en una \u00a1Estrella Enana Blanca!<\/p>\n<p style=\"text-align: justify;\"><img decoding=\"async\" loading=\"lazy\" src=\"http:\/\/1.bp.blogspot.com\/_DvHSK-p7zDo\/R9WkQby8VbI\/AAAAAAAAAeQ\/H0VC8JWcxV0\/s320\/Estrella_neutrones.gif\" alt=\"\" width=\"311\" height=\"320\" \/><\/p>\n<p style=\"text-align: justify;\">Nuestro Sol es de esta clase de estrellas y, tampoco su densidad se queda corta, ya que, alcanzan 5 x 10<sup>8<\/sup> Kg\/m<sup>3<\/sup>. Aqu\u00ed, cuando la estrella implosiona y comienza a comprimirse bajo su propio peso por la fuerza de Gravedad, como ocurri\u00f3 con la estrella de Neutrones, aparece el Principio de Exclusi\u00f3n de Pauli, el cual postula que los <a href=\"http:\/\/www.emiliosilveravazquez.com\/blog\/2012\/05\/04\/la-fascinacion-de-algunas-estrellas\/\"><a href=\"#\" onclick=\"referencia('fermion',event); return false;\">fermiones<\/a><\/a> (los <a href=\"http:\/\/www.emiliosilveravazquez.com\/blog\/2012\/05\/04\/la-fascinacion-de-algunas-estrellas\/\">electrones<\/a> son <a href=\"http:\/\/www.emiliosilveravazquez.com\/blog\/2012\/05\/04\/la-fascinacion-de-algunas-estrellas\/\"><a href=\"#\" onclick=\"referencia('fermion',event); return false;\">fermiones<\/a><\/a>) no pueden ocupar el mismo lugar estando en posesi\u00f3n del mismo n\u00famero cu\u00e1ntico, y, siendo as\u00ed, se degeneran y hace que, la compresi\u00f3n de la estrella por la Gravedad se frene y vuelve el equilibrio que la convierte en estrellas <a href=\"http:\/\/www.emiliosilveravazquez.com\/blog\/2012\/05\/04\/la-fascinacion-de-algunas-estrellas\/\"><a href=\"#\" onclick=\"referencia('enana blanca',event); return false;\">enana blanca<\/a><\/a>.<a href=\"http:\/\/www.emiliosilveravazquez.com\/blog\/2012\/05\/04\/2011\/08\/21\/ano-internacional-de-la-astronomia-2009-en-espana-aia-iya2009-2\/\"><br \/>\n<\/a><\/p>\n<p style=\"text-align: justify;\">El fen\u00f3meno de convertirse en <a href=\"http:\/\/www.emiliosilveravazquez.com\/blog\/2012\/05\/04\/la-fascinacion-de-algunas-estrellas\/\"><a href=\"#\" onclick=\"referencia('enana blanca',event); return false;\">enana blanca<\/a><\/a> ocurre cuando la estrella original tiene una m\u00e1sa m\u00e1xima posible de 1,44 masas solares, el l\u00edmite de Shandrashekar, si fuera mayor se convertir\u00eda en estrella de <a href=\"http:\/\/www.emiliosilveravazquez.com\/blog\/2012\/05\/04\/la-fascinacion-de-algunas-estrellas\/\">neutrones<\/a>. Y, siendo mayor la masa de 3-4 masas solares, su destino ser\u00eda un <a href=\"http:\/\/www.emiliosilveravazquez.com\/blog\/2012\/05\/04\/la-fascinacion-de-algunas-estrellas\/\"><a href=\"#\" onclick=\"referencia('agujero negro',event); return false;\">agujero negro<\/a><\/a>.<\/p>\n<p style=\"text-align: justify;\"><img decoding=\"async\" loading=\"lazy\" id=\"il_fi\" src=\"http:\/\/es.unawe.org\/static\/archives\/images\/screen\/Chandra_pne.jpg\" alt=\"\" width=\"783\" height=\"392\" \/><\/p>\n<p style=\"text-align: justify;\">Nos despediremos con estas bellas im\u00e1genes de sendas Nebulosas Planetarias como, un d\u00eda lejano aun en el futuro, nos mostrar\u00e1 nuestro Sol al llegar al t\u00e9rmino de su vida. Ese ser\u00e1 su final: Una bonita Nebulosa Planetaria con una estrella <a href=\"#\" onclick=\"referencia('enana blanca',event); return false;\">enana blanca<\/a> en en el centro.<\/p>\n<p style=\"text-align: justify;\"><img decoding=\"async\" loading=\"lazy\" id=\"il_fi\" src=\"http:\/\/www.rsstecnologia.com\/wp-content\/uploads\/2011\/11\/f4ed3f48eb60x350.jpg.jpg\" alt=\"\" width=\"660\" height=\"350\" \/><\/p>\n<p style=\"text-align: justify;\">Claro que, tampoco ese ser\u00e1 el final para el Universo en el que, nuevas estrellas seguir\u00e1n naciendo para hacer posible que, mundos como la Tierra puedan, con su luz y su calor, hacer surgir formas de vida que, como la nuestra, pueda alcanzar la consciencia de Ser y, a partir de ah\u00ed&#8230; comenzar\u00e1 otra nueva aventura que ser\u00e1 digna de contar.<\/p>\n<p style=\"text-align: justify;\">emilio silvera<\/p>\n<\/div>\n<div class='bookmark'>\r\n\t\t<table align='left' border='0' cellpadding='0' width='100%'>\r\n\t\t<tr><td><span class='pushbutton'><a href='http:\/\/delicious.com\/post?url=https%3A%2F%2Fwww.emiliosilveravazquez.com%2Fblog%2F2013%2F09%2F27%2Fsabemos-como-evoluciona-el-universo-observando-las-estrellas%2F&amp;title=Sabemos+c%C3%B3mo+evoluciona+el+Universo%2C+observando+las+estrellas' title='Delicious' target='_blank' rel='nofollow'><img src='https:\/\/www.emiliosilveravazquez.com\/blog\/wp-content\/plugins\/knxdt-bookmarks-wordpress-plugin\/images\/delicious.png'  alt='' class='book_img' border='none' style='margin:1px; padding: 0;'  \/><\/a><\/span><span class='pushbutton'><a href='http:\/\/digg.com\/submit?url=https%3A%2F%2Fwww.emiliosilveravazquez.com%2Fblog%2F2013%2F09%2F27%2Fsabemos-como-evoluciona-el-universo-observando-las-estrellas%2F&amp;title=Sabemos+c%C3%B3mo+evoluciona+el+Universo%2C+observando+las+estrellas' title='Digg' target='_blank' rel='nofollow'><img src='https:\/\/www.emiliosilveravazquez.com\/blog\/wp-content\/plugins\/knxdt-bookmarks-wordpress-plugin\/images\/digg.png'  alt='' class='book_img' border='none' style='margin:1px; padding: 0;'  \/><\/a><\/span><span class='pushbutton'><a href='http:\/\/www.google.com\/bookmarks\/mark?op=edit&amp;bkmk=https%3A%2F%2Fwww.emiliosilveravazquez.com%2Fblog%2F2013%2F09%2F27%2Fsabemos-como-evoluciona-el-universo-observando-las-estrellas%2F&amp;title=Sabemos+c%C3%B3mo+evoluciona+el+Universo%2C+observando+las+estrellas' title='Google' target='_blank' rel='nofollow'><img src='https:\/\/www.emiliosilveravazquez.com\/blog\/wp-content\/plugins\/knxdt-bookmarks-wordpress-plugin\/images\/google.png'   alt='' class='book_img' border='none' style='margin:1px; padding: 0;'  \/><\/a><\/span><span class='pushbutton'><a href='http:\/\/myweb2.search.yahoo.com\/myresults\/bookmarklet?u=https%3A%2F%2Fwww.emiliosilveravazquez.com%2Fblog%2F2013%2F09%2F27%2Fsabemos-como-evoluciona-el-universo-observando-las-estrellas%2F&amp;t=Sabemos+c%C3%B3mo+evoluciona+el+Universo%2C+observando+las+estrellas' title='Yahoo' target='_blank' rel='nofollow'><img src='https:\/\/www.emiliosilveravazquez.com\/blog\/wp-content\/plugins\/knxdt-bookmarks-wordpress-plugin\/images\/yahoo.png'  alt='' class='book_img' border='none' style='margin:1px; padding: 0;'  \/><\/a><\/span><span class='pushbutton'><a href='http:\/\/www.technorati.com\/faves?add=https%3A%2F%2Fwww.emiliosilveravazquez.com%2Fblog%2F2013%2F09%2F27%2Fsabemos-como-evoluciona-el-universo-observando-las-estrellas%2F' title='Technorati' target='_blank' rel='nofollow'><img src='https:\/\/www.emiliosilveravazquez.com\/blog\/wp-content\/plugins\/knxdt-bookmarks-wordpress-plugin\/images\/technorati.png'  alt='' class='book_img' border='none' style='margin:1px; padding: 0;'  \/><\/a><\/span><span class='pushbutton'><a href='http:\/\/meneame.net\/submit.php?url=https%3A%2F%2Fwww.emiliosilveravazquez.com%2Fblog%2F2013%2F09%2F27%2Fsabemos-como-evoluciona-el-universo-observando-las-estrellas%2F' title='Meneame' target='_blank' rel='nofollow'><img src='https:\/\/www.emiliosilveravazquez.com\/blog\/wp-content\/plugins\/knxdt-bookmarks-wordpress-plugin\/images\/meneame.png'  alt='' class='book_img' border='none' style='margin:1px; padding: 0;'  \/><\/a><\/span><span class='pushbutton'><a href='http:\/\/enchilame.com\/submit.php?url=https:\/\/www.emiliosilveravazquez.com\/blog\/2013\/09\/27\/sabemos-como-evoluciona-el-universo-observando-las-estrellas\/' target='_blank' rel='nofollow'><img title='Enchilame' src='https:\/\/www.emiliosilveravazquez.com\/blog\/wp-content\/plugins\/knxdt-bookmarks-wordpress-plugin\/images\/enchilame.png'  alt='' class='book_img' border='none' style='margin:1px; padding: 0;'  \/><\/a><\/span><span class='pushbutton'><a href='http:\/\/www.blinklist.com\/index.php?Action=Blink\/addblink.php&amp;Description=&amp;Url=https%3A%2F%2Fwww.emiliosilveravazquez.com%2Fblog%2F2013%2F09%2F27%2Fsabemos-como-evoluciona-el-universo-observando-las-estrellas%2F&amp;title=Sabemos+c%C3%B3mo+evoluciona+el+Universo%2C+observando+las+estrellas' title='BlinkList' target='_blank' rel='nofollow'><img src='https:\/\/www.emiliosilveravazquez.com\/blog\/wp-content\/plugins\/knxdt-bookmarks-wordpress-plugin\/images\/blinklist.png'  alt='' class='book_img' border='none' style='margin:1px; padding: 0;'  \/><\/a><\/span><span class='pushbutton'><a href='http:\/\/reddit.com\/submit?url=https%3A%2F%2Fwww.emiliosilveravazquez.com%2Fblog%2F2013%2F09%2F27%2Fsabemos-como-evoluciona-el-universo-observando-las-estrellas%2F&amp;title=Sabemos+c%C3%B3mo+evoluciona+el+Universo%2C+observando+las+estrellas' title='Reddit' target='_blank' rel='nofollow'><img src='https:\/\/www.emiliosilveravazquez.com\/blog\/wp-content\/plugins\/knxdt-bookmarks-wordpress-plugin\/images\/reddit.png'  alt='' class='book_img' border='none' style='margin:1px; padding: 0;'  \/><\/a><\/span><span class='pushbutton'><a href='http:\/\/www.tecnologiadiaria.com\/2009\/07\/abrir-com-hotmail-correo.html' target='_blank' title='hotmail'><img src='https:\/\/www.emiliosilveravazquez.com\/blog\/wp-content\/plugins\/knxdt-bookmarks-wordpress-plugin\/images\/linklove.png' alt='hotmail correo' class='book_img' border='none' style='margin:1px; padding: 0;' \/><\/a><\/span><span class='pushbutton'><a href='http:\/\/bitacoras.com\/votar\/anotacion\/externo\/mini\/www.emiliosilveravazquez.com\/blog\/2013\/09\/27\/sabemos-como-evoluciona-el-universo-observando-las-estrellas\/' title='Bitacoras.com' target='_blank' rel='nofollow'><img src='https:\/\/www.emiliosilveravazquez.com\/blog\/wp-content\/plugins\/knxdt-bookmarks-wordpress-plugin\/images\/bitacoras.png'  alt='' class='book_img' border='none' style='margin:1px; padding: 0;'  \/><\/a><\/span><span class='pushbutton'><a href='http:\/\/www.wikio.es\/vote?url=https%3A%2F%2Fwww.emiliosilveravazquez.com%2Fblog%2F2013%2F09%2F27%2Fsabemos-como-evoluciona-el-universo-observando-las-estrellas%2F' title='Wikio' target='_blank' rel='nofollow'><img src='https:\/\/www.emiliosilveravazquez.com\/blog\/wp-content\/plugins\/knxdt-bookmarks-wordpress-plugin\/images\/wikio.png'   alt='' class='book_img' border='none' style='margin:1px; padding: 0;'   \/><\/a><\/span><span class='pushbutton'><a href='http:\/\/friendfeed.com\/?url=https%3A%2F%2Fwww.emiliosilveravazquez.com%2Fblog%2F2013%2F09%2F27%2Fsabemos-como-evoluciona-el-universo-observando-las-estrellas%2F&amp;title=Sabemos+c%C3%B3mo+evoluciona+el+Universo%2C+observando+las+estrellas' title='Friend Feed' target='_blank' rel='nofollow'><img src='https:\/\/www.emiliosilveravazquez.com\/blog\/wp-content\/plugins\/knxdt-bookmarks-wordpress-plugin\/images\/friendfeed.png'  alt='' class='book_img' border='none' style='margin:1px; padding: 0;'  \/><\/a><\/span><span class='pushbutton'><a href='http:\/\/www.facebook.com\/share.php?u=https%3A%2F%2Fwww.emiliosilveravazquez.com%2Fblog%2F2013%2F09%2F27%2Fsabemos-como-evoluciona-el-universo-observando-las-estrellas%2F&amp;t=Sabemos+c%C3%B3mo+evoluciona+el+Universo%2C+observando+las+estrellas' title='Facebook' target='_blank' rel='nofollow'><img src='https:\/\/www.emiliosilveravazquez.com\/blog\/wp-content\/plugins\/knxdt-bookmarks-wordpress-plugin\/images\/facebook.png'  alt='' class='book_img' border='none' style='margin:1px; padding: 0;'  \/><\/a><\/span><span class='pushbutton'><a href='http:\/\/twitter.com\/home?status=Sabemos+c%C3%B3mo+evoluciona+el+Universo%2C+observando+las+estrellas: https%3A%2F%2Fwww.emiliosilveravazquez.com%2Fblog%2F2013%2F09%2F27%2Fsabemos-como-evoluciona-el-universo-observando-las-estrellas%2F' title='Twitter' target='_blank' rel='nofollow'><img src='https:\/\/www.emiliosilveravazquez.com\/blog\/wp-content\/plugins\/knxdt-bookmarks-wordpress-plugin\/images\/twitter.png'  alt='' class='book_img' border='none' style='margin:1px; padding: 0;'  \/><\/a><\/span><span class='pushbutton'><a href='http:\/\/www.feedburner.com\/fb\/a\/emailFlare?itemTitle=Sabemos+c%C3%B3mo+evoluciona+el+Universo%2C+observando+las+estrellas&amp;uri=https%3A%2F%2Fwww.emiliosilveravazquez.com%2Fblog%2F2013%2F09%2F27%2Fsabemos-como-evoluciona-el-universo-observando-las-estrellas%2F' title='Enviar por Email' target='_blank' rel='nofollow'><img src='https:\/\/www.emiliosilveravazquez.com\/blog\/wp-content\/plugins\/knxdt-bookmarks-wordpress-plugin\/images\/email.png'  alt='' class='book_img' border='none' style='margin:1px; padding: 0;'  \/><\/a><\/span><span style='font-weight:bold; padding-left: 5px;'><a href='http:\/\/wordpress.org\/extend\/plugins\/knxdt-bookmarks-wordpress-plugin\/' title='Plugin' rel='nofollow' target='_blank'>[?]<\/a><\/span><\/td><\/tr><\/table><br\/><br\/><\/div>","protected":false},"excerpt":{"rendered":"<p>Hace alg\u00fan tiempo que sali\u00f3 la noticia en los medios: &#8220;Un equipo de cient\u00edficos europeos, entre ellos investigadores del Instituto de Astrof\u00edsica de Canarias (IAC), ha hecho p\u00fablicos los resultados de 30 a\u00f1os de investigaci\u00f3n sobre la estrella hipergigante HR 8752, que han revelado el eslab\u00f3n perdido en la evoluci\u00f3n de este tipo de astros.Concretamente, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_s2mail":"yes","footnotes":""},"categories":[135],"tags":[],"_links":{"self":[{"href":"https:\/\/www.emiliosilveravazquez.com\/blog\/wp-json\/wp\/v2\/posts\/9824"}],"collection":[{"href":"https:\/\/www.emiliosilveravazquez.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.emiliosilveravazquez.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.emiliosilveravazquez.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.emiliosilveravazquez.com\/blog\/wp-json\/wp\/v2\/comments?post=9824"}],"version-history":[{"count":0,"href":"https:\/\/www.emiliosilveravazquez.com\/blog\/wp-json\/wp\/v2\/posts\/9824\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.emiliosilveravazquez.com\/blog\/wp-json\/wp\/v2\/media?parent=9824"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.emiliosilveravazquez.com\/blog\/wp-json\/wp\/v2\/categories?post=9824"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.emiliosilveravazquez.com\/blog\/wp-json\/wp\/v2\/tags?post=9824"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}