{"id":15707,"date":"2016-07-02T06:59:04","date_gmt":"2016-07-02T05:59:04","guid":{"rendered":"http:\/\/www.emiliosilveravazquez.com\/blog\/?p=15707"},"modified":"2016-07-02T06:59:04","modified_gmt":"2016-07-02T05:59:04","slug":"las-misteriosas-funciones-modulares-3","status":"publish","type":"post","link":"https:\/\/www.emiliosilveravazquez.com\/blog\/2016\/07\/02\/las-misteriosas-funciones-modulares-3\/","title":{"rendered":"Las misteriosas funciones  modulares"},"content":{"rendered":"<div>\n<h2 style=\"text-align: justify;\">\u00a0 <a href=\"http:\/\/www.emiliosilveravazquez.com\/blog\/2013\/05\/06\/%c2%a1interacciones-fundamentales\/\" rel=\"prev\">\u00a1Interacciones fundamentales!<\/a><\/h2>\n<\/div>\n<div style=\"text-align: justify;\">\n<div><a href=\"http:\/\/www.emiliosilveravazquez.com\/blog\/2013\/05\/07\/algo-sobre-darwin\/\" rel=\"next\">Lyell y Darwin \u00a1El caprichoso destino!<\/a><\/div>\n<\/div>\n<h3 style=\"text-align: justify;\"><\/h3>\n<p style=\"text-align: justify;\"><img decoding=\"async\" loading=\"lazy\" id=\"irc_mi\" src=\"http:\/\/www.uco.es\/hbarra\/Blog\/fractal.gif\" alt=\"\" width=\"478\" height=\"359\" \/><\/p>\n<div>\n<p style=\"text-align: justify;\">Al manipular los diagramas de lazos de Kikkawa, Sakita y Virasoro creados por cuerdas en interacci\u00f3n, all\u00ed est\u00e1n esas extra\u00f1as funciones modulares en las que el n\u00famero 10 aparecen en los lugares m\u00e1s extra\u00f1os.<\/p>\n<p style=\"text-align: justify;\">Estas funciones modulares son tan misteriosas como el hombre que las investig\u00f3, el m\u00edstico del Este.\u00a0 Quiz\u00e1 si entendi\u00e9ramos mejor el trabajo de este genio indio, comprender\u00edamos por qu\u00e9 vivimos en nuestro Universo actual.<\/p>\n<p style=\"text-align: justify;\">El misterio de las <strong>Funciones Modulares<\/strong> podr\u00eda ser explicado por quien ya no existe, Srinivasa Ramanujan, el hombre m\u00e1s extra\u00f1o del mundo de los matem\u00e1ticos.\u00a0 Igual que Riemann, muri\u00f3 antes de cumplir cuarenta a\u00f1os, y como Riemann antes que \u00e9l trabaj\u00f3 en total aislamiento, en su universo particular de n\u00fameros y fue capaz de reinventar por s\u00ed mismo lo m\u00e1s valioso de cien a\u00f1os de matem\u00e1ticas occidentales que, al estar aislado del mundo en las corrientes principales de los matem\u00e1ticos, le eran totalmente desconocidos, as\u00ed que, los busc\u00f3 sin conocerlos.\u00a0 Perdi\u00f3 muchos a\u00f1os de su vida en redescubrir matem\u00e1ticas conocidas.<\/p>\n<h3 style=\"text-align: justify;\"><a href=\"http:\/\/labellateoria.blogspot.com.es\/2006\/10\/la-funcin-modular-de-ramanujan-y-la.html\">La funci\u00f3n modular de Ramanujan y la teor\u00eda de cuerdas<\/a><\/h3>\n<p style=\"text-align: justify;\"><img decoding=\"async\" loading=\"lazy\" src=\"http:\/\/3.bp.blogspot.com\/-AvaAtMcGVAQ\/T3XsoHSRRvI\/AAAAAAAA6Yc\/Pn6DK9plbsg\/s1600\/images+%283%29.jpg\" alt=\"\" width=\"154\" height=\"39\" \/><\/p>\n<p style=\"text-align: justify;\">La funci\u00f3n de Ramanujan contiene un t\u00e9rmino elevado a la potencia veinticuatro. Ese n\u00famero es el origen de las cancelaciones milagrosas que se dan en la &#8230; Pero hablemos de las cuerdas.<\/p>\n<p style=\"text-align: justify;\"><strong>La teor\u00eda de cuerdas\u00a0<\/strong> supone que cada modo o vibraci\u00f3n de una cuerda fundamental representa una part\u00edcula elemental distinta, y puede explicar a la vez la naturaleza de la materia y del espacio-tiempo (las part\u00edculas en lugar de ser puntuales pasan a ser unidimensionales). Es la primera teor\u00eda cu\u00e1ntica de la gravedad: Cuando se calcularon por primera vez las ligaduras de autoconsistencia que impone la cuerda sobre el espacio-tiempo, se observ\u00f3 con sorpresa que las ecuaciones de <a href=\"#\" onclick=\"referencia('einstein',event); return false;\">Einstein<\/a> ( teor\u00eda de la gravedad) emerg\u00edan de la cuerda, de hecho, el <a href=\"#\" onclick=\"referencia('graviton',event); return false;\">gravit\u00f3n<\/a> o cuanto de gravedad era la menor vibraci\u00f3n de la cuerda cerrada.<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/photos1.blogger.com\/blogger2\/8150\/2477\/1600\/Cuerdas_cerradas.jpg\"><img decoding=\"async\" src=\"http:\/\/photos1.blogger.com\/blogger2\/8150\/2477\/320\/Cuerdas_cerradas.jpg\" alt=\"\" border=\"0\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">No sabemos todav\u00eda por qu\u00e9 la teor\u00eda de cuerdas est\u00e1 definida s\u00f3lo en 10 y 26 dimensiones, aunque parece seguro que esta teor\u00eda no podr\u00eda unificar las fuerzas fundamentales con tan solo tres dimensiones. Las cuerdas se rompen y se forman en el espacio N-dimensional arrastrando con ellas una serie de t\u00e9rminos que destruyen las maravillosas propiedades de la teor\u00eda. Afortunadamente, estos t\u00e9rminos aparecen multiplicados por el factor (N-10), lo que nos obliga a elegir N=10 para eliminarlos.<\/p>\n<p style=\"text-align: justify;\"><img decoding=\"async\" loading=\"lazy\" id=\"irc_mi\" src=\"http:\/\/mikipediageek.files.wordpress.com\/2010\/09\/ramanujan_.gif\" alt=\"\" width=\"478\" height=\"338\" \/><\/p>\n<p style=\"text-align: justify;\">Dispersas entre oscuras ecuaciones en sus cuadernos est\u00e1n estas <strong>funciones modulares<\/strong>,\u00a0 que figuran entre los m\u00e1s extra\u00f1os jam\u00e1s encontradas en matem\u00e1ticas.\u00a0\u00a0 Ellos reaparecen en los ramos m\u00e1s distantes e inconexos de las matem\u00e1ticas.\u00a0 Una funci\u00f3n, que aparece una y otra vez en la teor\u00eda de las funciones modulares, se denominan (como ya he dicho otras veces) hoy d\u00eda \u201cfunci\u00f3n de Ramanujan\u201d en su honor.\u00a0 Esta extra\u00f1a funci\u00f3n contiene un t\u00e9rmino elevado a la potencia veinticuatro.<\/p>\n<p style=\"text-align: justify;\">El n\u00famero 24 aparece repetidamente en la obra de Ramanujan.\u00a0 Este es un ejemplo de lo que las matem\u00e1ticas llaman n\u00fameros m\u00e1gicos,\u00a0 que aparecen continuamente, donde menos se esperan, por razones que nadie entiende.\u00a0\u00a0 Milagrosamente, la funci\u00f3n de Ramanujan aparece tambi\u00e9n en la teor\u00eda de cuerdas.\u00a0\u00a0 El n\u00famero 24 que aparece en la funci\u00f3n de Ramanujan es tambi\u00e9n el origen de las cancelaciones milagrosas que se dan en la teor\u00eda de cuerdas.\u00a0 En la teor\u00eda de cuerdas, cada uno de los veinticuatro modos de la funci\u00f3n de Ramanujan corresponde a una vibraci\u00f3n f\u00edsica de la cuerda.\u00a0 Cuando quiera que la cuerda ejecuta sus movimientos complejos en el espacio-tiempo dividi\u00e9ndose y recombin\u00e1ndose, deben satisfacerse un gran n\u00famero de identidades matem\u00e1ticas altamente perfeccionadas.\u00a0\u00a0 Estas son precisamente las entidades matem\u00e1ticas descubiertas por Ramanujan.\u00a0 (Puesto que los f\u00edsicos a\u00f1aden dos dimensiones m\u00e1s cuando cuentan el n\u00famero total de vibraciones que aparecen en una teor\u00eda relativista, ello significa que el espacio -tiempo debe tener 24 + 2 = 26 dimensiones espacio \u2013 temporales.)<\/p>\n<p style=\"text-align: justify;\"><img decoding=\"async\" loading=\"lazy\" id=\"irc_mi\" src=\"http:\/\/2.bp.blogspot.com\/-_yfoM32G8iU\/URIef-KPLtI\/AAAAAAAAAZA\/hA0sbYlfwAI\/s1600\/Cuerdas+3.png\" alt=\"\" width=\"478\" height=\"210\" \/><\/p>\n<p style=\"text-align: justify;\">Cuando se generaliza la funci\u00f3n de Ramanujan, el 24 queda reemplazado por el n\u00famero 8. Por lo tanto, el n\u00famero cr\u00edtico para la supercuerda es 8+2=10. No estar\u00e1 la soluci\u00f3n final de la Teor\u00eda de cuerdas, en estas misteriosas funciones modelares.<\/p>\n<p style=\"text-align: justify;\">Para comprender este misterioso factor de dos (que a\u00f1aden los f\u00edsicos consideramos un rayo de luz que tiene dos modos f\u00edsicos de vibraci\u00f3n.\u00a0 La luz polarizada puede vibrar, por ejemplo, o bien horizontal o bien verticalmente.\u00a0 Sin embargo, un campo de Maxwell relativista A<sub>\u00b5<\/sub> tiene cuatro componentes, donde <sub>\u00b5 = <\/sub>1, 2, 3, 4.\u00a0 Se nos permite sustraer dos de estas cuatro componentes utilizando la simetr\u00eda <a href=\"http:\/\/www.emiliosilveravazquez.com\/blog\/2013\/05\/07\/las-misteriosas-funciones-modulares\/comment-page-1\/#\"><a href=\"#\" onclick=\"referencia('gauge',event); return false;\">gauge<\/a><\/a> de las ecuaciones de Maxwell.\u00a0 Puesto que 4 \u2013 2 = 2, los cuatro campos de Maxwell originales se han reducido a dos.\u00a0 An\u00e1logamente, una cuerda relativista vibra en 26 dimensiones.\u00a0 Sin embargo, dos de estos modos vibracionales pueden ser eliminados cuando rompemos la simetr\u00eda de la cuerda, qued\u00e1ndonos con 24 modos vibracionales que son las que aparecen en la funci\u00f3n de Ramanujan.<\/p>\n<p style=\"text-align: justify;\">Antes explicamos que cuando se generaliza la funci\u00f3n de Ramanujan, el 24 queda reemplazado por el n\u00famero 8.\u00a0\u00a0 Por lo tanto, el n\u00famero cr\u00edtico para la supercuerda es 8+2=10.\u00a0 Este es el origen de la d\u00e9cima dimensi\u00f3n que exige la teor\u00eda.\u00a0\u00a0 La cuerda vibra en diez dimensiones porque requiere estas funciones de Ramanujan generalizadas para permanecer auto consistente.\u00a0 Dicho de otra manera, los f\u00edsicos no tienen la menor idea de por qu\u00e9 10 y 26 dimensiones se seleccionan como dimensi\u00f3n de la cuerda.\u00a0\u00a0 Es como si hubiera alg\u00fan tipo de numerolog\u00eda profunda que se manifestara en estas funciones que nadie comprende.\u00a0 Son precisamente estos n\u00fameros m\u00e1gicos que aparecen en las funciones modulares el\u00edpticas los que determinan que la dimensi\u00f3n del espacio \u2013 tiempo sea diez.<\/p>\n<p style=\"text-align: justify;\"><img decoding=\"async\" loading=\"lazy\" id=\"irc_mi\" src=\"http:\/\/www.medciencia.com\/wp-content\/uploads\/2014\/07\/11th_Dimension_Reflections_by_JP_Talma.jpg\" alt=\"\" width=\"478\" height=\"359\" \/><\/p>\n<p style=\"text-align: justify;\">\u00a0\u00a0\u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 Claro que, la Teor\u00eda de Cuerdas tiene versiones en 10, 11 y 26 dimensiones<\/p>\n<p style=\"text-align: justify;\">En el an\u00e1lisis final, el origen de la teor\u00eda decadimensional es tan misterioso como el propio Ramanujan.\u00a0 Si alguien preguntara a cualquier f\u00edsico del mundo por qu\u00e9 la naturaleza deber\u00eda existir en diez dimensiones, estar\u00eda obligado a responder \u201cNo lo se\u201d.\u00a0 Se sabe en t\u00e9rminos difusos, por qu\u00e9 debe seleccionarse alguna dimensi\u00f3n del espacio tiempo (de lo contrario la cuerda no puede vibrar de una forma cu\u00e1nticamente autoconsistente), pero no sabemos por que se seleccionan estos n\u00fameros concretos.<\/p>\n<p style=\"text-align: justify;\">Quiz\u00e1 la respuesta a todo esto est\u00e9 esperando a ser descubierta cuando alguien (alg\u00fan genio matem\u00e1tico como Perelman) sea capaz de entender el contenido de los cuadernos perdidos de Ramanujan<a name=\"r_pie\"><\/a>.<\/p>\n<p style=\"text-align: justify;\">Srinivasa Ramanujan naci\u00f3 en 1.887 en Erode, India, cerca de Madr\u00e1s.\u00a0 Su familia de clase media alta, brahmin, la m\u00e1s alta de las castas Hind\u00faes, fueron destituidos y venidos a menos, su padre trabajaba de oficinista de un comerciante de tejidos.<\/p>\n<p style=\"text-align: justify;\">Con diez a\u00f1os, lo mismo que pas\u00f3 antes con Riemann, ya destacaba y sorprend\u00eda a todos con sus enormes poderes de c\u00e1lculos.\u00a0\u00a0 Siendo ni\u00f1o, rederiv\u00f3 la identidad de Euler entre funciones trigonom\u00e9tricas y exponenciales.<\/p>\n<p style=\"text-align: justify;\"><img decoding=\"async\" loading=\"lazy\" id=\"irc_mi\" src=\"http:\/\/proyectoazul.com\/wp-content\/uploads\/2009\/10\/ph_einstein_01.jpg\" alt=\"\" width=\"256\" height=\"360\" \/><img decoding=\"async\" loading=\"lazy\" id=\"irc_mi\" src=\"http:\/\/image.slidesharecdn.com\/einsteinchrismason-140902202417-phpapp02\/95\/einstein-3-638.jpg?cb=1409689503\" alt=\"\" width=\"478\" height=\"359\" \/><\/p>\n<p style=\"text-align: justify;\">En la vida de cada cient\u00edfico joven hay un punto de partida, un hecho que, sin ellos saberlo, les marca el destino.\u00a0 Para <a href=\"http:\/\/www.emiliosilveravazquez.com\/blog\/2013\/05\/07\/las-misteriosas-funciones-modulares\/comment-page-1\/#\"><a href=\"#\" onclick=\"referencia('einstein',event); return false;\">Einstein<\/a><\/a> fue la fascinaci\u00f3n que le caus\u00f3 la br\u00fajula que le regal\u00f3 su t\u00edo cuando estaba enfermo siendo un ni\u00f1o, no pod\u00eda apartar la mirada de la aguja que siempre indicaba hacia el mismo sitio, y se pregunt\u00f3 una y mil veces por la fuerza invisible que la obligaba a dirigirse hacia esa direcci\u00f3n. Para Riemann, fue la lectura del libro de matem\u00e1ticas de Legendre.\u00a0 Para Ramanujan, fue cuando se sumergi\u00f3 en un oscuro y olvidado libro de matem\u00e1ticas escrito por George Carr.\u00a0\u00a0 Este libro ha quedado inmortalizado desde entonces por el hecho de que se\u00f1al\u00f3 la \u00fanica exposici\u00f3n conocida de Ramanujan a los modernas matem\u00e1ticas occidentales.\u00a0\u00a0 Seg\u00fan su hermana: \u201cFue este libro el que despert\u00f3 su genio.\u00a0 El se propuso establecer por s\u00ed mismo las f\u00f3rmulas dadas all\u00ed.\u00a0 Como no ten\u00eda la ayuda de otros libros, cada soluci\u00f3n era un trabajo de investigaci\u00f3n por lo que a \u00e9l concern\u00eda\u2026\u00a0 Ramanujan sol\u00eda decir que la diosa Namakkal le inspiraba las f\u00f3rmulas en sue\u00f1os\u201d.<\/p>\n<p style=\"text-align: justify;\"><img decoding=\"async\" loading=\"lazy\" id=\"irc_mi\" src=\"http:\/\/1.bp.blogspot.com\/_kKPAjw3Xh0o\/S88mBXE2MXI\/AAAAAAAAAS4\/f8zCdx_FYow\/s1600\/2004122600610401.jpg\" alt=\"\" width=\"289\" height=\"350\" \/><\/p>\n<p style=\"text-align: justify;\">Con ayuda de amigos, Ramanujan consigui\u00f3 un puesto de bajo nivel del puerto de Madr\u00e1s.\u00a0\u00a0 Era un trabajo servil, con una m\u00edsera paga de 20 libras al a\u00f1o, pero dio libertad a Ramanujan, como a <a href=\"http:\/\/www.emiliosilveravazquez.com\/blog\/2013\/05\/07\/las-misteriosas-funciones-modulares\/comment-page-1\/#\"><a href=\"#\" onclick=\"referencia('einstein',event); return false;\">Einstein<\/a><\/a> antes que \u00e9l en la oficina de Patentes Suiza, para seguir sus sue\u00f1os en su tiempo libre.\u00a0\u00a0 Ramanujan, en la fascinaci\u00f3n que en \u00e9l ejerc\u00edan los n\u00fameros, era incansable, llenaba libretas enteras de c\u00e1lculos y ecuaciones que antes ve\u00eda florecer en su cabeza.<\/p>\n<p style=\"text-align: justify;\">As\u00ed estaban las cosas cuando decidi\u00f3 escribir algunos de sus trabajos a las tres matem\u00e1ticos m\u00e1s famosos de Inglaterra y Europa.<\/p>\n<p style=\"text-align: justify;\">Dos de aquellos matem\u00e1ticos, al tener en su poder las cartas enviadas por un miserable empleado sin instrucci\u00f3n formal alguna, sin haber comprobado su contenido, las arrojaron directamente a la basura.\u00a0\u00a0 El tercero era el brillante matem\u00e1tico de Cambridge Godfrey Harold Hardy. Debido a su categor\u00eda en Inglaterra, Hardy estaba acostumbrado a recibir correo de chiflados proponi\u00e9ndole los m\u00e1s peregrinos proyectos y, en un primer momento apenas prest\u00f3 atenci\u00f3n a la carta del joven Ramanujan.<\/p>\n<p style=\"text-align: justify;\">Srinivasa Ramanujan trabaj\u00f3 principalmente en <strong>teor\u00eda de n\u00fameros<\/strong>, encontrando identidades relacionadas con el n\u00famero pi y el n\u00famero e o los n\u00fameros primos. Como decimos, en general sus f\u00f3rmulas son muy enrevesadas, pero en su mayor\u00eda verdaderas (a posteriori se ha descubierto que algunos de sus resultados era incorrectos), y algunas de ellas se han convertido en potentes herramientas para calcular grandes cantidades de decimales de, principalmente, el n\u00famero pi. Quiz\u00e1s la m\u00e1s conocida sea \u00e9sta:<\/p>\n<p style=\"text-align: justify;\" align=\"center\"><img decoding=\"async\" title=\"\\displaystyle{\\cfrac{1}{\\pi} = \\cfrac{2 \\sqrt{2}}{9801} \\sum^{\\infty}_{k=0} \\cfrac{(4k)!(1103+26390k)}{(k!)^4 396^{4k}}}\" src=\"http:\/\/s0.wp.com\/latex.php?latex=%5Cdisplaystyle%7B%5Ccfrac%7B1%7D%7B%5Cpi%7D+%3D+%5Ccfrac%7B2+%5Csqrt%7B2%7D%7D%7B9801%7D+%5Csum%5E%7B%5Cinfty%7D_%7Bk%3D0%7D+%5Ccfrac%7B%284k%29%21%281103%2B26390k%29%7D%7B%28k%21%29%5E4+396%5E%7B4k%7D%7D%7D&amp;bg=ffffff&amp;fg=000000&amp;s=0\" alt=\"\\displaystyle{\\cfrac{1}{\\pi} = \\cfrac{2 \\sqrt{2}}{9801} \\sum^{\\infty}_{k=0} \\cfrac{(4k)!(1103+26390k)}{(k!)^4 396^{4k}}}\" \/><\/p>\n<p style=\"text-align: justify;\">que nos da 8 decimales exactos de pi en cada iteraci\u00f3n. Tremendo, \u00bfverdad?<\/p>\n<p style=\"text-align: justify;\"><img decoding=\"async\" src=\"http:\/\/3.bp.blogspot.com\/-OqcWzTtOMWI\/UJqHMJP9TkI\/AAAAAAAAAXY\/iwwtOAHwFQs\/s1600\/ramanujan.jpg\" alt=\"http:\/\/3.bp.blogspot.com\/-OqcWzTtOMWI\/UJqHMJP9TkI\/AAAAAAAAAXY\/iwwtOAHwFQs\/s1600\/ramanujan.jpg\" \/><\/p>\n<p style=\"text-align: justify;\">Entre los densos garabatos advirti\u00f3 muchos teoremas matem\u00e1ticos que ya eran bien conocidos.\u00a0 Pensando que era la obra obvia de un plagiario, el tambi\u00e9n la desech\u00f3 en ese primer impulso.\u00a0\u00a0 Pero hab\u00eda algo que no encajaba.\u00a0 Algo que inquietaba a Hardy; no pod\u00eda dejar de pensar en aquella extra\u00f1a carta.<\/p>\n<p style=\"text-align: justify;\">Durante la cena de esa noche, 16 de enero de. 1913, Hardy y su colega John Littlewood discutieron esta carta singular y decidieron echar un segundo vistazo \u2013 repaso a su contenido.\u00a0\u00a0 Comenzaba de forma bastante inocente, con \u201cMe permito presentarme a usted como un empleado en el departamento de contabilidad de la oficina del puerto franco de Madr\u00e1s con un salario de solo veinte libras al a\u00f1o\u201d.\u00a0\u00a0 Pero la carta del pobre empleado de Madr\u00e1s conten\u00eda teoremas que eran totalmente desconocidos para los matem\u00e1ticos occidentales.\u00a0 En total, conten\u00eda 120 teoremas.\u00a0 Hardy estaba at\u00f3nito.\u00a0 Recordaba que demostrar algunos de esos teoremas \u201cMe derrot\u00f3 por completo\u201d.\u00a0 \u201cNunca hab\u00eda visto nada antes que se le pareciera en lo m\u00e1s m\u00ednimo.\u00a0\u00a0 Una simple ojeada a ellos es suficiente para mostrar que s\u00f3lo pod\u00edan estar elaborados por un matem\u00e1tico muy grande\u201d.<\/p>\n<p style=\"text-align: justify;\">Littlewood y Hardy alcanzaron la misma conclusi\u00f3n: Aquello era el trabajo de un genio empe\u00f1ado en derivar de nuevo 100 a\u00f1os de matem\u00e1ticas europeas. \u201c\u00c9l hab\u00eda estado llevando a cabo una carrera imposible, un pobre y solitario hind\u00fa, completamente solo y sin ayuda, enfrentando su cerebro contra toda la sabidur\u00eda acumulada en Europa\u201d, recordaba con asombro Hardy.<\/p>\n<p style=\"text-align: justify;\"><img decoding=\"async\" loading=\"lazy\" id=\"irc_mi\" src=\"http:\/\/static.betazeta.com\/www.fayerwayer.com\/up\/2013\/10\/70477655_805b7125-cf5e-4e62-9c59-52543b3beb591-660x595.jpg\" alt=\"\" width=\"478\" height=\"269\" \/><\/p>\n<p style=\"text-align: justify;\">Hardy escribi\u00f3 a Ramanujan y, tras muchas pesquisas, uso de amistades e influencias, arregl\u00f3 su estancia en Cambridge en 1.914.\u00a0 Por primera vez, Ramanujan pod\u00eda comunicarse regularmente con sus iguales, la comunidad de los matem\u00e1ticos europeos.\u00a0 Entonces comenz\u00f3 el estallido de su actividad: tres cortos e intensos a\u00f1os de colaboraci\u00f3n con Hardy en el Trinity Collage en Cambridge.<\/p>\n<p style=\"text-align: justify;\">Hardy trat\u00f3 m\u00e1s tarde de estimar la capacidad matem\u00e1tica que pose\u00eda Ramanujan.\u00a0\u00a0 Concedi\u00f3 a David Hilbert, universalmente conocido y reconocido como uno de los mayores matem\u00e1ticos occidentales del siglo XIX, una puntuaci\u00f3n de 80.\u00a0\u00a0 A Ramanujan le asign\u00f3 una puntuaci\u00f3n de 100.\u00a0 As\u00ed mismo, Hardy se concedi\u00f3 un 25.<\/p>\n<p style=\"text-align: justify;\">Por desgracia, ni Hardy ni Ramanujan parec\u00edan interesados en la <a href=\"http:\/\/www.emiliosilveravazquez.com\/blog\/2013\/05\/07\/las-misteriosas-funciones-modulares\/comment-page-1\/#\"><a href=\"#\" onclick=\"referencia('psi',event); return false;\">psi<\/a><\/a>colog\u00eda a los procesos de pensamiento mediante los cuales Ramanujan descubr\u00eda estos incre\u00edbles teoremas, especialmente cuando este diluvio material brotaba de sus sue\u00f1os con semejante frecuencia.\u00a0\u00a0 Hardy se\u00f1al\u00f3: \u201cParec\u00eda rid\u00edculo importunarle sobre como hab\u00eda descubierto este o ese teorema conocido, cuando \u00e9l me estaba mostrando media docena cada d\u00eda, de nuevos teoremas\u201d.<\/p>\n<p style=\"text-align: justify;\">Hardy recordaba vivamente:<\/p>\n<blockquote><p>-\u201dRecuerdo una vez que fui a visitarle cuando estaba enfermo en Putney.\u00a0 Yo hab\u00eda tomado el taxi n\u00famero 1.729, y coment\u00e9 que el numero me parec\u00eda bastante feo, y que esperaba que no fuese mal presagio.\u201d<\/p>\n<p>&#8211; No. -Replic\u00f3 Ramanujan postrado en su cama-. Es un n\u00famero muy interesante; es el n\u00famero m\u00e1s peque\u00f1o expresable como una suma de dos cubos en dos formas diferentes.<\/p>\n<p>&nbsp;<\/p><\/blockquote>\n<p style=\"text-align: justify;\"><em>(Es la suma de 1 x 1 x 1\u00a0 y 12 x 12 x 12, y tambi\u00e9n la suma de 9 x 9 x 9\u00a0 y\u00a0 10 x 10 x 10).<\/em><\/p>\n<p style=\"text-align: justify;\"><img decoding=\"async\" loading=\"lazy\" id=\"irc_mi\" src=\"http:\/\/3.bp.blogspot.com\/-k4nkUgey0mM\/TwGwOVAkwjI\/AAAAAAAAAGI\/WjFEyQ95uHg\/s400\/Untitled+1.bmp\" alt=\"\" width=\"395\" height=\"103\" \/><\/p>\n<p style=\"text-align: justify;\"><em> <\/em>Era capaz de recitar en el acto teoremas complejos de aritm\u00e9tica cuya demostraci\u00f3n requerir\u00eda un ordenador moderno.<\/p>\n<p style=\"text-align: justify;\">En 1.919 volvi\u00f3 a casa, en la India, donde un a\u00f1o m\u00e1s tarde muri\u00f3\u00a0 enfermo.<\/p>\n<p style=\"text-align: justify;\">El legado de Ramanujan es su obra, que consta de 4.000 f\u00f3rmulas en cuatrocientas p\u00e1ginas que llenan tres vol\u00famenes de notas, todas densamente llenas de teoremas de incre\u00edble fuerza pero sin ning\u00fan comentario o, lo que es m\u00e1s frustrante, sin ninguna demostraci\u00f3n.\u00a0 En 1.976, sin embargo, se hizo un nuevo descubrimiento.\u00a0\u00a0 Ciento treinta p\u00e1ginas de borradores, que conten\u00edan los resultados del \u00faltimo a\u00f1o de su vida, fueron descubiertas por casualidad en una caja en el Trinity Collage.\u00a0\u00a0 Esto se conoce ahora con el nombre de \u201cCuaderno Perdido\u201d de Ramanujan.<\/p>\n<p style=\"text-align: justify;\"><img decoding=\"async\" loading=\"lazy\" id=\"irc_mi\" src=\"http:\/\/4.bp.blogspot.com\/-z9YWrzskASg\/T52L3SnDILI\/AAAAAAAAOys\/vdySscv_M4Q\/s1600\/Cuaderno+de+Ramanujan.png\" alt=\"\" width=\"413\" height=\"355\" \/><\/p>\n<p style=\"text-align: justify;\">Comentando <strong>cuaderno perdido<\/strong>, el matem\u00e1tico Richard Askey dice:<\/p>\n<blockquote>\n<p style=\"text-align: justify;\">\u201cEl de este a\u00f1o, mientras se estaba muriendo, era el equivalente a una vida entera de un matem\u00e1tico muy grande\u201d.\u00a0 Lo que \u00e9l consigui\u00f3 era incre\u00edble.\u00a0 Los matem\u00e1ticos Jonathan Borwien y Meter Borwein, en relaci\u00f3n a la dificultad y la ardua tarea de descifrar los cuadernos perdidos, dijeron: \u201cQue nosotros sepamos nunca se ha intentado una redacci\u00f3n matem\u00e1tica de este alcance o dificultad\u201d.<\/p>\n<p>&nbsp;<\/p><\/blockquote>\n<p style=\"text-align: justify;\">Por mi parte creo que, Ramanujan, fue un genio matem\u00e1tico muy adelantado a su tiempo y que pasaran algunos a\u00f1os hasta que podamos descifrar al cien por ciento sus trabajos, especialmente, sus <strong>funciones modulares <\/strong>que guardan el secreto de la teor\u00eda m\u00e1s avanzada de la f\u00edsica moderna,\u00a0\u00a0 la \u00fanica capaz de unir la mec\u00e1nica qu\u00e1ntica y la Gravedad.<\/p>\n<p style=\"text-align: justify;\">Las matem\u00e1ticas de Ramanujan son como una sinfon\u00eda, la progresi\u00f3n de sus ecuaciones era algo nunca v\u00edsto, \u00e9l trabajaba desde otro nivel, los n\u00fameros se combinaban y flu\u00edan de su cabeza a velocidad de v\u00e9rtigo y con precisi\u00f3n nunca antes conseguida por nadie.\u00a0\u00a0 Ten\u00eda tal intuici\u00f3n de las cosas que \u00e9stas simplemente flu\u00edan de su cerebro.\u00a0\u00a0 Quiz\u00e1 no los ve\u00eda de una manera que sea traducible y el \u00fanico lenguaje eran los n\u00fameros.<\/p>\n<p style=\"text-align: justify;\"><img decoding=\"async\" loading=\"lazy\" id=\"irc_mi\" src=\"http:\/\/deletereo.com\/wp-content\/uploads\/2013\/03\/Blanca_Suave-620x530.jpg\" alt=\"\" width=\"478\" height=\"409\" \/><\/p>\n<p style=\"text-align: justify;\">\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Si finalmente las dos madejas se desenredan&#8230; \u00a1Por algo ser\u00e1!<\/p>\n<p style=\"text-align: justify;\">Como saben los f\u00edsicos, los \u201caccidentes\u201d no aparecen sin ninguna raz\u00f3n.\u00a0 Cuando est\u00e1n realizando un c\u00e1lculo largo y dif\u00edcil, y entonces resulta de repente que miles de t\u00e9rminos indeseados suman milagrosamente cero, los f\u00edsicos saben que esto no sucede sin una raz\u00f3n m\u00e1s profunda subyacente.\u00a0 Hoy, los f\u00edsicos conocen que estos \u201caccidentes\u201d son una indicaci\u00f3n de que hay una simetr\u00eda en juego.\u00a0 Para las cuerdas, la simetr\u00eda se denomina <strong>simetr\u00eda conforme<\/strong>, la simetr\u00eda de estirar y deformar la hoja del Universo de la cuerda.<\/p>\n<p style=\"text-align: justify;\">Aqu\u00ed es precisamente donde entra el trabajo de Ramanujan.\u00a0 Para proteger la simetr\u00eda conforme original contra su destrucci\u00f3n por la teor\u00eda cu\u00e1ntica, deben ser milagrosamente satisfechas cierto n\u00famero de identidades matem\u00e1ticas que, son precisamente las identidades de la funci\u00f3n modular de Ramanujan.\u00a0 \u00a1Incre\u00edble!\u00a0\u00a0 Pero, cierto.<\/p>\n<p style=\"text-align: justify;\">En resumen, he dicho que las leyes de la naturaleza se simplifican cuando se expresan en dimensiones m\u00e1s altas.\u00a0\u00a0 Sin embargo, a la luz de la teor\u00eda cu\u00e1ntica, debemos corregir algo Este sentido b\u00e1sico de mirar la cuesti\u00f3n.\u00a0\u00a0 El enunciado correcto ser\u00eda ahora:\u00a0\u00a0 las leyes de la naturaleza se simplifican cuando se expresan\u00a0 COHERENTEMENTE en dimensiones m\u00e1s altas.\u00a0 El a\u00f1adido de la palabra coherente es crucial.\u00a0\u00a0 Esta ligadura nos obliga a utilizar las funciones modulares de Ramanujan, que fijan en diez la dimensi\u00f3n del espacio \u2013 tiempo.\u00a0\u00a0 Esto, a su vez, puede darnos la clave decisiva para explicar el origen del Universo.<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.emiliosilveravazquez.com\/blog\/2013\/05\/07\/las-misteriosas-funciones-modulares\/comment-page-1\/#\"><a href=\"#\" onclick=\"referencia('einstein',event); return false;\">Einstein<\/a><\/a> se preguntaba a menudo si Dios tuvo alguna elecci\u00f3n al crear el universo.<\/p>\n<p style=\"text-align: justify;\"><img decoding=\"async\" loading=\"lazy\" id=\"irc_mi\" src=\"http:\/\/francis.naukas.com\/files\/2010\/09\/dibujo20100923_ads_cft_approaches_to_problems_in_relativistic_heavy_ion_collisions.jpg\" alt=\"\" width=\"478\" height=\"137\" \/><\/p>\n<p style=\"text-align: justify;\">Aunque el perfeccionamiento matem\u00e1tico introducido por la teor\u00eda de cuerdas ha alcanzado alturas de v\u00e9rtigo y ha sorprendido a los matem\u00e1ticos, los cr\u00edticos de la teor\u00eda a\u00fan la se\u00f1alan como su punto m\u00e1s d\u00e9bil.\u00a0 Cualquier teor\u00eda, afirman, debe ser verificable.\u00a0\u00a0 Puesto que ninguna teor\u00eda definida a la energ\u00eda de Planck de 10<sup>19<\/sup> miles de millones de eV es verificable, \u00a1La <a href=\"http:\/\/www.emiliosilveravazquez.com\/blog\/2013\/05\/07\/las-misteriosas-funciones-modulares\/comment-page-1\/#\"><a href=\"#\" onclick=\"referencia('supercuerdas teoria',event); return false;\">teor\u00eda de supercuerdas<\/a><\/a> no es realmente una teor\u00eda!<\/p>\n<p style=\"text-align: justify;\">El principal problema, es te\u00f3rico m\u00e1s que experimental.\u00a0 Si fu\u00e9ramos suficientemente inteligentes, podr\u00edamos resolver exactamente la teor\u00eda y encontrar la verdadera soluci\u00f3n no perturbativa de la teor\u00eda.\u00a0 Sin embargo, esto no nos excusa de encontrar alg\u00fan medio por el que verificar experimentalmente la teor\u00eda, debemos esperar se\u00f1ales de la d\u00e9cima dimensi\u00f3n.<\/p>\n<p style=\"text-align: justify;\">\u00bfLa d\u00e9cima dimensi\u00f3n?<\/p>\n<blockquote>\n<p style=\"text-align: justify;\">\u00a1Qu\u00e9 extra\u00f1o ser\u00eda que la teor\u00eda final se descubriera durante nuestra vida! El descubrimiento de las leyes finales de la Naturaleza marcar\u00e1 una discontinuidad en la Historia del intelecto humano, la m\u00e1s abrupta que haya ocurrido desde el comienzo de la ciencia moderna en el siglo XVII. \u00bfPodemos imaginar ahora como ser\u00eda?<\/p>\n<p><em> <\/em>Steven Weinberg<\/p>\n<p>&nbsp;<\/p><\/blockquote>\n<p style=\"text-align: justify;\"><em>emilio silvera<\/em><\/p>\n<hr \/>\n<p style=\"text-align: justify;\">El apunte sobre Ramanujan fue incluido en otro de mis trabajos. \u00a0Sin embargo, el presente cuaderno trata temas expresamente solicitados para utilizar en unos seminarios de f\u00edsica, y se me pidi\u00f3 incluir el tema \u201cRamanujan\u201d. La Fuente es diversa y precisar\u00eda una larga relaci\u00f3n.<\/p>\n<\/div>\n<div class='bookmark'>\r\n\t\t<table align='left' border='0' cellpadding='0' width='100%'>\r\n\t\t<tr><td><span class='pushbutton'><a href='http:\/\/delicious.com\/post?url=https%3A%2F%2Fwww.emiliosilveravazquez.com%2Fblog%2F2016%2F07%2F02%2Flas-misteriosas-funciones-modulares-3%2F&amp;title=Las+misteriosas+funciones++modulares' title='Delicious' target='_blank' rel='nofollow'><img src='https:\/\/www.emiliosilveravazquez.com\/blog\/wp-content\/plugins\/knxdt-bookmarks-wordpress-plugin\/images\/delicious.png'  alt='' class='book_img' border='none' style='margin:1px; padding: 0;'  \/><\/a><\/span><span class='pushbutton'><a href='http:\/\/digg.com\/submit?url=https%3A%2F%2Fwww.emiliosilveravazquez.com%2Fblog%2F2016%2F07%2F02%2Flas-misteriosas-funciones-modulares-3%2F&amp;title=Las+misteriosas+funciones++modulares' title='Digg' target='_blank' rel='nofollow'><img src='https:\/\/www.emiliosilveravazquez.com\/blog\/wp-content\/plugins\/knxdt-bookmarks-wordpress-plugin\/images\/digg.png'  alt='' class='book_img' border='none' style='margin:1px; padding: 0;'  \/><\/a><\/span><span class='pushbutton'><a href='http:\/\/www.google.com\/bookmarks\/mark?op=edit&amp;bkmk=https%3A%2F%2Fwww.emiliosilveravazquez.com%2Fblog%2F2016%2F07%2F02%2Flas-misteriosas-funciones-modulares-3%2F&amp;title=Las+misteriosas+funciones++modulares' title='Google' target='_blank' rel='nofollow'><img src='https:\/\/www.emiliosilveravazquez.com\/blog\/wp-content\/plugins\/knxdt-bookmarks-wordpress-plugin\/images\/google.png'   alt='' class='book_img' border='none' style='margin:1px; padding: 0;'  \/><\/a><\/span><span class='pushbutton'><a href='http:\/\/myweb2.search.yahoo.com\/myresults\/bookmarklet?u=https%3A%2F%2Fwww.emiliosilveravazquez.com%2Fblog%2F2016%2F07%2F02%2Flas-misteriosas-funciones-modulares-3%2F&amp;t=Las+misteriosas+funciones++modulares' title='Yahoo' target='_blank' rel='nofollow'><img src='https:\/\/www.emiliosilveravazquez.com\/blog\/wp-content\/plugins\/knxdt-bookmarks-wordpress-plugin\/images\/yahoo.png'  alt='' class='book_img' border='none' style='margin:1px; padding: 0;'  \/><\/a><\/span><span class='pushbutton'><a href='http:\/\/www.technorati.com\/faves?add=https%3A%2F%2Fwww.emiliosilveravazquez.com%2Fblog%2F2016%2F07%2F02%2Flas-misteriosas-funciones-modulares-3%2F' title='Technorati' target='_blank' rel='nofollow'><img src='https:\/\/www.emiliosilveravazquez.com\/blog\/wp-content\/plugins\/knxdt-bookmarks-wordpress-plugin\/images\/technorati.png'  alt='' class='book_img' border='none' style='margin:1px; padding: 0;'  \/><\/a><\/span><span class='pushbutton'><a href='http:\/\/meneame.net\/submit.php?url=https%3A%2F%2Fwww.emiliosilveravazquez.com%2Fblog%2F2016%2F07%2F02%2Flas-misteriosas-funciones-modulares-3%2F' title='Meneame' target='_blank' rel='nofollow'><img src='https:\/\/www.emiliosilveravazquez.com\/blog\/wp-content\/plugins\/knxdt-bookmarks-wordpress-plugin\/images\/meneame.png'  alt='' class='book_img' border='none' style='margin:1px; padding: 0;'  \/><\/a><\/span><span class='pushbutton'><a href='http:\/\/enchilame.com\/submit.php?url=https:\/\/www.emiliosilveravazquez.com\/blog\/2016\/07\/02\/las-misteriosas-funciones-modulares-3\/' target='_blank' rel='nofollow'><img title='Enchilame' src='https:\/\/www.emiliosilveravazquez.com\/blog\/wp-content\/plugins\/knxdt-bookmarks-wordpress-plugin\/images\/enchilame.png'  alt='' class='book_img' border='none' style='margin:1px; padding: 0;'  \/><\/a><\/span><span class='pushbutton'><a href='http:\/\/www.blinklist.com\/index.php?Action=Blink\/addblink.php&amp;Description=&amp;Url=https%3A%2F%2Fwww.emiliosilveravazquez.com%2Fblog%2F2016%2F07%2F02%2Flas-misteriosas-funciones-modulares-3%2F&amp;title=Las+misteriosas+funciones++modulares' title='BlinkList' target='_blank' rel='nofollow'><img src='https:\/\/www.emiliosilveravazquez.com\/blog\/wp-content\/plugins\/knxdt-bookmarks-wordpress-plugin\/images\/blinklist.png'  alt='' class='book_img' border='none' style='margin:1px; padding: 0;'  \/><\/a><\/span><span class='pushbutton'><a href='http:\/\/reddit.com\/submit?url=https%3A%2F%2Fwww.emiliosilveravazquez.com%2Fblog%2F2016%2F07%2F02%2Flas-misteriosas-funciones-modulares-3%2F&amp;title=Las+misteriosas+funciones++modulares' title='Reddit' target='_blank' rel='nofollow'><img src='https:\/\/www.emiliosilveravazquez.com\/blog\/wp-content\/plugins\/knxdt-bookmarks-wordpress-plugin\/images\/reddit.png'  alt='' class='book_img' border='none' style='margin:1px; padding: 0;'  \/><\/a><\/span><span class='pushbutton'><a href='http:\/\/www.tecnologiadiaria.com\/2009\/07\/abrir-com-hotmail-correo.html' target='_blank' title='hotmail'><img src='https:\/\/www.emiliosilveravazquez.com\/blog\/wp-content\/plugins\/knxdt-bookmarks-wordpress-plugin\/images\/linklove.png' alt='hotmail correo' class='book_img' border='none' style='margin:1px; padding: 0;' \/><\/a><\/span><span class='pushbutton'><a href='http:\/\/bitacoras.com\/votar\/anotacion\/externo\/mini\/www.emiliosilveravazquez.com\/blog\/2016\/07\/02\/las-misteriosas-funciones-modulares-3\/' title='Bitacoras.com' target='_blank' rel='nofollow'><img src='https:\/\/www.emiliosilveravazquez.com\/blog\/wp-content\/plugins\/knxdt-bookmarks-wordpress-plugin\/images\/bitacoras.png'  alt='' class='book_img' border='none' style='margin:1px; padding: 0;'  \/><\/a><\/span><span class='pushbutton'><a href='http:\/\/www.wikio.es\/vote?url=https%3A%2F%2Fwww.emiliosilveravazquez.com%2Fblog%2F2016%2F07%2F02%2Flas-misteriosas-funciones-modulares-3%2F' title='Wikio' target='_blank' rel='nofollow'><img src='https:\/\/www.emiliosilveravazquez.com\/blog\/wp-content\/plugins\/knxdt-bookmarks-wordpress-plugin\/images\/wikio.png'   alt='' class='book_img' border='none' style='margin:1px; padding: 0;'   \/><\/a><\/span><span class='pushbutton'><a href='http:\/\/friendfeed.com\/?url=https%3A%2F%2Fwww.emiliosilveravazquez.com%2Fblog%2F2016%2F07%2F02%2Flas-misteriosas-funciones-modulares-3%2F&amp;title=Las+misteriosas+funciones++modulares' title='Friend Feed' target='_blank' rel='nofollow'><img src='https:\/\/www.emiliosilveravazquez.com\/blog\/wp-content\/plugins\/knxdt-bookmarks-wordpress-plugin\/images\/friendfeed.png'  alt='' class='book_img' border='none' style='margin:1px; padding: 0;'  \/><\/a><\/span><span class='pushbutton'><a href='http:\/\/www.facebook.com\/share.php?u=https%3A%2F%2Fwww.emiliosilveravazquez.com%2Fblog%2F2016%2F07%2F02%2Flas-misteriosas-funciones-modulares-3%2F&amp;t=Las+misteriosas+funciones++modulares' title='Facebook' target='_blank' rel='nofollow'><img src='https:\/\/www.emiliosilveravazquez.com\/blog\/wp-content\/plugins\/knxdt-bookmarks-wordpress-plugin\/images\/facebook.png'  alt='' class='book_img' border='none' style='margin:1px; padding: 0;'  \/><\/a><\/span><span class='pushbutton'><a href='http:\/\/twitter.com\/home?status=Las+misteriosas+funciones++modulares: https%3A%2F%2Fwww.emiliosilveravazquez.com%2Fblog%2F2016%2F07%2F02%2Flas-misteriosas-funciones-modulares-3%2F' title='Twitter' target='_blank' rel='nofollow'><img src='https:\/\/www.emiliosilveravazquez.com\/blog\/wp-content\/plugins\/knxdt-bookmarks-wordpress-plugin\/images\/twitter.png'  alt='' class='book_img' border='none' style='margin:1px; padding: 0;'  \/><\/a><\/span><span class='pushbutton'><a href='http:\/\/www.feedburner.com\/fb\/a\/emailFlare?itemTitle=Las+misteriosas+funciones++modulares&amp;uri=https%3A%2F%2Fwww.emiliosilveravazquez.com%2Fblog%2F2016%2F07%2F02%2Flas-misteriosas-funciones-modulares-3%2F' title='Enviar por Email' target='_blank' rel='nofollow'><img src='https:\/\/www.emiliosilveravazquez.com\/blog\/wp-content\/plugins\/knxdt-bookmarks-wordpress-plugin\/images\/email.png'  alt='' class='book_img' border='none' style='margin:1px; padding: 0;'  \/><\/a><\/span><span style='font-weight:bold; padding-left: 5px;'><a href='http:\/\/wordpress.org\/extend\/plugins\/knxdt-bookmarks-wordpress-plugin\/' title='Plugin' rel='nofollow' target='_blank'>[?]<\/a><\/span><\/td><\/tr><\/table><br\/><br\/><\/div>","protected":false},"excerpt":{"rendered":"<p>\u00a0 \u00a1Interacciones fundamentales! Lyell y Darwin \u00a1El caprichoso destino! Al manipular los diagramas de lazos de Kikkawa, Sakita y Virasoro creados por cuerdas en interacci\u00f3n, all\u00ed est\u00e1n esas extra\u00f1as funciones modulares en las que el n\u00famero 10 aparecen en los lugares m\u00e1s extra\u00f1os. Estas funciones modulares son tan misteriosas como el hombre que las investig\u00f3, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_s2mail":"yes","footnotes":""},"categories":[178],"tags":[],"_links":{"self":[{"href":"https:\/\/www.emiliosilveravazquez.com\/blog\/wp-json\/wp\/v2\/posts\/15707"}],"collection":[{"href":"https:\/\/www.emiliosilveravazquez.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.emiliosilveravazquez.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.emiliosilveravazquez.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.emiliosilveravazquez.com\/blog\/wp-json\/wp\/v2\/comments?post=15707"}],"version-history":[{"count":0,"href":"https:\/\/www.emiliosilveravazquez.com\/blog\/wp-json\/wp\/v2\/posts\/15707\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.emiliosilveravazquez.com\/blog\/wp-json\/wp\/v2\/media?parent=15707"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.emiliosilveravazquez.com\/blog\/wp-json\/wp\/v2\/categories?post=15707"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.emiliosilveravazquez.com\/blog\/wp-json\/wp\/v2\/tags?post=15707"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}