{"id":7244,"date":"2026-07-16T09:58:34","date_gmt":"2026-07-16T08:58:34","guid":{"rendered":"http:\/\/www.emiliosilveravazquez.com\/blog\/?p=7244"},"modified":"2026-07-16T09:59:00","modified_gmt":"2026-07-16T08:59:00","slug":"%c2%bfcual-es-el-camino-no-hay-ningun-camino","status":"publish","type":"post","link":"http:\/\/www.emiliosilveravazquez.com\/blog\/2026\/07\/16\/%c2%bfcual-es-el-camino-no-hay-ningun-camino\/","title":{"rendered":"\u00bfCu\u00e1l es el Camino? No hay ning\u00fan camino."},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" class=\"\" src=\"https:\/\/www.turismodeobservacion.com\/media\/fotografias\/caravana-de-camellos-en-el-desierto-en-el-desierto-del-sahara-en-marruecos-turistas-en-camello-86953-xl.jpg\" alt=\"Caravana de camellos en el desierto en el Desierto del Sahara en Marruecos. Turistas en camello por Ra\u00fal Demangel | Fotograf\u00eda | Turismo de Observaci\u00f3n\" width=\"689\" height=\"459\" \/><\/p>\n<p><strong>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0No existen caminos, tenemos que crearlos<\/strong><\/p>\n<p style=\"text-align: justify;\"><span data-huuid=\"1729386057168873393\">El camino lo tenemos que hacer nosotros al andar, al trabajar, al buscar la respuesta&#8221; expresa la idea de que el destino o la meta no est\u00e1n preestablecidos, sino que se construyen a trav\u00e9s de las propias acciones, el esfuerzo y la b\u00fasqueda activa a lo largo de la vida.\u00a0<\/span><span data-huuid=\"1729386057168875390\">Es un llamado a la proactividad y a la creaci\u00f3n del propio futuro, en lugar de esperar un camino ya trazado.<span class=\"pjBG2e\" data-cid=\"5288d2c3-fd48-4649-a9ab-99e563cdc38e\"><span class=\"UV3uM\">\u00a0<\/span><\/span><\/span><\/p>\n<p style=\"text-align: justify;\">El Camino lo tenemos que hacer nosotros al andar. Lo mismo que se forma la vereda en la Monta\u00f1a cuando los seres vivos pasan por el mismo sitio una y otra vez, dando lugar a que se forme una vereda por aquel lugar que los viandantes han cre\u00eddo el m\u00e1s id\u00f3neo para transitar hacia alg\u00fan otro sitio. Lo tuvieron que elegir de manera racional al ser el m\u00e1s indicado y, por ese &#8220;camino&#8221; se cre\u00f3 el sendero por el que caminar. Antes all\u00ed, no hab\u00eda camino.<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"\" src=\"https:\/\/www.ucm.es\/infografias\/file\/proyecto-infografia-del-primer-viaje-de-colon-grupo-b1\/?ver\" alt=\"Infograf\u00edas Cient\u00edficas\" width=\"529\" height=\"374\" \/><\/p>\n<blockquote><p><strong>El viaje de Col\u00f3n<\/strong><\/p><\/blockquote>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"\" src=\"https:\/\/historia.nationalgeographic.com.es\/medio\/2020\/12\/21\/a-partida-de-vasco-da-gama-para-a-india-em-1497_209b9123_1200x630.jpg\" alt=\"Vasco da Gama y su peligroso viaje hacia la India por el sur de \u00c1frica\" width=\"532\" height=\"279\" \/><\/p>\n<h1 class=\"GW0XC indIKd cS4Vcb-pGL6qe-fwJd0c\">Vasco da Gama y su peligroso viaje hacia la India por el sur de \u00c1frica.<\/h1>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"\" src=\"https:\/\/content.api.news\/v3\/images\/bin\/e18ab9a6f374e87ddc2f97caa0fb6818?width=1280\" alt=\"James Cook rediscovered: the story of us | The Australian\" width=\"366\" height=\"206\" \/><img decoding=\"async\" loading=\"lazy\" class=\"\" src=\"https:\/\/www.lavanguardia.com\/files\/content_image_mobile_filter\/uploads\/2018\/10\/15\/5f15efaa36eca.jpeg\" alt=\"James Cook, el conquistador de las ant\u00edpodas\" width=\"313\" height=\"210\" \/><\/p>\n<h1 class=\"GW0XC indIKd cS4Vcb-pGL6qe-fwJd0c\">James Cook, el conquistador de las ant\u00edpodas<\/h1>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.newarab.com\/sites\/default\/files\/styles\/600x338\/public\/2023-08\/ILLUSTRATION_IBN_BATTUTA.jpg?h=c74750f6&amp;itok=VxTBxNPu\" alt=\"Was Ibn Battuta the greatest explorer of all time?\" \/><img decoding=\"async\" loading=\"lazy\" class=\"\" src=\"https:\/\/static.wixstatic.com\/media\/7335d9_febc40972fc64700ac27189c550b039b~mv2.jpeg\/v1\/fill\/w_750,h_521,al_c,q_85,enc_auto\/7335d9_febc40972fc64700ac27189c550b039b~mv2.jpeg\" width=\"605\" height=\"420\" \/><\/p>\n<h1 class=\"GW0XC indIKd cS4Vcb-pGL6qe-fwJd0c\" style=\"text-align: justify;\">Ibn Battuta, el mayor viajero musulm\u00e1n de todos los tiempos.<\/h1>\n<h1 class=\"GW0XC indIKd cS4Vcb-pGL6qe-fwJd0c\" style=\"text-align: justify;\"><\/h1>\n<p><strong>Todos los tenemos en la Mente:<\/strong><\/p>\n<ul class=\"i8Z77e\">\n<li class=\"TrT0Xe\"><strong>Crist\u00f3bal Col\u00f3n (1451-1506) &#8230;<\/strong><\/li>\n<li class=\"TrT0Xe\"><strong>Vasco da Gama (1460-1524) &#8230;<\/strong><\/li>\n<li class=\"TrT0Xe\"><strong>James Cook (1728-1779) &#8230;<\/strong><\/li>\n<li class=\"TrT0Xe\"><strong>Charles Robert Darwin (1809-1882) &#8230;<\/strong><\/li>\n<li class=\"TrT0Xe\"><strong>Ibn Battuta (1304-1368\/69) &#8230;<\/strong><\/li>\n<li class=\"TrT0Xe\"><strong>Sir Richard Francis Burton (1821 \u2013 1890) &#8230;<\/strong><\/li>\n<li class=\"TrT0Xe\"><strong>Ryszard Kapuscinski (1932-2007) &#8230;<\/strong><\/li>\n<li class=\"TrT0Xe\"><strong>Jeanne Baret (1740-1807)<\/strong><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"\" src=\"https:\/\/www.pilgrim.es\/wp-content\/uploads\/2019\/04\/camino-de-santiago-solo-1.jpg\" alt=\"El Camino de Santiago Solo | C\u00f3mo Encontrarse a uno Mismo | Pilgrim\" width=\"556\" height=\"303\" \/><img decoding=\"async\" loading=\"lazy\" class=\"\" src=\"https:\/\/lamenteesmaravillosa.com\/wp-content\/uploads\/2024\/09\/hombre-cima-atardecer-crecimiento-personal-768x432.jpg\" alt=\"8 pasos para lograr el crecimiento personal - La Mente es Maravillosa\" width=\"553\" height=\"311\" \/><\/p>\n<p>Mirar hacia el Horizonte y dar el primer paso, sin saber hasta donde nos llevar\u00e1<\/p>\n<p style=\"text-align: justify;\">No pocas veces, el camino se crea a partir de una idea, una intuici\u00f3n, una ganas de saber lo que hay m\u00e1s all\u00e1 de nuestros dominios, de explorar lo desconocido, de comprobar si la fascinaci\u00f3n que presentimos por lo que pensamos que &#8220;all\u00ed&#8221; pueda existir, se debe a una certera intuici\u00f3n, o, por el contrario, es s\u00f3lo un espejismo. No siempre el explorador encontr\u00f3 aquella civilizaci\u00f3n perdida que gritaba insistente en su mente llam\u00e1ndolo sin cesar, ni el cient\u00edfico encuentra la anhelada explicaci\u00f3n a un secreto de la Naturaleza que, tan claramente\u00a0 ve\u00eda en sus sue\u00f1os.<\/p>\n<p style=\"text-align: justify;\">Est\u00e1 claro que el mismo acto de la exploraci\u00f3n, modifica la perspectiva del explorador; Ni Ulises, Marco Polo o Col\u00f3n pod\u00edan ser los mismos cuando, despu\u00e9s de sus respectivas aventuras regresaron a sus hogares. Lo mismo ha sucedido con la investigaci\u00f3n cient\u00edfica en los extremos de las escalas, desde la grandiosa extensi\u00f3n del esapcio cosmol\u00f3gico&#8230;<a href=\"http:\/\/2.bp.blogspot.com\/-hoyqsAVE1C0\/T72EOP6-KPI\/AAAAAAAAM-g\/rRBD99nLjY4\/s1600\/distancias.gif\">\u00a0<\/a><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/2.bp.blogspot.com\/-hoyqsAVE1C0\/T72EOP6-KPI\/AAAAAAAAM-g\/rRBD99nLjY4\/s1600\/distancias.gif\"> <img decoding=\"async\" loading=\"lazy\" class=\"\" src=\"http:\/\/2.bp.blogspot.com\/-hoyqsAVE1C0\/T72EOP6-KPI\/AAAAAAAAM-g\/rRBD99nLjY4\/s320\/distancias.gif\" alt=\"\" width=\"469\" height=\"350\" border=\"0\" \/><\/a><\/p>\n<div><a href=\"http:\/\/2.bp.blogspot.com\/-KChZUEObKIQ\/T72ETZ6mSwI\/AAAAAAAAM-o\/YB23OJQuQTQ\/s1600\/galaxias_lente.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"\" src=\"http:\/\/2.bp.blogspot.com\/-KChZUEObKIQ\/T72ETZ6mSwI\/AAAAAAAAM-o\/YB23OJQuQTQ\/s320\/galaxias_lente.jpg\" alt=\"\" width=\"479\" height=\"362\" border=\"0\" \/><img decoding=\"async\" loading=\"lazy\" class=\"\" src=\"https:\/\/i.imgur.com\/e3JKcuB.png\" width=\"477\" height=\"320\" \/><\/a><\/div>\n<div><\/div>\n<div><\/div>\n<div><strong>&#8230; hasta el mundo min\u00fasculo y enloquecido de las part\u00edculas subat\u00f3micas<\/strong><\/div>\n<div><\/div>\n<div style=\"text-align: justify;\">Estos viajes nos cambiaron y cambiaron muchos de los conceptos ancestrales que, en nuestras mentes,\u00a0 estaban apaciblemente aposentados y, desafiaron muchas de las concepciones cient\u00edficas y tambi\u00e9n filos\u00f3ficas que m\u00e1s valor\u00e1bamos. Algunas, ante aquella realidad nueva, tuvieron que ser desechadas, como el bagaje que se deja atr\u00e1s en una larga y pesada traves\u00eda un desierto. Otras tuvieron que ser modificadas y reconstituidas hasta quedar casi irreconocibles.<\/div>\n<div><\/div>\n<div><\/div>\n<div style=\"text-align: justify;\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 <img decoding=\"async\" src=\"http:\/\/maniaticos.files.wordpress.com\/2009\/11\/cumulo_galaxias.jpg\" alt=\"http:\/\/maniaticos.files.wordpress.com\/2009\/11\/cumulo_galaxias.jpg\" \/><\/div>\n<div><\/div>\n<div><\/div>\n<div style=\"text-align: justify;\">La exploraci\u00f3n en el \u00e1mbito de las galaxias y c\u00famulos de galaxias extendi\u00f3 el alcance de la visi\u00f3n humana en un factor de 10<sup>26<\/sup> veces mayor que la propia escala humana, y produjo la revoluci\u00f3n que identificamos con la <a href=\"#\" onclick=\"referencia('relatividad',event); return false;\">relatividad<\/a>, la cual revel\u00f3 que la concepci\u00f3n newtoniana del mundo s\u00f3lo era un provincianismo dentro de un universo m\u00e1s vasto donde el espacio es curvo y el tiempo se hace flexible.<\/div>\n<div><\/div>\n<div><a href=\"https:\/\/youtu.be\/0IuIcWK7eEE\">https:\/\/youtu.be\/0IuIcWK7eEE<\/a><\/div>\n<div><\/div>\n<div><a href=\"https:\/\/youtu.be\/HiXUSyhpjuk\">https:\/\/youtu.be\/HiXUSyhpjuk<\/a><\/div>\n<div><\/div>\n<div><a href=\"https:\/\/youtu.be\/-2_usIkkl7E\">https:\/\/youtu.be\/-2_usIkkl7E<\/a><\/div>\n<div><\/div>\n<div><a href=\"https:\/\/youtu.be\/WnWJ7I3KrIQ\">https:\/\/youtu.be\/WnWJ7I3KrIQ<\/a><\/div>\n<div><\/div>\n<div><\/div>\n<div><a href=\"https:\/\/youtu.be\/WfzOI17JYEY\">https:\/\/youtu.be\/WfzOI17JYEY<\/a><\/div>\n<div><\/div>\n<div><\/div>\n<div><img decoding=\"async\" loading=\"lazy\" class=\"\" src=\"https:\/\/cdn.agenciasinc.es\/var\/ezwebin_site\/storage\/images\/_aliases\/img_1col\/noticias\/los-haces-de-protones-se-preparan-para-circular-por-el-lhc-esta-semana\/5346010-12-esl-MX\/Los-haces-de-protones-se-preparan-para-circular-por-el-LHC-esta-semana.jpg\" alt=\"Los haces de protones se preparan para circular por el LHC esta semana\" width=\"756\" height=\"505\" \/><\/div>\n<div><\/div>\n<div style=\"text-align: justify;\">La exploraci\u00f3n en el dominio subat\u00f3mico nos llev\u00f3 lejos en el \u00e1mbito de lo muy peque\u00f1o, a unos 10<sup>-15<\/sup> de la escala humana, y tambi\u00e9n signific\u00f3 una revoluci\u00f3n. Esta fue la f\u00edsica cu\u00e1ntica que transform\u00f3 todo lo que abord\u00f3 a partir de su nacimiento en 1900, cuando Max Planck, escribi\u00f3 aquel art\u00edculo de ocho p\u00e1ginas que fueron las semillas de las que m\u00e1s tarde, germinaron &#8220;las flores&#8221; de la M.C.. Planck, comprendi\u00f3 que s\u00f3lo pod\u00eda explicar lo que se llamaba la Curva del Cuerpo Negro -el espectro de energ\u00eda que genera un objeto de radiaci\u00f3n perfecta- si abandonaba el supuesto cl\u00e1sico de que la emisi\u00f3n de enetg\u00eda es continua, y lo reemplaz\u00f3 por la hip\u00f3tesis sin precedentes de que la energ\u00eda se emite en unidades discretas. Planck llam\u00f3 cuantos a estas unidades y quedaron simbolizadas por la letra h.<\/div>\n<div><\/div>\n<div><img decoding=\"async\" src=\"https:\/\/wikimedia.org\/api\/rest_v1\/media\/math\/render\/svg\/f2ee55300faabdbff114046bed1a1723960a1caa\" alt=\"{\\displaystyle E=hf\\,}\" \/><\/div>\n<div style=\"text-align: justify;\">Dado que la\u00a0<a title=\"Frecuencia\" href=\"https:\/\/es.wikipedia.org\/wiki\/Frecuencia\">frecuencia<\/a>\u00a0<i><span class=\"mwe-math-element\"><span class=\"mwe-math-mathml-inline mwe-math-mathml-a11y\">\ufffd<\/span><img decoding=\"async\" class=\"mwe-math-fallback-image-inline mw-invert\" src=\"https:\/\/wikimedia.org\/api\/rest_v1\/media\/math\/render\/svg\/132e57acb643253e7810ee9702d9581f159a1c61\" alt=\"f\" aria-hidden=\"true\" \/><\/span><\/i>, la\u00a0<a title=\"Longitud de onda\" href=\"https:\/\/es.wikipedia.org\/wiki\/Longitud_de_onda\">longitud de onda<\/a>\u00a0<i><span class=\"mwe-math-element\"><span class=\"mwe-math-mathml-inline mwe-math-mathml-a11y\">\ufffd<\/span><img decoding=\"async\" class=\"mwe-math-fallback-image-inline mw-invert\" src=\"https:\/\/wikimedia.org\/api\/rest_v1\/media\/math\/render\/svg\/b43d0ea3c9c025af1be9128e62a18fa74bedda2a\" alt=\"\\lambda \" aria-hidden=\"true\" \/><\/span><\/i>, y la\u00a0<a title=\"Velocidad de la luz\" href=\"https:\/\/es.wikipedia.org\/wiki\/Velocidad_de_la_luz\">velocidad de la luz<\/a>\u00a0<i><span class=\"mwe-math-element\"><span class=\"mwe-math-mathml-inline mwe-math-mathml-a11y\">\ufffd<\/span><img decoding=\"async\" class=\"mwe-math-fallback-image-inline mw-invert\" src=\"https:\/\/wikimedia.org\/api\/rest_v1\/media\/math\/render\/svg\/86a67b81c2de995bd608d5b2df50cd8cd7d92455\" alt=\"c\" aria-hidden=\"true\" \/><\/span><\/i>\u00a0cumplen\u00a0<span class=\"mwe-math-element\"><span class=\"mwe-math-mathml-inline mwe-math-mathml-a11y\">\ufffd\ufffd=\ufffd<\/span><img decoding=\"async\" class=\"mwe-math-fallback-image-inline mw-invert\" src=\"https:\/\/wikimedia.org\/api\/rest_v1\/media\/math\/render\/svg\/53f7859f76b2498f9fd6548f94f85e2e50b75cc6\" alt=\"{\\displaystyle \\lambda f=c}\" aria-hidden=\"true\" \/><\/span>\u00a0se puede expresar como:<\/div>\n<div><\/div>\n<div><img decoding=\"async\" src=\"https:\/\/wikimedia.org\/api\/rest_v1\/media\/math\/render\/svg\/5dbb63049ff36e30584940f483f17b0c68b68e1f\" alt=\"{\\displaystyle E={\\frac {hc}{\\lambda }}\\,}\" \/><\/div>\n<blockquote>\n<div style=\"text-align: justify;\">Constante universal, igual a\u00a0<b>6.55\u00d710<sup>&#8211;<\/sup><sup>27<\/sup>\u00a0ergios por segundo<\/b>. El cuanto de acci\u00f3n es la magnitud fundamental, descubierta por Planck (1900), de la mec\u00e1nica cu\u00e1ntica. Constituye un l\u00edmite especial entre los micro y los macro-fen\u00f3menos.<\/div>\n<\/blockquote>\n<div><\/div>\n<div style=\"text-align: justify;\">Plan no era ning\u00fan revolucionario -a la edad de 42 a\u00f1os era un viejo, juzgado por los patrones de las ciencias matem\u00e1ticas y, adem\u00e1s, un pilar de la elevada cultura germana del siglo XIX-, pero se percat\u00f3 f\u00e1cilmente de que el principio cu\u00e1ntico echar\u00eda abajo buena parte de la f\u00edsica cl\u00e1sica a la que hab\u00eda dedicado buena parte de su vida y de su carrera.<\/div>\n<div><\/div>\n<div style=\"text-align: justify;\">&#8220;Cuanto mayores sean sus dificultades -escribi\u00f3-&#8230; tanto m\u00e1s importante ser\u00e1 finalmente para la ampliaci\u00f3n y profundizaci\u00f3n del conocimiento de la F\u00edsica.&#8221; Aquellas palabras fueron prof\u00e9ticas: cambiando y desarroll\u00e1ndose constantemente, modificando su coloraci\u00f3n de manera tan impredecible como una reflexi\u00f3n en una\u00a0 burbuja de jab\u00f3n, la f\u00edsica cu\u00e1ntica pronto se expandi\u00f3 pr\u00e1cticamente a todo el \u00e1mbito de la f\u00edsica, y el cuanto de acci\u00f3n de Planck, h, lleg\u00f3 a ser considerado una constante de la naturaleza tan fundamental como la velocidad de la luz, c, de <a href=\"#\" onclick=\"referencia('einstein',event); return false;\">Einstein<\/a>.<\/div>\n<div><\/div>\n<div><\/div>\n<div style=\"text-align: justify;\"><img decoding=\"async\" loading=\"lazy\" class=\"\" src=\"http:\/\/www.mpe.mpg.de\/410729\/orbits3d_small_gif.gif\" alt=\"http:\/\/www.mpe.mpg.de\/410729\/orbits3d_small_gif.gif\" width=\"413\" height=\"330\" \/><\/div>\n<div><\/div>\n<div><\/div>\n<div style=\"text-align: justify;\">En una batalla entre los principios estrellas de la historia cu\u00e1ntica, s\u00f3lo puede haber un ganador. O no puede? . En el invierno de 1926-1927, Werner Heisenberg el brillante joven alem\u00e1n estaba trabajando como jefe asistente de Niels Bohr , alojado en un desv\u00e1n en la parte superior del instituto del gran dan\u00e9s de Copenhague. Despu\u00e9s de un d\u00eda de trabajo, Bohr se acercaba al encuentro con Heisenberg para hablar de f\u00edsica cu\u00e1ntica. A menudo se sentaban hasta altas horas de la noche, en un intenso debate sobre el significado de la teor\u00eda cu\u00e1ntica revolucionaria, entonces en su infancia.<\/div>\n<div><\/div>\n<div><\/div>\n<div><a href=\"https:\/\/youtu.be\/Sj3LK5XZ3Lo\">https:\/\/youtu.be\/Sj3LK5XZ3Lo<\/a><\/div>\n<div><\/div>\n<div><\/div>\n<div><\/div>\n<blockquote>\n<div style=\"text-align: justify;\">Los f\u00edsicos de part\u00edculas suelen encontrarse en sus vidas profesionales con el inconveniente de que aquello con lo que trabajan es tan sumamente peque\u00f1o que se vuelve\u00a0<strong>indetectable tanto para el ojo humano como para los m\u00e1s avanzados sistemas de microscop\u00eda<\/strong>. Es cierto que en la actualidad se pueden conseguir im\u00e1genes en las que se distinguen \u00e1tomos individuales cuando estos son lo suficientemente grandes, pero de ah\u00ed a poder visualizar un s\u00f3lo <a href=\"#\" onclick=\"referencia('proton',event); return false;\">prot\u00f3n<\/a>, o un a\u00fan m\u00e1s peque\u00f1o <a href=\"#\" onclick=\"referencia('electron',event); return false;\">electr\u00f3n<\/a>, hay un\u00a0<strong>escal\u00f3n insalvable para la t\u00e9cnica<\/strong>\u00a0actual.<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<\/blockquote>\n<div style=\"text-align: justify;\"><img decoding=\"async\" src=\"https:\/\/qph.cf2.quoracdn.net\/main-qimg-26eaae48c4861256d18cfafacbb3526b-lq\" alt=\"C\u00f3mo se explica que en las c\u00e1maras de niebla de un detector de part\u00edculas aparezcan claramente las trayectorias de las part\u00edculas, pudiendo saberse entonces su posici\u00f3n y velocidad? \u00bfNo es un claro\" \/><\/div>\n<div><\/div>\n<div style=\"text-align: justify;\">Un rompecabezas que se ponder\u00f3 eran los rastros de las gotitas que dejan los <a href=\"#\" onclick=\"referencia('electron',event); return false;\">electrones<\/a> al pasar a trav\u00e9s de las c\u00e1mara de niebla un aparato utilizado para rastrear los movimientos de part\u00edculas cargadas. Cuando Heisenberg trat\u00f3 de calcular estas aparentemente precisas trayectorias usando las ecuaciones de la mec\u00e1nica cu\u00e1ntica,\u00a0 no lo consigui\u00f3.<\/div>\n<div><\/div>\n<div style=\"text-align: justify;\">Una noche de mediados de febrero, Bohr hab\u00eda dejado la ciudad en un viaje de esqu\u00ed, y Heisenberg se hab\u00eda deslizado a tomar un poco de aire de la noche en las amplias avenidas de F\u00e6lled Parque, detr\u00e1s del instituto. Mientras caminaba, se le ocurri\u00f3. El rastro de los <a href=\"#\" onclick=\"referencia('electron',event); return false;\">electrones<\/a> no era preciso en lo absoluto: si uno lo mira de cerca, consiste en una serie de puntos difusos. Eso revel\u00f3 algo fundamental sobre la teor\u00eda cu\u00e1ntica. De vuelta en su \u00e1tico, Heisenberg escribi\u00f3 con entusiasmo su idea en una carta a su colega el f\u00edsico Wolfgang Pauli. Lo esencial de esto apareci\u00f3 en un documento unas pocas semanas m\u00e1s tarde: &#8220;Mientras m\u00e1s precisa la posici\u00f3n es determinada, menor precisi\u00f3n, en el momento se conoce en este instante, y viceversa.&#8221;<\/div>\n<div><\/div>\n<div><\/div>\n<div style=\"text-align: justify;\"><img decoding=\"async\" id=\"BLOGGER_PHOTO_ID_5607550772209662034\" src=\"http:\/\/2.bp.blogspot.com\/-rSN85nNKX8U\/TdIFt52GOFI\/AAAAAAAAAGU\/j8emOxXFTVA\/s400\/principio%2Bde%2Bincertidumbre.jpg\" alt=\"\" border=\"0\" \/><\/div>\n<div><\/div>\n<div><\/div>\n<div style=\"text-align: justify;\">As\u00ed el notorio <a href=\"#\" onclick=\"referencia('indeterminacion principio de',event); return false;\">principio de incertidumbre<\/a> de Heisenberg hab\u00eda nacido. Una declaraci\u00f3n de la <strong>incognoscibilidad<\/strong> fundamental del mundo cu\u00e1ntico, que se ha mantenido firme durante la mayor parte del siglo. Pero \u00bfpor cu\u00e1nto tiempo? Corren rumores de que un segundo principio cu\u00e1ntico \u2013 el entrelazamiento- puede sonar el ta\u00f1ido de muerte para la incertidumbre.<\/div>\n<div style=\"text-align: justify;\">S\u00f3lo podemos obtener respuestas parciales, cuya naturaleza est\u00e1 determinada en cierta medida por las cuestiones que optamos por indagar. Cuando Heisenberg calcul\u00f3 la cantidad m\u00ednima ineludible de incertidumbre que limita nuestra comprensi\u00f3n de los sucesos de peque\u00f1a escala, hall\u00f3 que est\u00e1 definida que nada menos que por h, el cuanto de acci\u00f3n de Planck.<\/div>\n<div><\/div>\n<div><\/div>\n<div style=\"text-align: justify;\"><img decoding=\"async\" loading=\"lazy\" id=\"il_fi\" src=\"http:\/\/2.bp.blogspot.com\/_62LJBP82YHk\/TKaLmsWBLCI\/AAAAAAAAAOU\/ZWoHwODegL0\/s1600\/los-ojos-en-el-mundo.jpg\" alt=\"\" width=\"497\" height=\"415\" \/><\/div>\n<div><\/div>\n<div><\/div>\n<div style=\"text-align: justify;\">La indeterminaci\u00f3n cu\u00e1ntica no depende del aparato experimental que podamos emplear para la investigaci\u00f3n del mundo subat\u00f3mico. Se trata, en la medida de nuestro conocimiento, de una limitaci\u00f3n absoluta, que los m\u00e1s destacados sabios de una civilizaci\u00f3n extraterrestre avanzada compartir\u00edan con los m\u00e1s humildes f\u00edsicos de la Tierra. En la f\u00edsica at\u00f3mica cl\u00e1sica se supon\u00eda que se pod\u00eda, en principio, medir las situaciones y trayectorias precisas de miles de millones de part\u00edculas -digamos, <a href=\"#\" onclick=\"referencia('proton',event); return false;\">protones<\/a>- y a partir de los datos resultantes hacer predicciones exactas de donde estar\u00edan los <a href=\"#\" onclick=\"referencia('proton',event); return false;\">protones<\/a> en determinado tiempo futuro.<\/div>\n<div><\/div>\n<div style=\"text-align: justify;\">Heisenberg demostr\u00f3 que tal supuesto era falso, que nunca podremos saberlo todo sobre la conducta de siquiera una s\u00f3la part\u00edcula, mucho menos de una gran cantidad de ellas, y, por lo tanto, nunca podremos hacer predicciones sobre el futuro que sean completamente exactas en todos los detalles. Esto marc\u00f3 un cambio fundamental en la visi\u00f3n del mundo de la f\u00edsica. Revelaba que no s\u00f3lo la materia y la energ\u00eda sino tambi\u00e9n el conocimiento est\u00e1n cuantizados.<\/div>\n<div><\/div>\n<div><\/div>\n<div><img decoding=\"async\" src=\"https:\/\/i.ytimg.com\/vi\/XSxLUHHriyo\/hq720.jpg?sqp=-oaymwEhCK4FEIIDSFryq4qpAxMIARUAAAAAGAElAADIQj0AgKJD&amp;rs=AOn4CLCL0i5uyv5MUEEO0njr_tUmyhq8dw\" alt=\"Principio de incertidumbre y espacio tiempo en Relatividad de Einstein\" \/><\/div>\n<div style=\"text-align: justify;\">\n<div><\/div>\n<\/div>\n<p style=\"text-align: justify;\">El <a href=\"#\" onclick=\"referencia('indeterminacion principio de',event); return false;\">principio de incertidumbre<\/a> es aplicado a modelos del espacio 3D ordinario, donde el espacio tiempo es continuo. En los sistema cuantizados con ret\u00edculos diminutos que conforman a los<strong> super-ejes,<\/strong> la informaci\u00f3n de las part\u00edculas pasa de un ret\u00edculo a otro o a una zona cu\u00e1ntica distinta del mismo ret\u00edculo. Dado que en el modelo de los eventos, los objetos no pertenecen a los eventos, simplemente evolucionan generando m\u00e1s informaci\u00f3n de nuevos eventos, la incertidumbre asociada a estos puede estar relacionada con radio del bucle de los ret\u00edculos diminutos, y para el traslado de la informaci\u00f3n de un ret\u00edculo a otro debe existir un nivel incertidumbre en cuanto a cual ret\u00edculo pertenece el evento durante la transferencia de dicha informaci\u00f3n, o \u00bfa qu\u00e9 conjunto de valores cu\u00e1nticos del mismo pertenece?<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.dailymotion.com\/video\/x397na1\">https:\/\/www.dailymotion.com\/video\/x397na1<\/a><\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/ishajudd.com\/wp-content\/uploads\/2017\/09\/jump_exercise_health_sun_mountain1.jpg\" alt=\"Un salto cu\u00e1ntico\" \/><\/p>\n<blockquote><p><strong>No, este no es el <a href=\"#\" onclick=\"referencia('salto cuantico',event); return false;\">salto cu\u00e1ntico<\/a>, es el salto de un necio<\/strong><\/p><\/blockquote>\n<p>&nbsp;<\/p>\n<blockquote><p><img decoding=\"async\" loading=\"lazy\" class=\"\" src=\"https:\/\/i.makeagif.com\/media\/1-06-2021\/nB5Y4g.gif\" alt=\"Salto Qu\u00e2ntico on Make a GIF\" width=\"445\" height=\"264\" \/><\/p>\n<p style=\"text-align: justify;\">Un <a href=\"#\" onclick=\"referencia('electron',event); return false;\">electr\u00f3n<\/a> est\u00e1 orbitando el n\u00facleo del \u00e1tomo y aparece un <a href=\"#\" onclick=\"referencia('foton',event); return false;\">fot\u00f3n<\/a> energ\u00e9tico que se choca contra \u00e9l, de inmediato, el <a href=\"#\" onclick=\"referencia('electron',event); return false;\">electr\u00f3n<\/a> desaparece y de manera simult\u00e1nea, aparece en una \u00f3rbita m\u00e1s cercana al n\u00facleo.<\/p>\n<p style=\"text-align: justify;\">Nadie ha podido explicar que es lo que pas\u00f3, el por qu\u00e9 se ha cambiado de una a otra \u00f3rbita, y, sobre todo&#8230; \u00bfPor donde hizo el viaje entre \u00f3rbitas?\u00a0 Si fu\u00e9semos capaces de comprender como lo hizo&#8230; \u00a1Tendr\u00edamos la respuesta para viajes a las estrellas!<\/p>\n<\/blockquote>\n<p style=\"text-align: justify;\">La mec\u00e1nica cu\u00e1ntica (el <a href=\"#\" onclick=\"referencia('salto cuantico',event); return false;\">salto cu\u00e1ntico<\/a> del <a href=\"#\" onclick=\"referencia('electron',event); return false;\">electr\u00f3n<\/a>) nos desvelar\u00e1 el secreto de c\u00f3mo el <a href=\"#\" onclick=\"referencia('electron',event); return false;\">electr\u00f3n<\/a> puede, al recibir un <a href=\"#\" onclick=\"referencia('foton',event); return false;\">fot\u00f3n<\/a>, desaparecer del nivel nuclear que ocupa para de manera instant\u00e1nea, y sin necesidad de recorrer la distancia que los separa, aparecer como por arte de magia en un nivel superior. Copiaremos el <a href=\"#\" onclick=\"referencia('salto cuantico',event); return false;\">salto cu\u00e1ntico<\/a> para viajar. Nos introduciremos en un cabina, marcaremos las coordenadas, pulsaremos un bot\u00f3n y desapareceremos en Madrid y de manera instant\u00e1nea, apareceremos de la nada en otra cabina igual situada en Nueva York a 6.000 Km de distancia.<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"http:\/\/2.bp.blogspot.com\/_Ak5CxSZ51vU\/S-kzFPZmyZI\/AAAAAAAAAEY\/XYI6QXFXvy8\/s1600\/SALTO+CUANTICO.jpg\"><img decoding=\"async\" loading=\"lazy\" src=\"http:\/\/2.bp.blogspot.com\/_Ak5CxSZ51vU\/S-kzFPZmyZI\/AAAAAAAAAEY\/XYI6QXFXvy8\/s1600\/SALTO+CUANTICO.jpg\" alt=\"\" width=\"614\" height=\"461\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">\u00bfQui\u00e9n sabe lo que podemos extraer del <a href=\"#\" onclick=\"referencia('salto cuantico',event); return false;\">salto cu\u00e1ntico<\/a>? El efecto t\u00fanel nos podr\u00eda dar la f\u00f3rmula para viajar a lugares lejanos. Creo que todos nuestros sue\u00f1os se podr\u00edan realizar si, en el momento adecuado, observando la Naturaleza, sabemos elegirt el camino que tenemos que andar para llegar a ese destino so\u00f1ado,,\u00a0 imaginado.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"\" src=\"http:\/\/1.bp.blogspot.com\/_xnpbZnamLKA\/TJJymVivNuI\/AAAAAAAAA7Y\/BqfBqcsf0ys\/s320\/saltocuantico.jpg\" alt=\"\" width=\"502\" height=\"523\" \/><\/p>\n<p style=\"text-align: justify;\">Nuestras Mentes buscar\u00e1n las formas de solucionar todos esos problemas complejos que ahora inquietan a la Humanidad.<\/p>\n<p style=\"text-align: justify;\">La F\u00edsica cu\u00e1ntica nos obliga a tomarnos en serio lo que antes eran puramente consideraciones filos\u00f3ficas: que no vemos las cosas en s\u00ed mismas, sino s\u00f3lo aspectos de las cosas. Lo que vemos en la trayectoria de un <a href=\"#\" onclick=\"referencia('electron',event); return false;\">electr\u00f3n<\/a> en la c\u00e1mara de niebla no es un <a href=\"#\" onclick=\"referencia('electron',event); return false;\">electr\u00f3n<\/a>, y lo que vemos en el cielo no son estrellas, <strong>como una grabaci\u00f3n de la voz de Pavoroti no es Pavarotti<\/strong>. Al revelar que el observador desempe\u00f1a un papel en la observaci\u00f3n, la f\u00edsica cu\u00e1ntica hizo por la f\u00edsica lo que Darwin ha hecho por las ciencias de la vida: Ech\u00f3 abajo las paredes, reunificando la Mente con el Universo m\u00e1s vasto.<\/p>\n<blockquote><p><strong>Emilio Silvera V.<\/strong><\/p><\/blockquote>\n<div class='bookmark'>\r\n\t\t<table align='left' border='0' cellpadding='0' width='100%'>\r\n\t\t<tr><td><span class='pushbutton'><a href='http:\/\/delicious.com\/post?url=http%3A%2F%2Fwww.emiliosilveravazquez.com%2Fblog%2F2026%2F07%2F16%2F%25c2%25bfcual-es-el-camino-no-hay-ningun-camino%2F&amp;title=%C2%BFCu%C3%A1l+es+el+Camino%3F+No+hay+ning%C3%BAn+camino.' title='Delicious' target='_blank' rel='nofollow'><img src='http:\/\/www.emiliosilveravazquez.com\/blog\/wp-content\/plugins\/knxdt-bookmarks-wordpress-plugin\/images\/delicious.png'  alt='' class='book_img' border='none' style='margin:1px; padding: 0;'  \/><\/a><\/span><span class='pushbutton'><a href='http:\/\/digg.com\/submit?url=http%3A%2F%2Fwww.emiliosilveravazquez.com%2Fblog%2F2026%2F07%2F16%2F%25c2%25bfcual-es-el-camino-no-hay-ningun-camino%2F&amp;title=%C2%BFCu%C3%A1l+es+el+Camino%3F+No+hay+ning%C3%BAn+camino.' title='Digg' target='_blank' rel='nofollow'><img src='http:\/\/www.emiliosilveravazquez.com\/blog\/wp-content\/plugins\/knxdt-bookmarks-wordpress-plugin\/images\/digg.png'  alt='' class='book_img' border='none' style='margin:1px; padding: 0;'  \/><\/a><\/span><span class='pushbutton'><a href='http:\/\/www.google.com\/bookmarks\/mark?op=edit&amp;bkmk=http%3A%2F%2Fwww.emiliosilveravazquez.com%2Fblog%2F2026%2F07%2F16%2F%25c2%25bfcual-es-el-camino-no-hay-ningun-camino%2F&amp;title=%C2%BFCu%C3%A1l+es+el+Camino%3F+No+hay+ning%C3%BAn+camino.' title='Google' target='_blank' rel='nofollow'><img src='http:\/\/www.emiliosilveravazquez.com\/blog\/wp-content\/plugins\/knxdt-bookmarks-wordpress-plugin\/images\/google.png'   alt='' class='book_img' border='none' style='margin:1px; padding: 0;'  \/><\/a><\/span><span class='pushbutton'><a href='http:\/\/myweb2.search.yahoo.com\/myresults\/bookmarklet?u=http%3A%2F%2Fwww.emiliosilveravazquez.com%2Fblog%2F2026%2F07%2F16%2F%25c2%25bfcual-es-el-camino-no-hay-ningun-camino%2F&amp;t=%C2%BFCu%C3%A1l+es+el+Camino%3F+No+hay+ning%C3%BAn+camino.' title='Yahoo' target='_blank' rel='nofollow'><img src='http:\/\/www.emiliosilveravazquez.com\/blog\/wp-content\/plugins\/knxdt-bookmarks-wordpress-plugin\/images\/yahoo.png'  alt='' class='book_img' border='none' style='margin:1px; padding: 0;'  \/><\/a><\/span><span class='pushbutton'><a href='http:\/\/www.technorati.com\/faves?add=http%3A%2F%2Fwww.emiliosilveravazquez.com%2Fblog%2F2026%2F07%2F16%2F%25c2%25bfcual-es-el-camino-no-hay-ningun-camino%2F' title='Technorati' target='_blank' rel='nofollow'><img src='http:\/\/www.emiliosilveravazquez.com\/blog\/wp-content\/plugins\/knxdt-bookmarks-wordpress-plugin\/images\/technorati.png'  alt='' class='book_img' border='none' style='margin:1px; padding: 0;'  \/><\/a><\/span><span class='pushbutton'><a href='http:\/\/meneame.net\/submit.php?url=http%3A%2F%2Fwww.emiliosilveravazquez.com%2Fblog%2F2026%2F07%2F16%2F%25c2%25bfcual-es-el-camino-no-hay-ningun-camino%2F' title='Meneame' target='_blank' rel='nofollow'><img src='http:\/\/www.emiliosilveravazquez.com\/blog\/wp-content\/plugins\/knxdt-bookmarks-wordpress-plugin\/images\/meneame.png'  alt='' class='book_img' border='none' style='margin:1px; padding: 0;'  \/><\/a><\/span><span class='pushbutton'><a href='http:\/\/enchilame.com\/submit.php?url=http:\/\/www.emiliosilveravazquez.com\/blog\/2026\/07\/16\/%c2%bfcual-es-el-camino-no-hay-ningun-camino\/' target='_blank' rel='nofollow'><img title='Enchilame' src='http:\/\/www.emiliosilveravazquez.com\/blog\/wp-content\/plugins\/knxdt-bookmarks-wordpress-plugin\/images\/enchilame.png'  alt='' class='book_img' border='none' style='margin:1px; padding: 0;'  \/><\/a><\/span><span class='pushbutton'><a href='http:\/\/www.blinklist.com\/index.php?Action=Blink\/addblink.php&amp;Description=&amp;Url=http%3A%2F%2Fwww.emiliosilveravazquez.com%2Fblog%2F2026%2F07%2F16%2F%25c2%25bfcual-es-el-camino-no-hay-ningun-camino%2F&amp;title=%C2%BFCu%C3%A1l+es+el+Camino%3F+No+hay+ning%C3%BAn+camino.' title='BlinkList' target='_blank' rel='nofollow'><img src='http:\/\/www.emiliosilveravazquez.com\/blog\/wp-content\/plugins\/knxdt-bookmarks-wordpress-plugin\/images\/blinklist.png'  alt='' class='book_img' border='none' style='margin:1px; padding: 0;'  \/><\/a><\/span><span class='pushbutton'><a href='http:\/\/reddit.com\/submit?url=http%3A%2F%2Fwww.emiliosilveravazquez.com%2Fblog%2F2026%2F07%2F16%2F%25c2%25bfcual-es-el-camino-no-hay-ningun-camino%2F&amp;title=%C2%BFCu%C3%A1l+es+el+Camino%3F+No+hay+ning%C3%BAn+camino.' title='Reddit' target='_blank' rel='nofollow'><img src='http:\/\/www.emiliosilveravazquez.com\/blog\/wp-content\/plugins\/knxdt-bookmarks-wordpress-plugin\/images\/reddit.png'  alt='' class='book_img' border='none' style='margin:1px; padding: 0;'  \/><\/a><\/span><span class='pushbutton'><a href='http:\/\/www.tecnologiadiaria.com\/2009\/07\/abrir-com-hotmail-correo.html' target='_blank' title='hotmail'><img src='http:\/\/www.emiliosilveravazquez.com\/blog\/wp-content\/plugins\/knxdt-bookmarks-wordpress-plugin\/images\/linklove.png' alt='hotmail correo' class='book_img' border='none' style='margin:1px; padding: 0;' \/><\/a><\/span><span class='pushbutton'><a href='http:\/\/bitacoras.com\/votar\/anotacion\/externo\/mini\/www.emiliosilveravazquez.com\/blog\/2026\/07\/16\/%c2%bfcual-es-el-camino-no-hay-ningun-camino\/' title='Bitacoras.com' target='_blank' rel='nofollow'><img src='http:\/\/www.emiliosilveravazquez.com\/blog\/wp-content\/plugins\/knxdt-bookmarks-wordpress-plugin\/images\/bitacoras.png'  alt='' class='book_img' border='none' style='margin:1px; padding: 0;'  \/><\/a><\/span><span class='pushbutton'><a href='http:\/\/www.wikio.es\/vote?url=http%3A%2F%2Fwww.emiliosilveravazquez.com%2Fblog%2F2026%2F07%2F16%2F%25c2%25bfcual-es-el-camino-no-hay-ningun-camino%2F' title='Wikio' target='_blank' rel='nofollow'><img src='http:\/\/www.emiliosilveravazquez.com\/blog\/wp-content\/plugins\/knxdt-bookmarks-wordpress-plugin\/images\/wikio.png'   alt='' class='book_img' border='none' style='margin:1px; padding: 0;'   \/><\/a><\/span><span class='pushbutton'><a href='http:\/\/friendfeed.com\/?url=http%3A%2F%2Fwww.emiliosilveravazquez.com%2Fblog%2F2026%2F07%2F16%2F%25c2%25bfcual-es-el-camino-no-hay-ningun-camino%2F&amp;title=%C2%BFCu%C3%A1l+es+el+Camino%3F+No+hay+ning%C3%BAn+camino.' title='Friend Feed' target='_blank' rel='nofollow'><img src='http:\/\/www.emiliosilveravazquez.com\/blog\/wp-content\/plugins\/knxdt-bookmarks-wordpress-plugin\/images\/friendfeed.png'  alt='' class='book_img' border='none' style='margin:1px; padding: 0;'  \/><\/a><\/span><span class='pushbutton'><a href='http:\/\/www.facebook.com\/share.php?u=http%3A%2F%2Fwww.emiliosilveravazquez.com%2Fblog%2F2026%2F07%2F16%2F%25c2%25bfcual-es-el-camino-no-hay-ningun-camino%2F&amp;t=%C2%BFCu%C3%A1l+es+el+Camino%3F+No+hay+ning%C3%BAn+camino.' title='Facebook' target='_blank' rel='nofollow'><img src='http:\/\/www.emiliosilveravazquez.com\/blog\/wp-content\/plugins\/knxdt-bookmarks-wordpress-plugin\/images\/facebook.png'  alt='' class='book_img' border='none' style='margin:1px; padding: 0;'  \/><\/a><\/span><span class='pushbutton'><a href='http:\/\/twitter.com\/home?status=%C2%BFCu%C3%A1l+es+el+Camino%3F+No+hay+ning%C3%BAn+camino.: http%3A%2F%2Fwww.emiliosilveravazquez.com%2Fblog%2F2026%2F07%2F16%2F%25c2%25bfcual-es-el-camino-no-hay-ningun-camino%2F' title='Twitter' target='_blank' rel='nofollow'><img src='http:\/\/www.emiliosilveravazquez.com\/blog\/wp-content\/plugins\/knxdt-bookmarks-wordpress-plugin\/images\/twitter.png'  alt='' class='book_img' border='none' style='margin:1px; padding: 0;'  \/><\/a><\/span><span class='pushbutton'><a href='http:\/\/www.feedburner.com\/fb\/a\/emailFlare?itemTitle=%C2%BFCu%C3%A1l+es+el+Camino%3F+No+hay+ning%C3%BAn+camino.&amp;uri=http%3A%2F%2Fwww.emiliosilveravazquez.com%2Fblog%2F2026%2F07%2F16%2F%25c2%25bfcual-es-el-camino-no-hay-ningun-camino%2F' title='Enviar por Email' target='_blank' rel='nofollow'><img src='http:\/\/www.emiliosilveravazquez.com\/blog\/wp-content\/plugins\/knxdt-bookmarks-wordpress-plugin\/images\/email.png'  alt='' class='book_img' border='none' style='margin:1px; padding: 0;'  \/><\/a><\/span><span style='font-weight:bold; padding-left: 5px;'><a href='http:\/\/wordpress.org\/extend\/plugins\/knxdt-bookmarks-wordpress-plugin\/' title='Plugin' rel='nofollow' target='_blank'>[?]<\/a><\/span><\/td><\/tr><\/table><br\/><br\/><\/div>","protected":false},"excerpt":{"rendered":"<p>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0No existen caminos, tenemos que crearlos El camino lo tenemos que hacer nosotros al andar, al trabajar, al buscar la respuesta&#8221; expresa la idea de que el destino o la meta no est\u00e1n preestablecidos, sino que se [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_s2mail":"yes","footnotes":""},"categories":[7],"tags":[],"_links":{"self":[{"href":"http:\/\/www.emiliosilveravazquez.com\/blog\/wp-json\/wp\/v2\/posts\/7244"}],"collection":[{"href":"http:\/\/www.emiliosilveravazquez.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.emiliosilveravazquez.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.emiliosilveravazquez.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/www.emiliosilveravazquez.com\/blog\/wp-json\/wp\/v2\/comments?post=7244"}],"version-history":[{"count":0,"href":"http:\/\/www.emiliosilveravazquez.com\/blog\/wp-json\/wp\/v2\/posts\/7244\/revisions"}],"wp:attachment":[{"href":"http:\/\/www.emiliosilveravazquez.com\/blog\/wp-json\/wp\/v2\/media?parent=7244"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.emiliosilveravazquez.com\/blog\/wp-json\/wp\/v2\/categories?post=7244"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.emiliosilveravazquez.com\/blog\/wp-json\/wp\/v2\/tags?post=7244"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}