{"id":35083,"date":"2026-01-13T09:30:13","date_gmt":"2026-01-13T08:30:13","guid":{"rendered":"https:\/\/www.emiliosilveravazquez.com\/blog\/?p=35083"},"modified":"2026-01-13T09:30:13","modified_gmt":"2026-01-13T08:30:13","slug":"asentamiento-en-marte-no-parece-muy-viable","status":"publish","type":"post","link":"http:\/\/www.emiliosilveravazquez.com\/blog\/2026\/01\/13\/asentamiento-en-marte-no-parece-muy-viable\/","title":{"rendered":"\u00bfAsentamiento en Marte? No parece muy viable"},"content":{"rendered":"<p><iframe loading=\"lazy\" title=\"1h de CARL SAGAN Para Dormir: \u00bfPor qu\u00e9 Nunca llegaremos a MARTE?\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/ccGQp3vOEvA?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p>Son tantos los problemas que nos impiden viajar y vivir en Marte que, enumerarlos es complicado, ya que, muchos de esos problemas, ni los conocemos.<\/p>\n<p>Por ejemplo:<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"\" src=\"https:\/\/fotografias-2.larazon.es\/clipping\/cmsimages02\/2025\/11\/30\/4B233B0B-FE5B-4455-A8E6-1A4F020B7BEB\/imagenes-rayos-marte_98.jpg?crop=1900,1069,x0,y0&amp;width=1900&amp;height=1069&amp;optimize=low&amp;format=webply\" alt=\"Un rover de la NASA ha captado el sonido de un rayo en Marte por primera vez en la historia revelando otro misterio de nuestro des\u00e9rtico planeta vecino\" width=\"736\" height=\"414\" \/><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">La\u00a0<b>ausencia de un campo magn\u00e9tico global<\/b>\u00a0en Marte, junto con la tenue atm\u00f3sfera del planeta, implica que rayos c\u00f3smicos de alta energ\u00eda y part\u00edculas solares inunden la superficie marciana. Estas altas dosis de radiaci\u00f3n y los riesgos para la salud asociados podr\u00edan obstaculizar la actividad humana en el Planeta Rojo y el viaje de ida y vuelta.<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/blogger.googleusercontent.com\/img\/b\/R29vZ2xl\/AVvXsEjNOTx2AuedKboma8denzN_2VZqJBk5l6vmJQ2wnT7x7Zh3GDtq3vQdLxUhmEZD4i8Os_OT8BiQ1AeTq4PRUUtXZsYy5Di4PRBd8GGSZ3McKoAxdkNz7LmkIEMbpcveF0MUnhGp\/s1600\/earthmarsorbittop.jpg\" alt=\"Eureka: C\u00f3mo viajar a Marte\" \/><img decoding=\"async\" loading=\"lazy\" class=\"\" src=\"https:\/\/e01-phantom-elmundo.uecdn.es\/f1f1b1d7ff537e9a47b46e75f7f20326\/resize\/828\/f\/webp\/assets\/multimedia\/imagenes\/2022\/12\/05\/16702612638005.jpg\" alt=\"Marte en oposici\u00f3n: cercano, superbrillante y ocultado por la Luna durante 46 minutos | Ciencia\" width=\"537\" height=\"358\" \/><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">Aunque en el contexto de la Galaxia y m\u00e1s concretamente en el \u00e1mbito del Sistema solar, el planetas rojo est\u00e1 a la vuelta de la esquina<b>, <\/b>en lo que se refiere a la tecnolog\u00eda de la que hoy disponemos,\u00a0<b> Marte est\u00e1 demasiado lejos<\/b>. Marte y la Tierra no orbitan alrededor del Sol a la misma velocidad, por lo que la distancia entre ellos var\u00eda. Se necesitan unos nueve meses para viajar a Marte, lo que significa que es necesario partir durante una &#8220;ventana de lanzamiento&#8221; espec\u00edfica para minimizar el tiempo de viaje.<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"\" src=\"https:\/\/skycr.org\/wp-content\/uploads\/2024\/12\/hombres-en-marte-con-ciudades.png\" alt=\"Primer asentamiento humano en Marte no est\u00e1 tan lejos como algunos creen - SKYCR.ORG: NASA, exploraci\u00f3n espacial y noticias astron\u00f3micas\" width=\"600\" height=\"450\" \/><img decoding=\"async\" src=\"https:\/\/images.ecestaticos.com\/zvEa66z-yVQQnZyzAGa2AghCip0=\/0x0:2180x1226\/600x315\/filters:fill(white):format(jpg):quality(99):watermark(f.elconfidencial.com\/file\/bae\/eea\/fde\/baeeeafde1b3229287b0c008f7602058.png,0,275,1)\/f.elconfidencial.com\/original\/9d6\/399\/230\/9d6399230168a3a6006591223f18fe1b.jpg\" alt=\"As\u00ed ser\u00e1n los primeros 10.000 d\u00edas de la humanidad en Marte\" \/><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">Adem\u00e1s de las necesidades b\u00e1sicas de supervivencia,\u00a0<b>la gente se enfrentar\u00eda a otros problemas al vivir en Marte<\/b>. Por ejemplo, las noches son extremadamente fr\u00edas, por debajo de los -38 \u00b0C. Marte tambi\u00e9n tiene tormentas de polvo, altos niveles de radiaci\u00f3n y menos gravedad que la Tierra. Antes de que podamos considerar al Planeta Rojo nuestro hogar, tendremos que solucionar estos problemas.<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/preview.redd.it\/new-research-suggests-that-mars-may-have-been-habitable-v0-g4cqmpcx4kjf1.jpeg?width=640&amp;crop=smart&amp;auto=webp&amp;s=21d24e18010a572873aaed796618a092096b40db\" alt=\"Una nueva investigaci\u00f3n sugiere que Marte pudo haber sido habitable hace m\u00e1s de 3 mil millones de a\u00f1os, antes que la Tierra, probablemente con oc\u00e9anos l\u00edquidos (Ve la secci\u00f3n de comentarios para\" \/><\/p>\n<p>Nos dicen que los vestigios encontrados en Marte nos dicen que hace miles de millones de a\u00f1os, fue habitable, atm\u00f3sfera y oc\u00e9anos y agua corriente. No sabemos, a Ciencia cierta, por qu\u00e9 todo eso desapareci\u00f3.<\/p>\n<p><strong>Lo cierto es que&#8230;<\/strong><\/p>\n<p style=\"text-align: justify;\"><b>Hasta la fecha a\u00fan no se ha podido encontrar evidencia definitiva que confirme la existencia presente o pasada de vida en Marte<\/b>. Sin embargo, se posee evidencia acumulativa que favorece la posibilidad de que Marte, en un pasado, haya albergado agua y que esta haya sido \u00f3ptima para poder sostener vida.<\/p>\n<p>La frustraci\u00f3n de las dificultades de viajar a Marte, nos hace pensar en&#8230;<\/p>\n<p><b>Regresar a la Luna que la tenemos m\u00e1s a mano.<\/b><\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"\" src=\"https:\/\/www.nasa.gov\/wp-content\/uploads\/2023\/03\/artemis_ii_public_spanish_002.jpg?w=1041\" alt=\"Mapa de Artemis II - NASA\" width=\"673\" height=\"379\" \/><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">Artemis II ser\u00e1 el primer vuelo con tripulaci\u00f3n a bordo del sistema de exploraci\u00f3n del espacio profundo de la NASA: la nave Orion, el cohete Sistema de Lanzamiento Espacial (SLS, por sus siglas en ingl\u00e9s) y los sistemas terrestres del Centro Espacial Kennedy de Cabo Ca\u00f1averal (Florida). Durante su misi\u00f3n, cuatro astronautas confirmar\u00e1n que todos los sistemas de la nave espacial funcionan seg\u00fan lo previsto con pasajeros a bordo en el entorno real del espacio profundo, durante una misi\u00f3n de unos 10 d\u00edas. El vuelo de prueba de Artemis II allanar\u00e1 el camino para el aterrizaje de la primera mujer y el pr\u00f3ximo hombre en la Luna con Artemis III.<\/p>\n<p><strong>Artemis II,<\/strong> cuyo lanzamiento est\u00e1 previsto entre febrero y abril, supone el regreso de las primeras personas a la Luna desde el Apolo 17 en 1972. Tres astronautas estadounidenses y uno canadiense orbitar\u00e1n la Luna en un viaje de 10 d\u00edas que sienta las bases para los alunizajes de los pr\u00f3ximos a\u00f1os.<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"\" src=\"https:\/\/fotografias.lasexta.com\/clipping\/cmsimages01\/2019\/06\/14\/47410532-5865-4DBC-9FF0-AC7AB43A218A\/98.jpg?crop=2998,1687,x0,y0&amp;width=1900&amp;height=1069&amp;optimize=high&amp;format=webply\" alt=\"La radiaci\u00f3n, uno de los mayores obst\u00e1culos para instalarnos en Marte\" width=\"682\" height=\"384\" \/><\/p>\n<p>No tenemos trajes espaciales con capacidad de impedir la entrada de la radiaci\u00f3n<\/p>\n<p>Un nuevo estudio publicado en la revista<strong> Nature<\/strong> revela las graves consecuencias que la radiaci\u00f3n espacial podr\u00eda tener en los astronautas que viajen al planeta rojo. Un viaje de ida y vuelta a Marte\u00a0<b>podr\u00eda ocasionar graves da\u00f1os renales a los astronautas, incluso permanentes, con la necesidad de di\u00e1lisis a su regreso<\/b>.<\/p>\n<p>&nbsp;<\/p>\n<blockquote><p><img decoding=\"async\" loading=\"lazy\" class=\"\" src=\"https:\/\/upload.wikimedia.org\/wikipedia\/commons\/5\/50\/Space_fluid_shift.gif\" alt=\"Effect of spaceflight on the human body - Wikipedia\" width=\"440\" height=\"227\" \/><\/p>\n<p>&nbsp;<\/p><\/blockquote>\n<p style=\"text-align: justify;\">La radiaci\u00f3n en Marte es un desaf\u00edo importante para la exploraci\u00f3n y para la vida, la tenue atm\u00f3sfera del planeta Marte y la falta de un campo magn\u00e9tico que envuelva al planeta como el de la Tierra, lo que expone la superficie a altos niveles de radiaci\u00f3n ultravioleta (UV), aunque recientes estudios sugieren que la UV no es totalmente incompatible con la vida, pareci\u00e9ndose a la Tierra primitiva, lo que subraya la necesidad de protecci\u00f3n para astronautas y estrictas medidas de contaminaci\u00f3n planetaria.<span class=\"uJ19be notranslate\" data-wiz-uids=\"XGy3Od_e,XGy3Od_f\"><span class=\"vKEkVd\" data-animation-atomic=\"\" data-wiz-attrbind=\"class=XGy3Od_d\/TKHnVd\">\u00a0<\/span><\/span><\/p>\n<p>&nbsp;<\/p>\n<blockquote><p><img decoding=\"async\" loading=\"lazy\" class=\"\" src=\"https:\/\/resizer.iproimg.com\/unsafe\/768x\/filters:format(webp):quality(75):max_bytes(102400)\/https:\/\/assets.iproup.com\/assets\/jpg\/2019\/11\/6811.jpg\" alt=\"Elon Musk confirma cuando viajar\u00e1 a Marte con SpaceX\" width=\"672\" height=\"378\" \/><\/p>\n<div class=\"image-container img-wide padding-b\">\n<div class=\"txts\">\n<h1 class=\"title full padding-lr\">Elon Musk confirma fecha para su viaje a Marte con SpaceX y revela cuando espera colonizar el planeta<\/h1>\n<\/div>\n<\/div>\n<p style=\"text-align: justify;\">La justificaci\u00f3n de Musk para colonizar el planeta rojo ha evolucionado con el tiempo. En 2018,\u00a0<b>el empresario enfatizaba la necesidad de tener una &#8220;base autosostenible en Marte&#8221; como refugio ante amenazas inmediatas.<\/b><\/p>\n<\/blockquote>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.rosario3.com\/__export\/1667412236597\/sites\/rosario3\/img\/2022\/11\/02\/2_1.jpg_529145118.jpg\" alt=\"Foto: as\u00ed se ver\u00edan los ni\u00f1os nacidos en Marte seg\u00fan una predicci\u00f3n hecha con inteligencia artificial | Rosario3\" \/><\/p>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"\" src=\"https:\/\/external-preview.redd.it\/can-you-have-a-baby-on-mars-v0-2nIHrIrmmc4o6GEGjYQtRcBmjd2ek2-WRKzUEB3l2ak.jpeg?auto=webp&amp;s=5247ab940ae40e54613ab294410e97f8c30f2d66\" alt=\"Se puede tener un beb\u00e9 en Marte? : r\/Mars\" width=\"366\" height=\"205\" \/><\/p>\n<p>No parece muy factible la posibilidad de tal evento en Marte<\/p>\n<p style=\"text-align: justify;\">El entorno marciano plantea desaf\u00edos especiales para los futuros padres del Planeta Rojo y sus descendientes.\u00a0<b>Los efectos de la radiaci\u00f3n solar y de los rayos c\u00f3smicos, la reducci\u00f3n de la gravedad, la exposici\u00f3n a toxinas ambientales e incluso la alteraci\u00f3n del ritmo circadiano pueden afectar tanto a los padres como a la descendencia<\/b>\u00a0.<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"\" src=\"https:\/\/i.blogs.es\/dc119c\/aldrin\/840_560.jpeg\" alt=\"La idea de que la NASA nunca lleg\u00f3 a la Luna sigue viva. El problema: hasta China ha fotografiado los restos de Apolo 11\" width=\"650\" height=\"433\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>La aventura del Apolo a la Luna cost\u00f3 ingentes cantidades de dinero. \u00bfCu\u00e1nto costar\u00eda una misi\u00f3n tripulada a Marte?<\/p>\n<div class=\"webanswers-webanswers_table__webanswers-table\"><\/div>\n<div><img decoding=\"async\" loading=\"lazy\" class=\"\" src=\"https:\/\/www.infobae.com\/resizer\/v2\/https%3A%2F%2Fs3.amazonaws.com%2Farc-wordpress-client-uploads%2Finfobae-wp%2Fwp-content%2Fuploads%2F2017%2F02%2F22150558%2FNASA-1920.jpg?auth=cff09f1653d923dc0348ef75df3ffbc4669b426a78faac376b4845d25a4396fa&amp;smart=true&amp;width=1200&amp;height=630&amp;quality=85\" alt=\"Los 5 planetas m\u00e1s habitables, seg\u00fan la NASA - Infobae\" width=\"690\" height=\"362\" \/><\/div>\n<div><\/div>\n<div>No pocos son los mundos que situados en la zona habitables de sus estrellas, podr\u00edan ser habitables para los humanos.<\/div>\n<div>Pensar en un viaje a Pr\u00f3xima b, situado a 2,4 a\u00f1os luz de la Tierra, supone un reto insuperable para nosotros. Pensar en ir a otros mundos mucho m\u00e1s alejados&#8230; \u00a1Un sue\u00f1o irrealizable!<\/div>\n<div><\/div>\n<div>La reiteraci\u00f3n de insistir en viajar a Marte por ser el planeta cercano que podr\u00eda tener m\u00e1s posibilidades (muy pocas), es la manera de ocultar lo que nunca podremos, viajar a otros mundos. Si la Naturaleza es sabia, habr\u00eda que preguntar \u00bfPor qu\u00e9 coloc\u00f3 a las estrellas tan alejadas las unas de las otras. Y, adem\u00e1s, \u00bfPor qu\u00e9 el Espacio es tan inadecuado para nosotros?<\/div>\n<div><\/div>\n<div><\/div>\n<div><img decoding=\"async\" src=\"https:\/\/i.ytimg.com\/vi\/cjBJuF4l_5Q\/sddefault.jpg\" alt=\"Los robots revolucionan nuestro mundo: humanoides, viajes espaciales, IA y m\u00e1s | Pro robots - YouTube\" \/><\/div>\n<div><\/div>\n<div style=\"text-align: justify;\">No queremos reconocer que estamos confinados en este peque\u00f1o mundo y si no cambian muchas cosas (incluida mutaciones en nuestro f\u00edsico), los viajes a otros mundos estar\u00e1n predestinados para que los ejecute una nueva raza, los humanoides &#8220;fabricados&#8221; por los humanos. Robots de \u00faltima generaci\u00f3n a los que no les afecta nada de lo que rese\u00f1amos anteriormente.<\/div>\n<div><\/div>\n<div style=\"text-align: justify;\">Puede que el narrador del del Video lleve raz\u00f3n cuando nos aconseja dedicar los esfuerzos humanos y econ\u00f3micos a lo que pasa en la Tierra, nuestro \u00fanico y verdadero mundo. Todo lo dem\u00e1s&#8230;Teor\u00edas, Conjeturas, Sue\u00f1os, Fantas\u00edas.<\/div>\n<div><\/div>\n<blockquote>\n<div><strong>Emilio Silvera V.<\/strong><\/div>\n<\/blockquote>\n<p>&nbsp;<\/p>\n<div class='bookmark'>\r\n\t\t<table align='left' border='0' cellpadding='0' width='100%'>\r\n\t\t<tr><td><span class='pushbutton'><a href='http:\/\/delicious.com\/post?url=http%3A%2F%2Fwww.emiliosilveravazquez.com%2Fblog%2F2026%2F01%2F13%2Fasentamiento-en-marte-no-parece-muy-viable%2F&amp;title=%C2%BFAsentamiento+en+Marte%3F+No+parece+muy+viable' title='Delicious' target='_blank' rel='nofollow'><img src='http:\/\/www.emiliosilveravazquez.com\/blog\/wp-content\/plugins\/knxdt-bookmarks-wordpress-plugin\/images\/delicious.png'  alt='' class='book_img' border='none' style='margin:1px; padding: 0;'  \/><\/a><\/span><span class='pushbutton'><a href='http:\/\/digg.com\/submit?url=http%3A%2F%2Fwww.emiliosilveravazquez.com%2Fblog%2F2026%2F01%2F13%2Fasentamiento-en-marte-no-parece-muy-viable%2F&amp;title=%C2%BFAsentamiento+en+Marte%3F+No+parece+muy+viable' title='Digg' target='_blank' rel='nofollow'><img src='http:\/\/www.emiliosilveravazquez.com\/blog\/wp-content\/plugins\/knxdt-bookmarks-wordpress-plugin\/images\/digg.png'  alt='' class='book_img' border='none' style='margin:1px; padding: 0;'  \/><\/a><\/span><span class='pushbutton'><a href='http:\/\/www.google.com\/bookmarks\/mark?op=edit&amp;bkmk=http%3A%2F%2Fwww.emiliosilveravazquez.com%2Fblog%2F2026%2F01%2F13%2Fasentamiento-en-marte-no-parece-muy-viable%2F&amp;title=%C2%BFAsentamiento+en+Marte%3F+No+parece+muy+viable' title='Google' target='_blank' rel='nofollow'><img src='http:\/\/www.emiliosilveravazquez.com\/blog\/wp-content\/plugins\/knxdt-bookmarks-wordpress-plugin\/images\/google.png'   alt='' class='book_img' border='none' style='margin:1px; padding: 0;'  \/><\/a><\/span><span class='pushbutton'><a href='http:\/\/myweb2.search.yahoo.com\/myresults\/bookmarklet?u=http%3A%2F%2Fwww.emiliosilveravazquez.com%2Fblog%2F2026%2F01%2F13%2Fasentamiento-en-marte-no-parece-muy-viable%2F&amp;t=%C2%BFAsentamiento+en+Marte%3F+No+parece+muy+viable' title='Yahoo' target='_blank' rel='nofollow'><img src='http:\/\/www.emiliosilveravazquez.com\/blog\/wp-content\/plugins\/knxdt-bookmarks-wordpress-plugin\/images\/yahoo.png'  alt='' class='book_img' border='none' style='margin:1px; padding: 0;'  \/><\/a><\/span><span class='pushbutton'><a href='http:\/\/www.technorati.com\/faves?add=http%3A%2F%2Fwww.emiliosilveravazquez.com%2Fblog%2F2026%2F01%2F13%2Fasentamiento-en-marte-no-parece-muy-viable%2F' title='Technorati' target='_blank' rel='nofollow'><img src='http:\/\/www.emiliosilveravazquez.com\/blog\/wp-content\/plugins\/knxdt-bookmarks-wordpress-plugin\/images\/technorati.png'  alt='' class='book_img' border='none' style='margin:1px; padding: 0;'  \/><\/a><\/span><span class='pushbutton'><a href='http:\/\/meneame.net\/submit.php?url=http%3A%2F%2Fwww.emiliosilveravazquez.com%2Fblog%2F2026%2F01%2F13%2Fasentamiento-en-marte-no-parece-muy-viable%2F' title='Meneame' target='_blank' rel='nofollow'><img src='http:\/\/www.emiliosilveravazquez.com\/blog\/wp-content\/plugins\/knxdt-bookmarks-wordpress-plugin\/images\/meneame.png'  alt='' class='book_img' border='none' style='margin:1px; padding: 0;'  \/><\/a><\/span><span class='pushbutton'><a href='http:\/\/enchilame.com\/submit.php?url=http:\/\/www.emiliosilveravazquez.com\/blog\/2026\/01\/13\/asentamiento-en-marte-no-parece-muy-viable\/' target='_blank' rel='nofollow'><img title='Enchilame' src='http:\/\/www.emiliosilveravazquez.com\/blog\/wp-content\/plugins\/knxdt-bookmarks-wordpress-plugin\/images\/enchilame.png'  alt='' class='book_img' border='none' style='margin:1px; padding: 0;'  \/><\/a><\/span><span class='pushbutton'><a href='http:\/\/www.blinklist.com\/index.php?Action=Blink\/addblink.php&amp;Description=&amp;Url=http%3A%2F%2Fwww.emiliosilveravazquez.com%2Fblog%2F2026%2F01%2F13%2Fasentamiento-en-marte-no-parece-muy-viable%2F&amp;title=%C2%BFAsentamiento+en+Marte%3F+No+parece+muy+viable' title='BlinkList' target='_blank' rel='nofollow'><img src='http:\/\/www.emiliosilveravazquez.com\/blog\/wp-content\/plugins\/knxdt-bookmarks-wordpress-plugin\/images\/blinklist.png'  alt='' class='book_img' border='none' style='margin:1px; padding: 0;'  \/><\/a><\/span><span class='pushbutton'><a href='http:\/\/reddit.com\/submit?url=http%3A%2F%2Fwww.emiliosilveravazquez.com%2Fblog%2F2026%2F01%2F13%2Fasentamiento-en-marte-no-parece-muy-viable%2F&amp;title=%C2%BFAsentamiento+en+Marte%3F+No+parece+muy+viable' title='Reddit' target='_blank' rel='nofollow'><img src='http:\/\/www.emiliosilveravazquez.com\/blog\/wp-content\/plugins\/knxdt-bookmarks-wordpress-plugin\/images\/reddit.png'  alt='' class='book_img' border='none' style='margin:1px; padding: 0;'  \/><\/a><\/span><span class='pushbutton'><a href='http:\/\/www.tecnologiadiaria.com\/2009\/07\/abrir-com-hotmail-correo.html' target='_blank' title='hotmail'><img src='http:\/\/www.emiliosilveravazquez.com\/blog\/wp-content\/plugins\/knxdt-bookmarks-wordpress-plugin\/images\/linklove.png' alt='hotmail correo' class='book_img' border='none' style='margin:1px; padding: 0;' \/><\/a><\/span><span class='pushbutton'><a href='http:\/\/bitacoras.com\/votar\/anotacion\/externo\/mini\/www.emiliosilveravazquez.com\/blog\/2026\/01\/13\/asentamiento-en-marte-no-parece-muy-viable\/' title='Bitacoras.com' target='_blank' rel='nofollow'><img src='http:\/\/www.emiliosilveravazquez.com\/blog\/wp-content\/plugins\/knxdt-bookmarks-wordpress-plugin\/images\/bitacoras.png'  alt='' class='book_img' border='none' style='margin:1px; padding: 0;'  \/><\/a><\/span><span class='pushbutton'><a href='http:\/\/www.wikio.es\/vote?url=http%3A%2F%2Fwww.emiliosilveravazquez.com%2Fblog%2F2026%2F01%2F13%2Fasentamiento-en-marte-no-parece-muy-viable%2F' title='Wikio' target='_blank' rel='nofollow'><img src='http:\/\/www.emiliosilveravazquez.com\/blog\/wp-content\/plugins\/knxdt-bookmarks-wordpress-plugin\/images\/wikio.png'   alt='' class='book_img' border='none' style='margin:1px; padding: 0;'   \/><\/a><\/span><span class='pushbutton'><a href='http:\/\/friendfeed.com\/?url=http%3A%2F%2Fwww.emiliosilveravazquez.com%2Fblog%2F2026%2F01%2F13%2Fasentamiento-en-marte-no-parece-muy-viable%2F&amp;title=%C2%BFAsentamiento+en+Marte%3F+No+parece+muy+viable' title='Friend Feed' target='_blank' rel='nofollow'><img src='http:\/\/www.emiliosilveravazquez.com\/blog\/wp-content\/plugins\/knxdt-bookmarks-wordpress-plugin\/images\/friendfeed.png'  alt='' class='book_img' border='none' style='margin:1px; padding: 0;'  \/><\/a><\/span><span class='pushbutton'><a href='http:\/\/www.facebook.com\/share.php?u=http%3A%2F%2Fwww.emiliosilveravazquez.com%2Fblog%2F2026%2F01%2F13%2Fasentamiento-en-marte-no-parece-muy-viable%2F&amp;t=%C2%BFAsentamiento+en+Marte%3F+No+parece+muy+viable' title='Facebook' target='_blank' rel='nofollow'><img src='http:\/\/www.emiliosilveravazquez.com\/blog\/wp-content\/plugins\/knxdt-bookmarks-wordpress-plugin\/images\/facebook.png'  alt='' class='book_img' border='none' style='margin:1px; padding: 0;'  \/><\/a><\/span><span class='pushbutton'><a href='http:\/\/twitter.com\/home?status=%C2%BFAsentamiento+en+Marte%3F+No+parece+muy+viable: http%3A%2F%2Fwww.emiliosilveravazquez.com%2Fblog%2F2026%2F01%2F13%2Fasentamiento-en-marte-no-parece-muy-viable%2F' title='Twitter' target='_blank' rel='nofollow'><img src='http:\/\/www.emiliosilveravazquez.com\/blog\/wp-content\/plugins\/knxdt-bookmarks-wordpress-plugin\/images\/twitter.png'  alt='' class='book_img' border='none' style='margin:1px; padding: 0;'  \/><\/a><\/span><span class='pushbutton'><a href='http:\/\/www.feedburner.com\/fb\/a\/emailFlare?itemTitle=%C2%BFAsentamiento+en+Marte%3F+No+parece+muy+viable&amp;uri=http%3A%2F%2Fwww.emiliosilveravazquez.com%2Fblog%2F2026%2F01%2F13%2Fasentamiento-en-marte-no-parece-muy-viable%2F' title='Enviar por Email' target='_blank' rel='nofollow'><img src='http:\/\/www.emiliosilveravazquez.com\/blog\/wp-content\/plugins\/knxdt-bookmarks-wordpress-plugin\/images\/email.png'  alt='' class='book_img' border='none' style='margin:1px; padding: 0;'  \/><\/a><\/span><span style='font-weight:bold; padding-left: 5px;'><a href='http:\/\/wordpress.org\/extend\/plugins\/knxdt-bookmarks-wordpress-plugin\/' title='Plugin' rel='nofollow' target='_blank'>[?]<\/a><\/span><\/td><\/tr><\/table><br\/><br\/><\/div>","protected":false},"excerpt":{"rendered":"<p>Son tantos los problemas que nos impiden viajar y vivir en Marte que, enumerarlos es complicado, ya que, muchos de esos problemas, ni los conocemos. Por ejemplo: &nbsp; &nbsp; La\u00a0ausencia de un campo magn\u00e9tico global\u00a0en Marte, junto con la tenue atm\u00f3sfera del planeta, implica que rayos c\u00f3smicos de alta energ\u00eda y part\u00edculas solares inunden la [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_s2mail":"","footnotes":""},"categories":[1],"tags":[],"_links":{"self":[{"href":"http:\/\/www.emiliosilveravazquez.com\/blog\/wp-json\/wp\/v2\/posts\/35083"}],"collection":[{"href":"http:\/\/www.emiliosilveravazquez.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.emiliosilveravazquez.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.emiliosilveravazquez.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/www.emiliosilveravazquez.com\/blog\/wp-json\/wp\/v2\/comments?post=35083"}],"version-history":[{"count":0,"href":"http:\/\/www.emiliosilveravazquez.com\/blog\/wp-json\/wp\/v2\/posts\/35083\/revisions"}],"wp:attachment":[{"href":"http:\/\/www.emiliosilveravazquez.com\/blog\/wp-json\/wp\/v2\/media?parent=35083"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.emiliosilveravazquez.com\/blog\/wp-json\/wp\/v2\/categories?post=35083"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.emiliosilveravazquez.com\/blog\/wp-json\/wp\/v2\/tags?post=35083"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}