{"id":25502,"date":"2026-01-12T07:07:17","date_gmt":"2026-01-12T06:07:17","guid":{"rendered":"http:\/\/www.emiliosilveravazquez.com\/blog\/?p=25502"},"modified":"2026-01-12T07:07:18","modified_gmt":"2026-01-12T06:07:18","slug":"el-universo-misterioso-4","status":"publish","type":"post","link":"http:\/\/www.emiliosilveravazquez.com\/blog\/2026\/01\/12\/el-universo-misterioso-4\/","title":{"rendered":"El Universo misterioso"},"content":{"rendered":"<div style=\"text-align: justify;\">\n<div>\n<h2>\u00bfPor Qu\u00e9 se Forman Nubes Cerca de los Agujeros Negros?<\/h2>\n<\/div>\n<\/div>\n<div style=\"text-align: justify;\">\u00a0<a href=\"https:\/\/www.lanasa.net\/noticias\/newsnasa\">Actualidad@NASA<\/a><\/div>\n<div><\/div>\n<div id=\"ccm-layout-column-wrapper-233\" style=\"text-align: justify;\">\n<div id=\"ccm-layout-column-437\"><\/div>\n<\/div>\n<div>\n<div style=\"text-align: justify;\">\n<figure><img decoding=\"async\" loading=\"lazy\" class=\"\" src=\"https:\/\/www.lanasa.net\/application\/files\/thumbnails\/small\/7115\/8947\/5461\/news_AGN140520.jpg\" alt=\"Por Qu\u00e9 se Forman Nubes Cerca de los Agujeros Negros\" width=\"617\" height=\"617\" \/><\/figure>\n<p>&nbsp;<\/p>\n<\/div>\n<p style=\"text-align: justify;\">Una vez que abandonas los majestuosos cielos de la Tierra, la palabra &#8220;nube&#8221; ya no significa una estructura blanca de aspecto esponjoso que produce lluvia. En cambio, las nubes en el universo mayor son \u00e1reas grumosas de mayor densidad que sus alrededores.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\"><img decoding=\"async\" src=\"https:\/\/www.lanasa.net\/application\/files\/4615\/8947\/5405\/miniatura_AGN140520.jpg\" alt=\"Por Qu\u00e9 se Forman Nubes Cerca de los Agujeros Negros :: NASA EN ESPA\u00d1OL\" \/><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">Los telescopios espaciales han observado estas nubes c\u00f3smicas en la vecindad de <a href=\"#\" onclick=\"referencia('agujero negro',event); return false;\">agujeros negros<\/a> supermasivos, esos misteriosos objetos densos de los que no puede escapar la luz, con masas equivalentes a m\u00e1s de 100.000 soles. Hay un <a href=\"#\" onclick=\"referencia('agujero negro',event); return false;\">agujero negro<\/a> supermasivo en el centro de casi todas las galaxias, y se llama un &#8220;n\u00facleo gal\u00e1ctico activo&#8221; (AGN) si est\u00e1 absorbiendo una gran cantidad de gas y polvo de su entorno. Si bien el <a href=\"#\" onclick=\"referencia('agujero negro',event); return false;\">agujero negro<\/a> en s\u00ed no se puede ver, su vecindad se ilumina extremadamente brillante a medida que la materia se desgarra cerca de su horizonte de eventos, su punto de no retorno.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\"><img decoding=\"async\" src=\"https:\/\/images.clarin.com\/2020\/05\/15\/imagen-facilitada-por-el-observatorio___mp8q8gl0e_600x338__1.jpg\" alt=\"La NASA revela por qu\u00e9 se forman nubes cerca de los agujeros negros - Clar\u00edn\" \/><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">Pero los <a href=\"#\" onclick=\"referencia('agujero negro',event); return false;\">agujeros negros<\/a> no son realmente como las aspiradoras; no solo absorben todo lo que se acerca demasiado. Si bien parte del material alrededor de un <a href=\"#\" onclick=\"referencia('agujero negro',event); return false;\">agujero negro<\/a> caer\u00e1 directamente, y nunca se volver\u00e1 a ver, parte del gas cercano se arrojar\u00e1 hacia afuera, creando una capa que se expandir\u00e1 durante miles de a\u00f1os. Esto se debe a que el \u00e1rea cerca del horizonte de eventos es extremadamente en\u00e9rgica; la radiaci\u00f3n de alta energ\u00eda de las part\u00edculas de r\u00e1pido movimiento alrededor del <a href=\"#\" onclick=\"referencia('agujero negro',event); return false;\">agujero negro<\/a> puede expulsar una cantidad significativa de gas en la inmensidad del espacio.<\/p>\n<p style=\"text-align: justify;\">Los cient\u00edficos cre\u00edan que este flujo de gas era suave. En cambio, es grumoso, se extiende mucho m\u00e1s all\u00e1 de 1 parsec (3,3 a\u00f1os luz) desde el <a href=\"#\" onclick=\"referencia('agujero negro',event); return false;\">agujero negro<\/a>. Cada nube comienza siendo peque\u00f1a, pero puede expandirse hasta tener m\u00e1s de 1 parsec de ancho, e incluso podr\u00eda cubrir la distancia entre la Tierra y la estrella m\u00e1s cercana m\u00e1s all\u00e1 del Sol, Pr\u00f3xima Centauri.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">.<img decoding=\"async\" src=\"https:\/\/images.ecestaticos.com\/1Wtr6Mtkoh56ZfcDuEVjW1KSE3I=\/0x34:583x347\/600x315\/filters:fill(white):format(jpg):quality(99):watermark(f.elconfidencial.com\/file\/bae\/eea\/fde\/baeeeafde1b3229287b0c008f7602058.png,0,275,1)\/f.elconfidencial.com\/original\/4ca\/a6c\/a35\/4caa6ca3591d8e49aa0c8ba86ef57056.jpg\" alt=\"Captan por primera vez la brutal erupci\u00f3n de un agujero negro al destruir una estrella\" \/><\/p>\n<\/div>\n<p>&nbsp;<\/p>\n<blockquote>\n<p style=\"text-align: justify;\"><strong>Los <a href=\"#\" onclick=\"referencia('agujero negro',event); return false;\">agujeros negros<\/a> tienen una erupci\u00f3n cuando se tragan a una estrella. Un <a href=\"#\" onclick=\"referencia('agujero negro',event); return false;\">agujero negro<\/a> produce una gran erupci\u00f3n tras desgarrar una estrella. <b>Los astr\u00f3nomos han logrado observar por primera vez la formaci\u00f3n y evoluci\u00f3n de un chorro de material expulsado por un\u00a0<span tabindex=\"0\" role=\"tooltip\"><span class=\"c5aZPb\" tabindex=\"0\" role=\"button\" data-enable-toggle-animation=\"true\" data-extra-container-classes=\"ZLo7Eb\" data-hover-hide-delay=\"1000\" data-hover-open-delay=\"500\" data-send-open-event=\"true\" data-theme=\"0\" data-width=\"250\" data-ved=\"2ahUKEwjukJHCi5CJAxVF3wIHHQ6OIZ4QmpgGegQIFhAD\"><span class=\"JPfdse\" data-bubble-link=\"\" data-segment-text=\"agujero negro supermasivo\"><a href=\"#\" onclick=\"referencia('agujero negro',event); return false;\">agujero negro<\/a> supermasivo<\/span><\/span><\/span> despu\u00e9s de haber destruido una estrella<\/b><\/strong><\/p>\n<\/blockquote>\n<div>\n<p style=\"text-align: justify;\"><strong>Proga<\/strong> y sus colegas tienen un nuevo modelo de ordenados que presenta una posible soluci\u00f3n a este misterio.<\/p>\n<blockquote>\n<p style=\"text-align: justify;\">&#8220;Cerca del borde exterior de la carcasa hay una perturbaci\u00f3n que hace que la densidad del gas sea un poco m\u00e1s baja de lo que sol\u00eda ser&#8221;, dijo Proga. \u201cEso hace que este gas se caliente de manera muy eficiente. El gas fr\u00edo que est\u00e1 m\u00e1s lejos est\u00e1 siendo arrojado hacia fuera por eso.\u201d<\/p>\n<\/blockquote>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\"><img decoding=\"async\" src=\"https:\/\/encrypted-tbn0.gstatic.com\/images?q=tbn%3AANd9GcTJYzN9x0U_ma8pLDxWN9o5SpSmJ_MG_g4PFQ&amp;usqp=CAU\" alt=\"Gran Colisionador: El origen del Universo pudo haber sido L\u00edquido,\" \/><img decoding=\"async\" src=\"https:\/\/cdn.agenciasinc.es\/var\/ezwebin_site\/storage\/images\/_aliases\/img_1col\/media\/images\/agn_anatomia-1\/12009660-1-esl-MX\/AGN_anatomia-1.jpg\" alt=\"El Webb revela un cu\u00e1sar maduro en el amanecer c\u00f3smico\" \/><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">&#8220;Este trabajo es importante porque los astr\u00f3nomos siempre han necesitado colocar nubes en una ubicaci\u00f3n y velocidad determinadas para ajustarse a las observaciones que vemos del AGN,&#8221; dijo <strong>Dannen<\/strong>, y nuestro trabajo ofrece una posible explicaci\u00f3n para la formaci\u00f3n de estas nubes &#8220;.<\/p>\n<p style=\"text-align: justify;\">Este modelo solo mira la capa de gas, no el disco de material que gira alrededor del <a href=\"#\" onclick=\"referencia('agujero negro',event); return false;\">agujero negro<\/a> que lo alimenta. El siguiente paso de los investigadores es examinar si el flujo de gas se origina en el propio disco. Tambi\u00e9n est\u00e1n interesados en abordar el misterio de por qu\u00e9 algunas nubes se mueven extremadamente r\u00e1pido, del orden de 10.000 kil\u00f3metros por segundo.<\/p>\n<p style=\"text-align: justify;\">Esta investigaci\u00f3n, que aborda un tema importante en la f\u00edsica de los n\u00facleos gal\u00e1cticos activos, fue apoyada con una subvenci\u00f3n de la NASA. Los coautores son Dannen, <strong>Proga,<\/strong> el acad\u00e9mico postdoctoral de UNLV Tim Waters y el ex acad\u00e9mico postdoctoral de UNLV Sergei Dyda (ahora en la Universidad de Cambridge).<\/p>\n<p style=\"text-align: justify;\"><strong>Fuente: NASA<\/strong><\/p>\n<\/div>\n<div class='bookmark'>\r\n\t\t<table align='left' border='0' cellpadding='0' width='100%'>\r\n\t\t<tr><td><span class='pushbutton'><a href='http:\/\/delicious.com\/post?url=http%3A%2F%2Fwww.emiliosilveravazquez.com%2Fblog%2F2026%2F01%2F12%2Fel-universo-misterioso-4%2F&amp;title=El+Universo+misterioso' title='Delicious' target='_blank' rel='nofollow'><img src='http:\/\/www.emiliosilveravazquez.com\/blog\/wp-content\/plugins\/knxdt-bookmarks-wordpress-plugin\/images\/delicious.png'  alt='' class='book_img' border='none' style='margin:1px; padding: 0;'  \/><\/a><\/span><span class='pushbutton'><a href='http:\/\/digg.com\/submit?url=http%3A%2F%2Fwww.emiliosilveravazquez.com%2Fblog%2F2026%2F01%2F12%2Fel-universo-misterioso-4%2F&amp;title=El+Universo+misterioso' title='Digg' target='_blank' rel='nofollow'><img src='http:\/\/www.emiliosilveravazquez.com\/blog\/wp-content\/plugins\/knxdt-bookmarks-wordpress-plugin\/images\/digg.png'  alt='' class='book_img' border='none' style='margin:1px; padding: 0;'  \/><\/a><\/span><span class='pushbutton'><a href='http:\/\/www.google.com\/bookmarks\/mark?op=edit&amp;bkmk=http%3A%2F%2Fwww.emiliosilveravazquez.com%2Fblog%2F2026%2F01%2F12%2Fel-universo-misterioso-4%2F&amp;title=El+Universo+misterioso' title='Google' target='_blank' rel='nofollow'><img src='http:\/\/www.emiliosilveravazquez.com\/blog\/wp-content\/plugins\/knxdt-bookmarks-wordpress-plugin\/images\/google.png'   alt='' class='book_img' border='none' style='margin:1px; padding: 0;'  \/><\/a><\/span><span class='pushbutton'><a href='http:\/\/myweb2.search.yahoo.com\/myresults\/bookmarklet?u=http%3A%2F%2Fwww.emiliosilveravazquez.com%2Fblog%2F2026%2F01%2F12%2Fel-universo-misterioso-4%2F&amp;t=El+Universo+misterioso' title='Yahoo' target='_blank' rel='nofollow'><img src='http:\/\/www.emiliosilveravazquez.com\/blog\/wp-content\/plugins\/knxdt-bookmarks-wordpress-plugin\/images\/yahoo.png'  alt='' class='book_img' border='none' style='margin:1px; padding: 0;'  \/><\/a><\/span><span class='pushbutton'><a href='http:\/\/www.technorati.com\/faves?add=http%3A%2F%2Fwww.emiliosilveravazquez.com%2Fblog%2F2026%2F01%2F12%2Fel-universo-misterioso-4%2F' title='Technorati' target='_blank' rel='nofollow'><img src='http:\/\/www.emiliosilveravazquez.com\/blog\/wp-content\/plugins\/knxdt-bookmarks-wordpress-plugin\/images\/technorati.png'  alt='' class='book_img' border='none' style='margin:1px; padding: 0;'  \/><\/a><\/span><span class='pushbutton'><a href='http:\/\/meneame.net\/submit.php?url=http%3A%2F%2Fwww.emiliosilveravazquez.com%2Fblog%2F2026%2F01%2F12%2Fel-universo-misterioso-4%2F' title='Meneame' target='_blank' rel='nofollow'><img src='http:\/\/www.emiliosilveravazquez.com\/blog\/wp-content\/plugins\/knxdt-bookmarks-wordpress-plugin\/images\/meneame.png'  alt='' class='book_img' border='none' style='margin:1px; padding: 0;'  \/><\/a><\/span><span class='pushbutton'><a href='http:\/\/enchilame.com\/submit.php?url=http:\/\/www.emiliosilveravazquez.com\/blog\/2026\/01\/12\/el-universo-misterioso-4\/' target='_blank' rel='nofollow'><img title='Enchilame' src='http:\/\/www.emiliosilveravazquez.com\/blog\/wp-content\/plugins\/knxdt-bookmarks-wordpress-plugin\/images\/enchilame.png'  alt='' class='book_img' border='none' style='margin:1px; padding: 0;'  \/><\/a><\/span><span class='pushbutton'><a href='http:\/\/www.blinklist.com\/index.php?Action=Blink\/addblink.php&amp;Description=&amp;Url=http%3A%2F%2Fwww.emiliosilveravazquez.com%2Fblog%2F2026%2F01%2F12%2Fel-universo-misterioso-4%2F&amp;title=El+Universo+misterioso' title='BlinkList' target='_blank' rel='nofollow'><img src='http:\/\/www.emiliosilveravazquez.com\/blog\/wp-content\/plugins\/knxdt-bookmarks-wordpress-plugin\/images\/blinklist.png'  alt='' class='book_img' border='none' style='margin:1px; padding: 0;'  \/><\/a><\/span><span class='pushbutton'><a href='http:\/\/reddit.com\/submit?url=http%3A%2F%2Fwww.emiliosilveravazquez.com%2Fblog%2F2026%2F01%2F12%2Fel-universo-misterioso-4%2F&amp;title=El+Universo+misterioso' title='Reddit' target='_blank' rel='nofollow'><img src='http:\/\/www.emiliosilveravazquez.com\/blog\/wp-content\/plugins\/knxdt-bookmarks-wordpress-plugin\/images\/reddit.png'  alt='' class='book_img' border='none' style='margin:1px; padding: 0;'  \/><\/a><\/span><span class='pushbutton'><a href='http:\/\/www.tecnologiadiaria.com\/2009\/07\/abrir-com-hotmail-correo.html' target='_blank' title='hotmail'><img src='http:\/\/www.emiliosilveravazquez.com\/blog\/wp-content\/plugins\/knxdt-bookmarks-wordpress-plugin\/images\/linklove.png' alt='hotmail correo' class='book_img' border='none' style='margin:1px; padding: 0;' \/><\/a><\/span><span class='pushbutton'><a href='http:\/\/bitacoras.com\/votar\/anotacion\/externo\/mini\/www.emiliosilveravazquez.com\/blog\/2026\/01\/12\/el-universo-misterioso-4\/' title='Bitacoras.com' target='_blank' rel='nofollow'><img src='http:\/\/www.emiliosilveravazquez.com\/blog\/wp-content\/plugins\/knxdt-bookmarks-wordpress-plugin\/images\/bitacoras.png'  alt='' class='book_img' border='none' style='margin:1px; padding: 0;'  \/><\/a><\/span><span class='pushbutton'><a href='http:\/\/www.wikio.es\/vote?url=http%3A%2F%2Fwww.emiliosilveravazquez.com%2Fblog%2F2026%2F01%2F12%2Fel-universo-misterioso-4%2F' title='Wikio' target='_blank' rel='nofollow'><img src='http:\/\/www.emiliosilveravazquez.com\/blog\/wp-content\/plugins\/knxdt-bookmarks-wordpress-plugin\/images\/wikio.png'   alt='' class='book_img' border='none' style='margin:1px; padding: 0;'   \/><\/a><\/span><span class='pushbutton'><a href='http:\/\/friendfeed.com\/?url=http%3A%2F%2Fwww.emiliosilveravazquez.com%2Fblog%2F2026%2F01%2F12%2Fel-universo-misterioso-4%2F&amp;title=El+Universo+misterioso' title='Friend Feed' target='_blank' rel='nofollow'><img src='http:\/\/www.emiliosilveravazquez.com\/blog\/wp-content\/plugins\/knxdt-bookmarks-wordpress-plugin\/images\/friendfeed.png'  alt='' class='book_img' border='none' style='margin:1px; padding: 0;'  \/><\/a><\/span><span class='pushbutton'><a href='http:\/\/www.facebook.com\/share.php?u=http%3A%2F%2Fwww.emiliosilveravazquez.com%2Fblog%2F2026%2F01%2F12%2Fel-universo-misterioso-4%2F&amp;t=El+Universo+misterioso' title='Facebook' target='_blank' rel='nofollow'><img src='http:\/\/www.emiliosilveravazquez.com\/blog\/wp-content\/plugins\/knxdt-bookmarks-wordpress-plugin\/images\/facebook.png'  alt='' class='book_img' border='none' style='margin:1px; padding: 0;'  \/><\/a><\/span><span class='pushbutton'><a href='http:\/\/twitter.com\/home?status=El+Universo+misterioso: http%3A%2F%2Fwww.emiliosilveravazquez.com%2Fblog%2F2026%2F01%2F12%2Fel-universo-misterioso-4%2F' title='Twitter' target='_blank' rel='nofollow'><img src='http:\/\/www.emiliosilveravazquez.com\/blog\/wp-content\/plugins\/knxdt-bookmarks-wordpress-plugin\/images\/twitter.png'  alt='' class='book_img' border='none' style='margin:1px; padding: 0;'  \/><\/a><\/span><span class='pushbutton'><a href='http:\/\/www.feedburner.com\/fb\/a\/emailFlare?itemTitle=El+Universo+misterioso&amp;uri=http%3A%2F%2Fwww.emiliosilveravazquez.com%2Fblog%2F2026%2F01%2F12%2Fel-universo-misterioso-4%2F' title='Enviar por Email' target='_blank' rel='nofollow'><img src='http:\/\/www.emiliosilveravazquez.com\/blog\/wp-content\/plugins\/knxdt-bookmarks-wordpress-plugin\/images\/email.png'  alt='' class='book_img' border='none' style='margin:1px; padding: 0;'  \/><\/a><\/span><span style='font-weight:bold; padding-left: 5px;'><a href='http:\/\/wordpress.org\/extend\/plugins\/knxdt-bookmarks-wordpress-plugin\/' title='Plugin' rel='nofollow' target='_blank'>[?]<\/a><\/span><\/td><\/tr><\/table><br\/><br\/><\/div>","protected":false},"excerpt":{"rendered":"<p>\u00bfPor Qu\u00e9 se Forman Nubes Cerca de los Agujeros Negros? \u00a0Actualidad@NASA &nbsp; Una vez que abandonas los majestuosos cielos de la Tierra, la palabra &#8220;nube&#8221; ya no significa una estructura blanca de aspecto esponjoso que produce lluvia. En cambio, las nubes en el universo mayor son \u00e1reas grumosas de mayor densidad que sus alrededores. &nbsp; [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_s2mail":"yes","footnotes":""},"categories":[155],"tags":[],"_links":{"self":[{"href":"http:\/\/www.emiliosilveravazquez.com\/blog\/wp-json\/wp\/v2\/posts\/25502"}],"collection":[{"href":"http:\/\/www.emiliosilveravazquez.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.emiliosilveravazquez.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.emiliosilveravazquez.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/www.emiliosilveravazquez.com\/blog\/wp-json\/wp\/v2\/comments?post=25502"}],"version-history":[{"count":0,"href":"http:\/\/www.emiliosilveravazquez.com\/blog\/wp-json\/wp\/v2\/posts\/25502\/revisions"}],"wp:attachment":[{"href":"http:\/\/www.emiliosilveravazquez.com\/blog\/wp-json\/wp\/v2\/media?parent=25502"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.emiliosilveravazquez.com\/blog\/wp-json\/wp\/v2\/categories?post=25502"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.emiliosilveravazquez.com\/blog\/wp-json\/wp\/v2\/tags?post=25502"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}