{"id":2145,"date":"2026-05-31T07:46:47","date_gmt":"2026-05-31T06:46:47","guid":{"rendered":"http:\/\/www.emiliosilveravazquez.com\/blog\/?p=2145"},"modified":"2026-05-31T07:47:09","modified_gmt":"2026-05-31T06:47:09","slug":"matematicas-que-describen-la-naturaleza","status":"publish","type":"post","link":"http:\/\/www.emiliosilveravazquez.com\/blog\/2026\/05\/31\/matematicas-que-describen-la-naturaleza\/","title":{"rendered":"Matem\u00e1ticas que describen la Naturaleza"},"content":{"rendered":"<p style=\"text-indent: 24pt; text-align: justify;\">Suponiendo que alg\u00fan f\u00edsico brillante nos resuelva la teor\u00eda de campos de cuerdas y derive las propiedades conocidas de nuestro universo, con un poco de suerte, podr\u00eda ocurrir en este mismo siglo, lo que no estar\u00eda nada mal considerando las dificultades de la empresa. Parece que la dichosa teor\u00eda no se puede verificar porque, para llegar hasta las cvuerdas, se necesita la energ\u00eda de 10<sup>19<\/sup> GeV. la energ\u00eda de la crweaci\u00f3n que no est\u00e1 a nuestro ance.<\/p>\n<p><strong>\u00bfEntonces nunca podremos llegar hasta las cuerdas?<\/strong><\/p>\n<p style=\"text-align: justify;\">No me atrever\u00eda a realizar esa aseveraci\u00f3n, recordad a aquel Presidente de la Real Sociedad de F\u00edsica de Londres, cuando delante de todos sus afuiliados dijo: &#8220;Nunca podremos saber, de qu\u00e9 est\u00e1n hechas las estrellas&#8221;. Unos meses despu\u00e9s, lleg\u00f3 Johan Frenhauser que, por medio de las l\u00edneas espectrales de los elementos que conforman las estrellas, nos dijo de qu\u00e9 estaban hechas. Y, de la misma\u00a0 manera, pas\u00f3 con aquel otro que dijo: &#8220;Nunca m\u00e1s pesado que el airte podr\u00e1 volar&#8221;. Poco m\u00e1s tarde,\u00a0 remont\u00f3 el vuielo el famoso primer avi\u00f3n de los hermanos Wrigh.<\/p>\n<p>Es dif\u00edcil y arriesgado negar alguna posibilidad que, aunque parezca remota, la hisotiria nos aconseja no negar tal posibnilidad. La I. A. es un buen ejemplo de lo que digo.<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"\" src=\"https:\/\/www.ecoticias.com\/wp-content\/uploads\/2024\/04\/20913-1.jpg\" alt=\"La desconocida fuerza del universo que produce energ\u00eda: no sabemos usarla, pero tenemos un plan\" width=\"577\" height=\"325\" \/><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-indent: 24pt; text-align: justify;\">El problema fundamental es que estamos obligando a la <a href=\"#\" onclick=\"referencia('supercuerdas teoria',event); return false;\">teor\u00eda de supercuerdas<\/a> a responder preguntas sobre energ\u00edas cotidianas, cuando su &#8220;\u00e1mbito natural&#8221; est\u00e1 en la energ\u00eda de Planck. Esta fabulosa energ\u00eda fue liberada s\u00f3lo en el propio instante de la creaci\u00f3n, lo que quiere decir que la <a href=\"#\" onclick=\"referencia('supercuerdas teoria',event); return false;\">teor\u00eda de supercuerdas<\/a> es naturalmente <strong>una teor\u00eda de la creaci\u00f3n.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/starchild.gsfc.nasa.gov\/docs\/StarChild_Spanish\/Images\/StarChild\/universe_level1\/penzias4.gif\" alt=\"StarChild: \u00bfLo sab\u00edas... (Cosmolog\u00eda)?\" \/><img decoding=\"async\" loading=\"lazy\" class=\"\" src=\"https:\/\/e01-elmundo.uecdn.es\/elmundo\/imagenes\/2009\/10\/28\/1256724101_extras_ladillos_4_0.jpg\" alt=\"1965. El eco del 'Big Bang' | Ciencia | elmundo.es\" width=\"330\" height=\"168\" \/><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-indent: 24pt; text-align: justify;\">Fuimos capaces de predecir que el <a href=\"#\" onclick=\"referencia('big bang',event); return false;\">Big Bang<\/a> produjo un &#8220;eco&#8221; c\u00f3smico reverberando en el universo y que podr\u00eda ser mesurable por los instrumentos adecuados. De hecho, Arno Penzias y Robert Wilson de los <em style=\"mso-bidi-font-style: normal;\">Bell Telephone Laboratories<\/em> ganaron el premio Nobel en 1.978 por detectar este eco del <a href=\"#\" onclick=\"referencia('big bang',event); return false;\">Big Bang<\/a>, una radiaci\u00f3n de microondas que impregna el universo conocido. El que el eco del <a href=\"#\" onclick=\"referencia('big bang',event); return false;\">Big Bang<\/a> deber\u00eda estar circulando por el universo miles de millones de a\u00f1os despu\u00e9s del suceso fue predicho por primera vez por George Gamow y sus disc\u00edpulos Ralpher y Robert Herman, pero nadie les tom\u00f3 en serio. La propia idea de medir el eco de la creaci\u00f3n parec\u00eda extravagante cuando la propusieron por primera vez poco despu\u00e9s de la segunda guerra mundial. Su l\u00f3gica, sin embargo, era aplastante. Cualquier objeto, cuando se calienta, emite radiaci\u00f3n de forma gradual. \u00c9sta es la raz\u00f3n de que el hierro se ponga al rojo vivo cuando se calienta en un horno, y cuanto m\u00e1s se calienta, mayor es la frecuencia de radiaci\u00f3n que emite. Una f\u00f3rmula matem\u00e1tica exacta, la ley de Stefan-Boltzmann, relaciona la frecuencia de la luz (o el color en este caso) con la temperatura. De hecho, as\u00ed es como los cient\u00edficos determinan la temperatura de la superficie de una estrella lejana; examinando su color. Esta radiaci\u00f3n se denomina <em style=\"mso-bidi-font-style: normal;\">radiaci\u00f3n de cuerpo negro<\/em>.<\/p>\n<p><!--more--><\/p>\n<p style=\"text-indent: 24pt; text-align: justify;\">Esta radiaci\u00f3n, c\u00f3mo no, ha sido aprovechada por los ej\u00e9rcitos, que mediante visores nocturnos pueden operar en la oscuridad. De noche, los objetos relativamente calientes, tales como soldados enemigos o los carros de combate, pueden estar ocultos en la oscuridad, pero contin\u00faan emitiendo radiaci\u00f3n de cuerpo negro invisible en forma de radiaci\u00f3n infrarroja, que puede ser captada por gafas especiales de infrarrojo. \u00c9sta es tambi\u00e9n la raz\u00f3n de que nuestros autom\u00f3viles cerrados se calientes en verano, ya que la luz del Sol atraviesa los cristales del coche y calienta el interior. A medida que se calienta, empieza a emitir radiaci\u00f3n de cuerpo negro en forma de radiaci\u00f3n infrarroja. Sin embargo, esta clase de radiaci\u00f3n no atraviesa muy bien el vidrio, y por lo tanto queda atrapada en el interior del autom\u00f3vil, incrementando espectacularmente la temperatura.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"\" src=\"https:\/\/i.ytimg.com\/vi\/GQAsG65H2AU\/maxresdefault.jpg\" alt=\"TEMA 8. Teor\u00eda cu\u00e1ntica | 8.7. Radiaci\u00f3n del cuerpo negro\" width=\"788\" height=\"443\" \/><\/p>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"\" src=\"https:\/\/img.europapress.es\/fotoweb\/fotonoticia_20140520174113_1200.jpg\" alt=\"El descubrimiento del 'eco' del Big Bang cumple 50 a\u00f1os\" width=\"531\" height=\"266\" \/><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-indent: 24pt; text-align: justify;\">An\u00e1logamente, la radiaci\u00f3n de cuerpo negro produce el efecto invernadero. Al igual que el vidrio, los altos niveles de di\u00f3xido de carbono en la atm\u00f3sfera, causados por la combusti\u00f3n sin control de combustibles f\u00f3siles, pueden atrapar la radiaci\u00f3n de cuerpo negro infrarroja en la Tierra, y de este modo calentar gradualmente el planeta.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/media3.giphy.com\/media\/SUFv63LCURn1e\/giphy.gif?cid=6c09b9528dypx3opqduuojin3ruxwe83mrc57nz1usxbs3bo&amp;ep=v1_internal_gif_by_id&amp;rid=giphy.gif&amp;ct=g\" alt=\"space GIF by NASA\" \/><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-indent: 24pt; text-align: justify;\">Gamow razon\u00f3 que el <a href=\"#\" onclick=\"referencia('big bang',event); return false;\">Big Bang<\/a> era inicialmente muy caliente, y que por lo tanto ser\u00eda un cuerpo negro ideal emisor de radiaci\u00f3n. Aunque la tecnolog\u00eda de los a\u00f1os cuarenta era demasiado primitiva para captar esta d\u00e9bil se\u00f1al de la creaci\u00f3n, Gamow pudo calcular la temperatura de dicha radiaci\u00f3n y predecir con fiabilidad que un d\u00eda nuestros instrumentos ser\u00edan lo suficientemente sensibles como para detectar esta radiaci\u00f3n &#8220;f\u00f3sil&#8221;.<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"\" src=\"https:\/\/estaticos-cdn.prensaiberica.es\/clip\/532bbc35-7209-439e-856d-7daf870bf22c_16-9-discover-aspect-ratio_default_0.jpg\" alt=\"Qu\u00e9 pas\u00f3 con la primera materia despu\u00e9s del Big Bang?\" width=\"782\" height=\"440\" \/><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-indent: 24pt; text-align: justify;\">La l\u00f3gica que hab\u00eda detr\u00e1s de su razonamiento era la siguiente: alrededor de 300.000 a\u00f1os despu\u00e9s del <a href=\"#\" onclick=\"referencia('big bang',event); return false;\">Big Bang<\/a>, el universo se enfri\u00f3 hasta el punto en el que los \u00e1tomos pudieron empezar a componerse; los <a href=\"#\" onclick=\"referencia('electron',event); return false;\">electrones<\/a> pudieron empezar a rodear a los <a href=\"#\" onclick=\"referencia('proton',event); return false;\">protones<\/a> y <a href=\"#\" onclick=\"referencia('neutron',event); return false;\">neutrones<\/a> formando \u00e1tomos estables, que ya no ser\u00edan destruidos por la intensa radiaci\u00f3n que estaba impregnando todo el universo. Antes de este momento, el universo estaba tan caliente que los \u00e1tomos eran inmediatamente descompuestos por esa radiaci\u00f3n tan potente en el mismo acto de su formaci\u00f3n. Esto significa que el universo era opaco, como una niebla espesa absorbente e impenetrable.<\/p>\n<p style=\"text-indent: 24pt; text-align: justify;\">Pasados 300.000 a\u00f1os, la radiaci\u00f3n no era tan potente; se hab\u00eda enfriado y por lo tanto la luz pod\u00eda atravesar grades distancias sin ser dispersada. En otras palabras, el universo se hizo repentinamente negro y transparente.<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/encrypted-tbn0.gstatic.com\/images?q=tbn:ANd9GcRgpiX5wgT6D6RXVpRWvDehjauzGVRkYrSiyA&amp;s\" alt=\"EL F\u00cdSICO LOCO: Cuerpo Negro. Ley de Wien. Ley de Stefan-Boltzmann\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<blockquote>\n<p style=\"text-align: justify;\">El cuerpo negro imaginario de Kirchhoff\u00a0<b>era un simple recipiente oscuro con un peque\u00f1o orificio en una de sus paredes<\/b>. En su interior la radiaci\u00f3n sufre diversas reflexiones en las paredes hasta que acaba siendo completamente absorbida aumentando la energ\u00eda interna y con ello la temperatura.<\/p>\n<\/blockquote>\n<p style=\"text-indent: 24pt; text-align: justify;\">Terminar\u00e9 esta parte comentando que un aut\u00e9ntico cuerpo negro es un concepto imaginario; un peque\u00f1o agujero en la pared de un recinto a temperatura uniforme es la mejor aproximaci\u00f3n que se puede tener de \u00e9l en la pr\u00e1ctica.<\/p>\n<p style=\"text-indent: 24pt; text-align: justify;\">La radiaci\u00f3n de cuerpo negro es la radiaci\u00f3n electromagn\u00e9tica emitida por un cuerpo negro. Se extiende sobre todo el rango de longitudes de onda y la disminuci\u00f3n de energ\u00edas sobre este rango tiene una forma caracter\u00edstica con un m\u00e1ximo en una cierta longitud de onda, desplaz\u00e1ndose a longitudes de onda m\u00e1s cortas al aumentar las temperaturas<a href=\"#pie\" name=\"r_pie\"><\/a>*.<\/p>\n<p style=\"text-indent: 24pt; text-align: justify;\">Hablar, sin m\u00e1s especificaciones, de radiaci\u00f3n, es estar refiri\u00e9ndonos a una energ\u00eda que viaja en forma de ondas electromagn\u00e9ticas o <a href=\"#\" onclick=\"referencia('foton',event); return false;\">fotones<\/a> por el universo. Tambi\u00e9n nos podr\u00edamos estar refiriendo a un chorro de part\u00edculas, especialmente <a href=\"#\" onclick=\"referencia('particula alfa',event); return false;\">part\u00edculas alfa<\/a> o beta de una fuente radiactiva o <a href=\"#\" onclick=\"referencia('neutron',event); return false;\">neutrones<\/a> de un reactor nuclear.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<blockquote><p><img decoding=\"async\" loading=\"lazy\" class=\"\" src=\"https:\/\/www.radiation-dosimetry.org\/wp-content\/uploads\/2019\/12\/Alpha-Decay-Alpha-Radioactivity-definition.png\" alt=\"Qu\u00e9 es la desintegraci\u00f3n alfa? - Radiactividad alfa - Definici\u00f3n\" width=\"316\" height=\"168\" \/><img decoding=\"async\" loading=\"lazy\" class=\"\" src=\"https:\/\/upload.wikimedia.org\/wikipedia\/commons\/thumb\/7\/79\/Alpha_Decay.svg\/1280px-Alpha_Decay.svg.png\" alt=\"Part\u00edcula alfa - Wikipedia, la enciclopedia libre\" width=\"241\" height=\"164\" \/><\/p>\n<p>&nbsp;<\/p><\/blockquote>\n<p style=\"text-indent: 24pt; text-align: justify;\">La radiaci\u00f3n act\u00ednida es la electromagn\u00e9tica que es capaz de iniciar una reacci\u00f3n qu\u00edmica. El t\u00e9rmino es usado especialmente para la radiaci\u00f3n ultravioleta y tambi\u00e9n para denotar radiaci\u00f3n que podr\u00eda afectar a las emulsiones fotogr\u00e1ficas.<\/p>\n<p style=\"text-indent: 24pt; text-align: justify;\">Radiaci\u00f3n blanda, radiaci\u00f3n c\u00f3smica, radiaci\u00f3n de calor, radiaci\u00f3n de fondo, de fondo de microondas, radiaci\u00f3n dura, electromagn\u00e9tica, radiaci\u00f3n gamma, infrarroja, ionizante, monocrom\u00e1tica, policrom\u00e1tica, de sincrot\u00f3n, ultravioleta, de la teor\u00eda cu\u00e1ntica, de <a href=\"#\" onclick=\"referencia('radiactividad',event); return false;\">radiactividad<\/a>&#8230; y, como se puede ver, la radiaci\u00f3n en sus diversas formas es un universo en s\u00ed misma.<\/p>\n<p>&nbsp;<\/p>\n<blockquote><p><img decoding=\"async\" src=\"https:\/\/cdn0.unprofesor.com\/es\/posts\/4\/3\/9\/la_constante_de_planck_y_la_formula_de_la_constante_de_planck_3934_0_600.jpg\" alt=\"La CONSTANTE de PLANCK: definici\u00f3n sencilla - \u00a1\u00a1RESUMEN F\u00c1CIL!!\" \/><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">&#8220;El cuanto de acci\u00f3n de Planck desempe\u00f1a un papel central en la teor\u00eda de la <a title=\"Mec\u00e1nica cu\u00e1ntica\" href=\"https:\/\/es.wikipedia.org\/wiki\/Mec%C3%A1nica_cu%C3%A1ntica\">mec\u00e1nica cu\u00e1ntica<\/a>\u00a0y recibe su nombre de su descubridor, el f\u00edsico y matem\u00e1tico alem\u00e1n\u00a0<a title=\"Max Planck\" href=\"https:\/\/es.wikipedia.org\/wiki\/Max_Planck\">Max Planck<\/a>, uno de los padres de dicha teor\u00eda. Denotada como\u00a0<i><span class=\"mwe-math-element\"><span class=\"mwe-math-mathml-inline mwe-math-mathml-a11y\">h<\/span><img decoding=\"async\" class=\"mwe-math-fallback-image-inline mw-invert skin-invert\" src=\"https:\/\/wikimedia.org\/api\/rest_v1\/media\/math\/render\/svg\/b26be3e694314bc90c3215047e4a2010c6ee184a\" alt=\"{\\displaystyle h}\" aria-hidden=\"true\" \/><\/span><\/i>, es la constante que frecuentemente se define como el\u00a0<a title=\"Cuanto\" href=\"https:\/\/es.wikipedia.org\/wiki\/Cuanto\">cuanto<\/a>\u00a0elemental de\u00a0<a title=\"Acci\u00f3n (f\u00edsica)\" href=\"https:\/\/es.wikipedia.org\/wiki\/Acci%C3%B3n_(f%C3%ADsica)\">acci\u00f3n<\/a>. Planck la denominar\u00eda precisamente \u00abcuanto de acci\u00f3n\u00bb (en alem\u00e1n,\u00a0<i>Wirkungsquantum<\/i>), debido a que la cantidad denominada acci\u00f3n de un proceso f\u00edsico (el producto de la energ\u00eda implicada y el tiempo empleado) solo pod\u00eda tomar\u00a0<a title=\"Cantidad\" href=\"https:\/\/es.wikipedia.org\/wiki\/Cantidad#Cantidades_continuas_y_discretas\">valores discretos<\/a>, es decir, m\u00faltiplos enteros de\u00a0<i><span class=\"mwe-math-element\"><span class=\"mwe-math-mathml-inline mwe-math-mathml-a11y\">h<\/span><img decoding=\"async\" class=\"mwe-math-fallback-image-inline mw-invert skin-invert\" src=\"https:\/\/wikimedia.org\/api\/rest_v1\/media\/math\/render\/svg\/b26be3e694314bc90c3215047e4a2010c6ee184a\" alt=\"{\\displaystyle h}\" aria-hidden=\"true\" \/><\/span><\/i>.&#8221;<\/p>\n<\/blockquote>\n<p style=\"text-align: justify;\">Fue inicialmente propuesta como la constante de proporcionalidad entre la energ\u00eda\u00a0<i><span class=\"mwe-math-element\"><span class=\"mwe-math-mathml-inline mwe-math-mathml-a11y\">E<\/span><img decoding=\"async\" class=\"mwe-math-fallback-image-inline mw-invert skin-invert\" src=\"https:\/\/wikimedia.org\/api\/rest_v1\/media\/math\/render\/svg\/4232c9de2ee3eec0a9c0a19b15ab92daa6223f9b\" alt=\"{\\displaystyle E}\" aria-hidden=\"true\" \/><\/span><\/i>\u00a0de un\u00a0<a title=\"Fot\u00f3n\" href=\"https:\/\/es.wikipedia.org\/wiki\/Fot%C3%B3n\">fot\u00f3n<\/a>\u00a0y la frecuencia\u00a0<i><span class=\"mwe-math-element\"><span class=\"mwe-math-mathml-inline mwe-math-mathml-a11y\">f<\/span><img decoding=\"async\" class=\"mwe-math-fallback-image-inline mw-invert skin-invert\" src=\"https:\/\/wikimedia.org\/api\/rest_v1\/media\/math\/render\/svg\/132e57acb643253e7810ee9702d9581f159a1c61\" alt=\"{\\displaystyle f}\" aria-hidden=\"true\" \/><\/span><\/i>\u00a0de su onda electromagn\u00e9tica asociada.<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/wikimedia.org\/api\/rest_v1\/media\/math\/render\/svg\/f2ee55300faabdbff114046bed1a1723960a1caa\" alt=\"{\\displaystyle E=hf\\,}\" \/><\/p>\n<p>Dado que la\u00a0<a title=\"Frecuencia\" href=\"https:\/\/es.wikipedia.org\/wiki\/Frecuencia\">frecuencia<\/a>\u00a0<i><span class=\"mwe-math-element\"><span class=\"mwe-math-mathml-inline mwe-math-mathml-a11y\">f<\/span><img decoding=\"async\" class=\"mwe-math-fallback-image-inline mw-invert skin-invert\" src=\"https:\/\/wikimedia.org\/api\/rest_v1\/media\/math\/render\/svg\/132e57acb643253e7810ee9702d9581f159a1c61\" alt=\"{\\displaystyle f}\" aria-hidden=\"true\" \/><\/span><\/i>, la\u00a0<a title=\"Longitud de onda\" href=\"https:\/\/es.wikipedia.org\/wiki\/Longitud_de_onda\">longitud de onda<\/a>\u00a0<i><span class=\"mwe-math-element\"><span class=\"mwe-math-mathml-inline mwe-math-mathml-a11y\">\u03bb<\/span><img decoding=\"async\" class=\"mwe-math-fallback-image-inline mw-invert skin-invert\" src=\"https:\/\/wikimedia.org\/api\/rest_v1\/media\/math\/render\/svg\/b43d0ea3c9c025af1be9128e62a18fa74bedda2a\" alt=\"{\\displaystyle \\lambda }\" aria-hidden=\"true\" \/><\/span><\/i>, y la\u00a0<a title=\"Velocidad de la luz\" href=\"https:\/\/es.wikipedia.org\/wiki\/Velocidad_de_la_luz\">velocidad de la luz<\/a>\u00a0<i><span class=\"mwe-math-element\"><span class=\"mwe-math-mathml-inline mwe-math-mathml-a11y\">c<\/span><img decoding=\"async\" class=\"mwe-math-fallback-image-inline mw-invert skin-invert\" src=\"https:\/\/wikimedia.org\/api\/rest_v1\/media\/math\/render\/svg\/86a67b81c2de995bd608d5b2df50cd8cd7d92455\" alt=\"{\\displaystyle c}\" aria-hidden=\"true\" \/><\/span><\/i>\u00a0cumplen\u00a0<span class=\"mwe-math-element\"><span class=\"mwe-math-mathml-inline mwe-math-mathml-a11y\">\u03bbf=c<\/span><img decoding=\"async\" class=\"mwe-math-fallback-image-inline mw-invert skin-invert\" src=\"https:\/\/wikimedia.org\/api\/rest_v1\/media\/math\/render\/svg\/53f7859f76b2498f9fd6548f94f85e2e50b75cc6\" alt=\"{\\displaystyle \\lambda f=c}\" aria-hidden=\"true\" \/><\/span>\u00a0se puede expresar como:<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/wikimedia.org\/api\/rest_v1\/media\/math\/render\/svg\/5dbb63049ff36e30584940f483f17b0c68b68e1f\" alt=\"{\\displaystyle E={\\frac {hc}{\\lambda }}\\,}\" \/><\/p>\n<p style=\"text-align: justify;\">Otra ecuaci\u00f3n fundamental en la que interviene la <a href=\"#\" onclick=\"referencia('planck constante de',event); return false;\">constante de Planck<\/a> es la que relaciona el\u00a0<a title=\"Cantidad de movimiento\" href=\"https:\/\/es.wikipedia.org\/wiki\/Cantidad_de_movimiento\">momento lineal<\/a>\u00a0<i><span class=\"mwe-math-element\"><span class=\"mwe-math-mathml-inline mwe-math-mathml-a11y\">p<\/span><img decoding=\"async\" class=\"mwe-math-fallback-image-inline mw-invert skin-invert\" src=\"https:\/\/wikimedia.org\/api\/rest_v1\/media\/math\/render\/svg\/81eac1e205430d1f40810df36a0edffdc367af36\" alt=\"{\\displaystyle p}\" aria-hidden=\"true\" \/><\/span><\/i>\u00a0de una part\u00edcula con la\u00a0<a title=\"Dualidad onda corp\u00fasculo\" href=\"https:\/\/es.wikipedia.org\/wiki\/Dualidad_onda_corp%C3%BAsculo\">longitud de onda de De Broglie<\/a>\u00a0\u03bb de la misma:<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/wikimedia.org\/api\/rest_v1\/media\/math\/render\/svg\/3ba64e374ccd3f05ca8b646070a27e94a2b28921\" alt=\"{\\displaystyle \\lambda ={\\frac {h}{p}}}\" \/><\/p>\n<p style=\"text-align: justify;\">En aplicaciones donde la frecuencia viene expresada en t\u00e9rminos de radianes por segundo o\u00a0<a class=\"mw-redirect\" title=\"Frecuencia angular\" href=\"https:\/\/es.wikipedia.org\/wiki\/Frecuencia_angular\">frecuencia angular<\/a>, es \u00fatil incluir el factor\u00a0<span class=\"mwe-math-element\"><span class=\"mwe-math-mathml-inline mwe-math-mathml-a11y\">12\u03c0<\/span><img decoding=\"async\" class=\"mwe-math-fallback-image-inline mw-invert skin-invert\" src=\"https:\/\/wikimedia.org\/api\/rest_v1\/media\/math\/render\/svg\/129204d50704b07e6a4223870954242b21170354\" alt=\"{\\displaystyle {\\frac {1}{2\\pi }}}\" aria-hidden=\"true\" \/><\/span>\u00a0dentro de la <a href=\"#\" onclick=\"referencia('planck constante de',event); return false;\">constante de Planck<\/a>. La constante resultante, \u00ab<a href=\"#\" onclick=\"referencia('planck constante de',event); return false;\">constante de Planck<\/a> reducida\u00bb o \u00abconstante de Dirac\u00bb, se expresa como\u00a0<i>\u0127<\/i>\u00a0(\u00ab<i>h barra<\/i>\u00bb):<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/wikimedia.org\/api\/rest_v1\/media\/math\/render\/svg\/df05180652a87fe1af83af4bba3402117bd18466\" alt=\"{\\displaystyle \\hbar ={\\frac {h}{2\\pi }}}\" \/><\/p>\n<p style=\"text-align: justify;\">De esta forma la energ\u00eda de un <a href=\"#\" onclick=\"referencia('foton',event); return false;\">fot\u00f3n<\/a> con frecuencia angular\u00a0<i><span class=\"mwe-math-element\"><span class=\"mwe-math-mathml-inline mwe-math-mathml-a11y\">\u03c9<\/span><img decoding=\"async\" class=\"mwe-math-fallback-image-inline mw-invert skin-invert\" src=\"https:\/\/wikimedia.org\/api\/rest_v1\/media\/math\/render\/svg\/48eff443f9de7a985bb94ca3bde20813ea737be8\" alt=\"{\\displaystyle \\omega }\" aria-hidden=\"true\" \/><\/span><\/i>, donde\u00a0<i><span class=\"mwe-math-element\"><span class=\"mwe-math-mathml-inline mwe-math-mathml-a11y\">\u03c9=2\u03c0f<\/span><img decoding=\"async\" class=\"mwe-math-fallback-image-inline mw-invert skin-invert\" src=\"https:\/\/wikimedia.org\/api\/rest_v1\/media\/math\/render\/svg\/7a1bf35d395c2d52391265e4bbda0aed14f52579\" alt=\"{\\displaystyle \\omega =2\\pi f}\" aria-hidden=\"true\" \/><\/span><\/i>, se podr\u00e1 expresar como:<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/wikimedia.org\/api\/rest_v1\/media\/math\/render\/svg\/fb16565f02349106457258633097e0d0414a8e2d\" alt=\"{\\displaystyle E=\\hbar \\omega }\" \/><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">El camino que llev\u00f3 a\u00a0<a title=\"Max Planck\" href=\"https:\/\/es.wikipedia.org\/wiki\/Max_Planck\">Max Planck<\/a>\u00a0a su constante tuvo su origen en un proyecto que comenz\u00f3 con un cuarto de siglo de anterioridad, la teor\u00eda sobre \u00abla ley de distribuci\u00f3n de energ\u00eda del espectro normal\u00bb.<sup id=\"cite_ref-2\" class=\"reference separada\"><\/sup>\u00a0En \u00e9l estudiaba la\u00a0<a title=\"Radiaci\u00f3n t\u00e9rmica\" href=\"https:\/\/es.wikipedia.org\/wiki\/Radiaci%C3%B3n_t%C3%A9rmica\">radiaci\u00f3n t\u00e9rmica<\/a>\u00a0emitida por un cuerpo debido a su temperatura. En esta teor\u00eda se introdujo en 1862 el concepto de\u00a0<a title=\"Cuerpo negro\" href=\"https:\/\/es.wikipedia.org\/wiki\/Cuerpo_negro\">cuerpo negro<\/a>, cuya superficie absorbe toda la radiaci\u00f3n t\u00e9rmica que incide sobre \u00e9l y que adem\u00e1s emite la radiaci\u00f3n t\u00e9rmica con el mismo\u00a0<a title=\"Espectro de frecuencias\" href=\"https:\/\/es.wikipedia.org\/wiki\/Espectro_de_frecuencias\">espectro<\/a>\u00a0a la misma temperatura.<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/phet.colorado.edu\/sims\/html\/blackbody-spectrum\/latest\/blackbody-spectrum-600.png\" alt=\"Espectro de radiaci\u00f3n del Cuerpo Negro - Cuerpo Negro | Ley de Planck | Ley de Wien - Simulaciones Interactivas de PhET\" \/><\/p>\n<p><strong>Esta es, la aut\u00e9ntica semilla de lo que m\u00e1s tarde ser\u00eda la Mec\u00e1nica Cu\u00e1ntica<\/strong><\/p>\n<p style=\"text-indent: 24pt; text-align: justify;\">Siempre me llam\u00f3 la atenci\u00f3n y se gan\u00f3 mi admiraci\u00f3n el f\u00edsico alem\u00e1n Max Planck (1.858 &#8211; 1.947), responsable entre otros muchos logros de la ley de radiaci\u00f3n de Planck, que da la distribuci\u00f3n de energ\u00eda radiada por un cuerpo negro. Introdujo en f\u00edsica el concepto novedoso de que la energ\u00eda es una cantidad que es radiada por un cuerpo en peque\u00f1os paquetes discretos, en vez de una emisi\u00f3n continua. Estos peque\u00f1os paquetes se conocieron como <em style=\"mso-bidi-font-style: normal;\">cuantos<\/em> y la ley formulada es la base de la teor\u00eda cu\u00e1ntica.<\/p>\n<p style=\"text-indent: 24pt; text-align: justify;\"><a href=\"#\" onclick=\"referencia('einstein',event); return false;\">Einstein<\/a> se inspir\u00f3 en este trabajo para a su vez presentar el suyo propio sobre el efecto fotoel\u00e9ctrico, donde la energ\u00eda m\u00e1xima cin\u00e9tica del foto<a href=\"#\" onclick=\"referencia('electron',event); return false;\">electr\u00f3n<\/a>, <em style=\"mso-bidi-font-style: normal;\">E<sub>m<\/sub><\/em>, est\u00e1 dada por la ecuaci\u00f3n que lleva su nombre: E<sub>m<\/sub> = hf &#8211; \u03a6.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/i.ytimg.com\/vi\/8-o8tfJlm5c\/hqdefault.jpg\" alt=\"Radiaci\u00f3n del Cuerpo Negro: F\u00f3rmula al detalle\" \/><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-indent: 24pt; text-align: justify;\">Planck public\u00f3 en 1.900 un art\u00edculo sobre la radiaci\u00f3n de cuerpo negro que sent\u00f3 las bases para la teor\u00eda de la mec\u00e1nica cu\u00e1ntica que m\u00e1s tarde desarrollaron otros, como el mismo <a href=\"#\" onclick=\"referencia('einstein',event); return false;\">Einstein<\/a>, Heisenberg, Schr\u00f6dinger, Dirac, Feymann, etc. Todos los f\u00edsicos son conocedores de la enorme contribuci\u00f3n que Max Planck hizo en f\u00edsica: la <a href=\"#\" onclick=\"referencia('planck constante de',event); return false;\">constante de Planck<\/a>, radiaci\u00f3n de Planck, <a href=\"#\" onclick=\"referencia('planck longitud de',event); return false;\">longitud de Planck<\/a>, unidades de Planck, etc. Es posible que sea el f\u00edsico de la historia que m\u00e1s veces ha dado su nombre a conceptos de f\u00edsica. Pongamos un par te ejemplos de su ingenio:<\/p>\n<ol>\n<li><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-full wp-image-417\" title=\"long_planck\" src=\"http:\/\/www.emiliosilveravazquez.com\/blog\/wp-content\/uploads\/2008\/07\/long_planck.png\" alt=\"long_planck\" width=\"101\" height=\"22\" \/> vale 10<sup>-35<\/sup> metros. Esta escala de longitud (veinte \u00f3rdenes de magnitud menor que el tama\u00f1o del <a href=\"#\" onclick=\"referencia('proton',event); return false;\">prot\u00f3n<\/a>, de 10<sup>-15<\/sup> m) es a la que la descripci\u00f3n cl\u00e1sica de gravedad cesa de ser v\u00e1lida y debe ser tenida en cuenta la mec\u00e1nica cu\u00e1ntica. En la f\u00f3rmula que la describe, <em style=\"mso-bidi-font-style: normal;\">G<\/em> es la constante gravitacional, <em style=\"mso-bidi-font-style: normal;\">\u0127<\/em> es la <a href=\"#\" onclick=\"referencia('planck constante de',event); return false;\">constante de Planck<\/a> racionalizada y <em style=\"mso-bidi-font-style: normal;\">c<\/em> en la velocidad de la luz.<\/li>\n<li><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-full wp-image-418\" title=\"masa_planck\" src=\"http:\/\/www.emiliosilveravazquez.com\/blog\/wp-content\/uploads\/2008\/07\/masa_planck.png\" alt=\"masa_planck\" width=\"86\" height=\"22\" \/>. Es la masa de una part\u00edcula cuya longitud de onda Compton es igual a la <a href=\"#\" onclick=\"referencia('planck longitud de',event); return false;\">longitud de Planck<\/a>. En la ecuaci\u00f3n, <em style=\"mso-bidi-font-style: normal;\">\u0127<\/em> es la <a href=\"#\" onclick=\"referencia('planck constante de',event); return false;\">constante de Planck<\/a> racionalizada, <em style=\"mso-bidi-font-style: normal;\">c<\/em> es la velocidad de la luz y <em style=\"mso-bidi-font-style: normal;\">G<\/em> es la constante gravitacional.<\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"\" src=\"https:\/\/s3.abcstatics.com\/abc\/www\/multimedia\/ciencia\/2023\/12\/04\/PRX-figure-RDtPw9QptGgMMuhjAyeEchK-1200x840@abc.jpg\" alt=\"Anuncian una nueva teor\u00eda capaz de unir, por fin, la gravedad de Einstein con la mec\u00e1nica cu\u00e1ntica\" width=\"562\" height=\"394\" \/><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-indent: 24pt; text-align: justify;\">La descripci\u00f3n de una part\u00edcula elemental de esta masa, o part\u00edculas que interaccionan con energ\u00edas por part\u00edculas equivalentes a ellas (a trav\u00e9s de E = mc<sup>2<\/sup>), requiere de una teor\u00eda cu\u00e1ntica de la gravedad. Como la <a href=\"#\" onclick=\"referencia('planck masa de',event); return false;\">masa de Planck<\/a> es del orden de <strong>10<sup>-8<\/sup> Kg (equivalente a una energ\u00eda de<\/strong> <strong>10<sup>19<\/sup> GeV)<\/strong> y, por ejemplo, la masa del <a href=\"#\" onclick=\"referencia('proton',event); return false;\">prot\u00f3n<\/a> es del orden de 10<sup>-27<\/sup> Kg y las mayores energ\u00edas alcanzables en los aceleradores de part\u00edculas actuales son del orden de 10<sup>3<\/sup> GeV, los efectos de gravitaci\u00f3n cu\u00e1ntica no aparecen en los laboratorios de f\u00edsica de part\u00edculas. \u00danicamente en un laboratorio aparecieron part\u00edculas que ten\u00edan energ\u00edas del orden de la <a href=\"#\" onclick=\"referencia('planck masa de',event); return false;\">masa de Planck<\/a>: en el universo primitivo, de acuerdo con la teor\u00eda del <a href=\"#\" onclick=\"referencia('big bang',event); return false;\">Big Bang<\/a>, motivo \u00e9ste por el que es necesaria una teor\u00eda cu\u00e1ntica de la gravedad para estudiar aquellas condiciones. Esta energ\u00eda de la que estamos hablando, del orden de <strong>10<sup>19<\/sup> GeV<\/strong> (inalcanzable para nosotros), es la que necesitamos para verificar la <a href=\"#\" onclick=\"referencia('supercuerdas teoria',event); return false;\">teor\u00eda de supercuerdas<\/a>.<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"\" src=\"https:\/\/estaticos-cdn.prensaiberica.es\/clip\/9a433f45-1eea-42fa-b9a2-3a598dc77860_alta-libre-aspect-ratio_default_0.jpg\" alt=\"Un peque\u00f1o acelerador de part\u00edculas revoluciona la obtenci\u00f3n de energ\u00eda - El Peri\u00f3dico\" width=\"559\" height=\"315\" \/><\/p>\n<p>Si 10<sup>19<\/sup> GeV es la energ\u00eda que se necesita para verificar la teor\u00eda de cuerdas&#8230; habr\u00e1 que armarse de paciencia<\/p>\n<p style=\"text-indent: 24pt; text-align: justify;\">Siempre, desde que puedo recordar, me llam\u00f3 la atenci\u00f3n los misterios y secretos encerrados en la naturaleza, y la innegable batalla mantenida a lo largo de la historia por los cient\u00edficos para descubrirlos.<\/p>\n<p style=\"text-indent: 24pt; text-align: right;\"><strong><em>Emilio silvera V\u00e1zquez<\/em><\/strong><\/p>\n<hr size=\"1\" \/>\n<p style=\"text-align: justify;\"><a name=\"pie\"><\/a>* Ley de Stefan y Ley de desplazamiento de Wien.<\/p>\n<div class='bookmark'>\r\n\t\t<table align='left' border='0' cellpadding='0' width='100%'>\r\n\t\t<tr><td><span class='pushbutton'><a href='http:\/\/delicious.com\/post?url=http%3A%2F%2Fwww.emiliosilveravazquez.com%2Fblog%2F2026%2F05%2F31%2Fmatematicas-que-describen-la-naturaleza%2F&amp;title=Matem%C3%A1ticas+que+describen+la+Naturaleza' title='Delicious' target='_blank' rel='nofollow'><img src='http:\/\/www.emiliosilveravazquez.com\/blog\/wp-content\/plugins\/knxdt-bookmarks-wordpress-plugin\/images\/delicious.png'  alt='' class='book_img' border='none' style='margin:1px; padding: 0;'  \/><\/a><\/span><span class='pushbutton'><a href='http:\/\/digg.com\/submit?url=http%3A%2F%2Fwww.emiliosilveravazquez.com%2Fblog%2F2026%2F05%2F31%2Fmatematicas-que-describen-la-naturaleza%2F&amp;title=Matem%C3%A1ticas+que+describen+la+Naturaleza' title='Digg' target='_blank' rel='nofollow'><img src='http:\/\/www.emiliosilveravazquez.com\/blog\/wp-content\/plugins\/knxdt-bookmarks-wordpress-plugin\/images\/digg.png'  alt='' class='book_img' border='none' style='margin:1px; padding: 0;'  \/><\/a><\/span><span class='pushbutton'><a href='http:\/\/www.google.com\/bookmarks\/mark?op=edit&amp;bkmk=http%3A%2F%2Fwww.emiliosilveravazquez.com%2Fblog%2F2026%2F05%2F31%2Fmatematicas-que-describen-la-naturaleza%2F&amp;title=Matem%C3%A1ticas+que+describen+la+Naturaleza' title='Google' target='_blank' rel='nofollow'><img src='http:\/\/www.emiliosilveravazquez.com\/blog\/wp-content\/plugins\/knxdt-bookmarks-wordpress-plugin\/images\/google.png'   alt='' class='book_img' border='none' style='margin:1px; padding: 0;'  \/><\/a><\/span><span class='pushbutton'><a href='http:\/\/myweb2.search.yahoo.com\/myresults\/bookmarklet?u=http%3A%2F%2Fwww.emiliosilveravazquez.com%2Fblog%2F2026%2F05%2F31%2Fmatematicas-que-describen-la-naturaleza%2F&amp;t=Matem%C3%A1ticas+que+describen+la+Naturaleza' title='Yahoo' target='_blank' rel='nofollow'><img src='http:\/\/www.emiliosilveravazquez.com\/blog\/wp-content\/plugins\/knxdt-bookmarks-wordpress-plugin\/images\/yahoo.png'  alt='' class='book_img' border='none' style='margin:1px; padding: 0;'  \/><\/a><\/span><span class='pushbutton'><a href='http:\/\/www.technorati.com\/faves?add=http%3A%2F%2Fwww.emiliosilveravazquez.com%2Fblog%2F2026%2F05%2F31%2Fmatematicas-que-describen-la-naturaleza%2F' title='Technorati' target='_blank' rel='nofollow'><img src='http:\/\/www.emiliosilveravazquez.com\/blog\/wp-content\/plugins\/knxdt-bookmarks-wordpress-plugin\/images\/technorati.png'  alt='' class='book_img' border='none' style='margin:1px; padding: 0;'  \/><\/a><\/span><span class='pushbutton'><a href='http:\/\/meneame.net\/submit.php?url=http%3A%2F%2Fwww.emiliosilveravazquez.com%2Fblog%2F2026%2F05%2F31%2Fmatematicas-que-describen-la-naturaleza%2F' title='Meneame' target='_blank' rel='nofollow'><img src='http:\/\/www.emiliosilveravazquez.com\/blog\/wp-content\/plugins\/knxdt-bookmarks-wordpress-plugin\/images\/meneame.png'  alt='' class='book_img' border='none' style='margin:1px; padding: 0;'  \/><\/a><\/span><span class='pushbutton'><a href='http:\/\/enchilame.com\/submit.php?url=http:\/\/www.emiliosilveravazquez.com\/blog\/2026\/05\/31\/matematicas-que-describen-la-naturaleza\/' target='_blank' rel='nofollow'><img title='Enchilame' src='http:\/\/www.emiliosilveravazquez.com\/blog\/wp-content\/plugins\/knxdt-bookmarks-wordpress-plugin\/images\/enchilame.png'  alt='' class='book_img' border='none' style='margin:1px; padding: 0;'  \/><\/a><\/span><span class='pushbutton'><a href='http:\/\/www.blinklist.com\/index.php?Action=Blink\/addblink.php&amp;Description=&amp;Url=http%3A%2F%2Fwww.emiliosilveravazquez.com%2Fblog%2F2026%2F05%2F31%2Fmatematicas-que-describen-la-naturaleza%2F&amp;title=Matem%C3%A1ticas+que+describen+la+Naturaleza' title='BlinkList' target='_blank' rel='nofollow'><img src='http:\/\/www.emiliosilveravazquez.com\/blog\/wp-content\/plugins\/knxdt-bookmarks-wordpress-plugin\/images\/blinklist.png'  alt='' class='book_img' border='none' style='margin:1px; padding: 0;'  \/><\/a><\/span><span class='pushbutton'><a href='http:\/\/reddit.com\/submit?url=http%3A%2F%2Fwww.emiliosilveravazquez.com%2Fblog%2F2026%2F05%2F31%2Fmatematicas-que-describen-la-naturaleza%2F&amp;title=Matem%C3%A1ticas+que+describen+la+Naturaleza' title='Reddit' target='_blank' rel='nofollow'><img src='http:\/\/www.emiliosilveravazquez.com\/blog\/wp-content\/plugins\/knxdt-bookmarks-wordpress-plugin\/images\/reddit.png'  alt='' class='book_img' border='none' style='margin:1px; padding: 0;'  \/><\/a><\/span><span class='pushbutton'><a href='http:\/\/www.tecnologiadiaria.com\/2009\/07\/abrir-com-hotmail-correo.html' target='_blank' title='hotmail'><img src='http:\/\/www.emiliosilveravazquez.com\/blog\/wp-content\/plugins\/knxdt-bookmarks-wordpress-plugin\/images\/linklove.png' alt='hotmail correo' class='book_img' border='none' style='margin:1px; padding: 0;' \/><\/a><\/span><span class='pushbutton'><a href='http:\/\/bitacoras.com\/votar\/anotacion\/externo\/mini\/www.emiliosilveravazquez.com\/blog\/2026\/05\/31\/matematicas-que-describen-la-naturaleza\/' title='Bitacoras.com' target='_blank' rel='nofollow'><img src='http:\/\/www.emiliosilveravazquez.com\/blog\/wp-content\/plugins\/knxdt-bookmarks-wordpress-plugin\/images\/bitacoras.png'  alt='' class='book_img' border='none' style='margin:1px; padding: 0;'  \/><\/a><\/span><span class='pushbutton'><a href='http:\/\/www.wikio.es\/vote?url=http%3A%2F%2Fwww.emiliosilveravazquez.com%2Fblog%2F2026%2F05%2F31%2Fmatematicas-que-describen-la-naturaleza%2F' title='Wikio' target='_blank' rel='nofollow'><img src='http:\/\/www.emiliosilveravazquez.com\/blog\/wp-content\/plugins\/knxdt-bookmarks-wordpress-plugin\/images\/wikio.png'   alt='' class='book_img' border='none' style='margin:1px; padding: 0;'   \/><\/a><\/span><span class='pushbutton'><a href='http:\/\/friendfeed.com\/?url=http%3A%2F%2Fwww.emiliosilveravazquez.com%2Fblog%2F2026%2F05%2F31%2Fmatematicas-que-describen-la-naturaleza%2F&amp;title=Matem%C3%A1ticas+que+describen+la+Naturaleza' title='Friend Feed' target='_blank' rel='nofollow'><img src='http:\/\/www.emiliosilveravazquez.com\/blog\/wp-content\/plugins\/knxdt-bookmarks-wordpress-plugin\/images\/friendfeed.png'  alt='' class='book_img' border='none' style='margin:1px; padding: 0;'  \/><\/a><\/span><span class='pushbutton'><a href='http:\/\/www.facebook.com\/share.php?u=http%3A%2F%2Fwww.emiliosilveravazquez.com%2Fblog%2F2026%2F05%2F31%2Fmatematicas-que-describen-la-naturaleza%2F&amp;t=Matem%C3%A1ticas+que+describen+la+Naturaleza' title='Facebook' target='_blank' rel='nofollow'><img src='http:\/\/www.emiliosilveravazquez.com\/blog\/wp-content\/plugins\/knxdt-bookmarks-wordpress-plugin\/images\/facebook.png'  alt='' class='book_img' border='none' style='margin:1px; padding: 0;'  \/><\/a><\/span><span class='pushbutton'><a href='http:\/\/twitter.com\/home?status=Matem%C3%A1ticas+que+describen+la+Naturaleza: http%3A%2F%2Fwww.emiliosilveravazquez.com%2Fblog%2F2026%2F05%2F31%2Fmatematicas-que-describen-la-naturaleza%2F' title='Twitter' target='_blank' rel='nofollow'><img src='http:\/\/www.emiliosilveravazquez.com\/blog\/wp-content\/plugins\/knxdt-bookmarks-wordpress-plugin\/images\/twitter.png'  alt='' class='book_img' border='none' style='margin:1px; padding: 0;'  \/><\/a><\/span><span class='pushbutton'><a href='http:\/\/www.feedburner.com\/fb\/a\/emailFlare?itemTitle=Matem%C3%A1ticas+que+describen+la+Naturaleza&amp;uri=http%3A%2F%2Fwww.emiliosilveravazquez.com%2Fblog%2F2026%2F05%2F31%2Fmatematicas-que-describen-la-naturaleza%2F' title='Enviar por Email' target='_blank' rel='nofollow'><img src='http:\/\/www.emiliosilveravazquez.com\/blog\/wp-content\/plugins\/knxdt-bookmarks-wordpress-plugin\/images\/email.png'  alt='' class='book_img' border='none' style='margin:1px; padding: 0;'  \/><\/a><\/span><span style='font-weight:bold; padding-left: 5px;'><a href='http:\/\/wordpress.org\/extend\/plugins\/knxdt-bookmarks-wordpress-plugin\/' title='Plugin' rel='nofollow' target='_blank'>[?]<\/a><\/span><\/td><\/tr><\/table><br\/><br\/><\/div>","protected":false},"excerpt":{"rendered":"<p>Suponiendo que alg\u00fan f\u00edsico brillante nos resuelva la teor\u00eda de campos de cuerdas y derive las propiedades conocidas de nuestro universo, con un poco de suerte, podr\u00eda ocurrir en este mismo siglo, lo que no estar\u00eda nada mal considerando las dificultades de la empresa. Parece que la dichosa teor\u00eda no se puede verificar porque, para [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_s2mail":"yes","footnotes":""},"categories":[6],"tags":[],"_links":{"self":[{"href":"http:\/\/www.emiliosilveravazquez.com\/blog\/wp-json\/wp\/v2\/posts\/2145"}],"collection":[{"href":"http:\/\/www.emiliosilveravazquez.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.emiliosilveravazquez.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.emiliosilveravazquez.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/www.emiliosilveravazquez.com\/blog\/wp-json\/wp\/v2\/comments?post=2145"}],"version-history":[{"count":0,"href":"http:\/\/www.emiliosilveravazquez.com\/blog\/wp-json\/wp\/v2\/posts\/2145\/revisions"}],"wp:attachment":[{"href":"http:\/\/www.emiliosilveravazquez.com\/blog\/wp-json\/wp\/v2\/media?parent=2145"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.emiliosilveravazquez.com\/blog\/wp-json\/wp\/v2\/categories?post=2145"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.emiliosilveravazquez.com\/blog\/wp-json\/wp\/v2\/tags?post=2145"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}