{"id":21072,"date":"2018-05-15T04:35:55","date_gmt":"2018-05-15T03:35:55","guid":{"rendered":"http:\/\/www.emiliosilveravazquez.com\/blog\/?p=21072"},"modified":"2018-05-15T04:35:55","modified_gmt":"2018-05-15T03:35:55","slug":"hace-65-millones-de-anos","status":"publish","type":"post","link":"http:\/\/www.emiliosilveravazquez.com\/blog\/2018\/05\/15\/hace-65-millones-de-anos\/","title":{"rendered":"Hace 65 millones de a\u00f1os"},"content":{"rendered":"<div>\n<h1 style=\"text-align: justify;\"><img decoding=\"async\" style=\"font-size: 2em; font-weight: normal;\" src=\"http:\/\/img.europapress.es\/fotoweb\/fotonoticia_20170219085922_640.jpg\" alt=\"Resultado de imagen de El asteroide que acab\u00c3\u00b3 con los Dinosaurios\" \/><\/h1>\n<h1 style=\"text-align: justify;\"><\/h1>\n<h1 style=\"text-align: justify;\"><\/h1>\n<h1 style=\"text-align: justify;\"><\/h1>\n<h1 style=\"text-align: justify;\">Hallan los fragmentos mejor conservados del mundo del asteroide que acab\u00f3 con los dinosaurios<\/h1>\n<p>&nbsp;<\/p>\n<div style=\"text-align: justify;\">\n<h2>GEOLOG\u00cdA<\/h2>\n<p>&nbsp;<\/p>\n<p>Los fragmentos desprendidos del impacto llegaron hasta el espacio exterior<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<\/div>\n<\/div>\n<div><img decoding=\"async\" src=\"https:\/\/e00-elmundo.uecdn.es\/assets\/multimedia\/imagenes\/2018\/05\/10\/15259659771117.jpg\" alt=\"\" \/><\/div>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">Recreaci\u00f3n de la colisi\u00f3n del meteorito de Chicxulub y la expulsi\u00f3n de las tectitas. P. VON KNORRING\/V. VAJDA<\/p>\n<p>&nbsp;<\/p>\n<div style=\"text-align: justify;\">\n<p><a href=\"http:\/\/www.elmundo.es\/ciencia-y-salud\/ciencia\/2017\/08\/22\/599985b6e5fdeaa4758b457b.html\">El asteroide que acab\u00f3 con los dinosaurios sumi\u00f3 a la Tierra en la oscuridad durante dos a\u00f1os<\/a><\/p>\n<p>&nbsp;<\/p>\n<\/div>\n<p style=\"text-align: justify;\">Hace aproximadamente 66 millones de a\u00f1os el impacto del asteroide Chicxulub en la pen\u00ednsula de Yucat\u00e1n (M\u00e9xico) produjo una reacci\u00f3n en cadena que acab\u00f3 con el 70% de las especies del planeta. Famoso por extinguir a los dinosaurios que hab\u00edan dominado la tierra durante millones de a\u00f1os, este evento catastr\u00f3fico produjo una lluvia de rocas incandescentes a nivel global. Ahora un nuevo hallazgo de estas rocas (tectitas) en la isla colombiana de Gorgonilla arroja nuevos datos sobre su composici\u00f3n.<\/p>\n<p style=\"text-align: justify;\"><img decoding=\"async\" src=\"https:\/\/www.portalastronomico.com\/wp-content\/uploads\/2016\/03\/crater-asteroide-extincion-dinosaurios.jpg\" alt=\"Resultado de imagen de El asteroide que acab\u00c3\u00b3 con los Dinosaurios\" \/><\/p>\n<p style=\"text-align: justify;\">Un grupo de micropaleont\u00f3logos de la Universidad de Zaragoza ha participado en el descubrimiento que recoge la revista <a href=\"https:\/\/pubs.geoscienceworld.org\/geology\" target=\"_blank\"><em>Geology<\/em><\/a>. Los investigadores Ignacio Arenillas, Jos\u00e9 Antonio Arz y Vicente Gilabert han colaborado en esta investigaci\u00f3n internacional que ha permitido <strong>precisar la edad de estas esf\u00e9rulas de roca, demostrando que se formaron<\/strong> exactamente en el l\u00edmite Cret\u00e1cico\/Terciario (o l\u00edmite K\/T) <strong>como resultado del impacto del asteroide que caus\u00f3 la gran extinci\u00f3n<\/strong> que acab\u00f3 con los dinosaurios.<\/p>\n<p style=\"text-align: justify;\">&#8220;El m\u00e9todo de dataci\u00f3n arg\u00f3n-arg\u00f3n nos permiti\u00f3 conocer cu\u00e1ntos millones de a\u00f1os tienen estas rocas&#8221;, afirma a EL MUNDO el paleont\u00f3logo Jos\u00e9 Antonio Arz, coautor de la investigaci\u00f3n. Mediante este sistema se liberan los gases del interior de las muestras para su an\u00e1lisis.<\/p>\n<div><img decoding=\"async\" src=\"https:\/\/e00-elmundo.uecdn.es\/assets\/multimedia\/imagenes\/2018\/05\/10\/15259672259207.jpg\" alt=\"\" \/><\/div>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">Lugar del hallazgo en la Isla de Gorgonilla. HERMANN BERM\u00daDEZ<\/p>\n<p style=\"text-align: justify;\">La Isla de Gorgonilla, situada a 35 Km de la costa pac\u00edfica del norte de Colombia, es un islote deshabitado de unos dos kil\u00f3metros cuadrados cubierto por un bosque h\u00famedo tropical. <strong>En sus bordes litorales se escond\u00edan este tesoro de nuestro pasado geol\u00f3gico<\/strong>, una capa de 2 cent\u00edmetros de grosor de tectitas a\u00fan v\u00edtreas.<\/p>\n<p style=\"text-align: justify;\"><img decoding=\"async\" src=\"http:\/\/cdn3.radiosantafe.com\/wp-content\/uploads\/2016\/03\/GORGONA-GORGONILLA-.jpg\" alt=\"Resultado de imagen de La Isla de Gorgonilla\" \/><\/p>\n<p style=\"text-align: justify;\">Estas rocas, al ser fragmentos vidriosos sin ordenamiento cristalino, en la naturaleza tienden a convertirse en materiales m\u00e1s estables como la arcilla. Por lo que la mayor parte de las tectitas formadas por un evento catastr\u00f3fico como el impacto de un asteroide no conservan su composici\u00f3n original. No es el caso de las encontradas en Gorgonilla, catalogadas por los cient\u00edficos como las muestras m\u00e1s puras del mundo de este material.<\/p>\n<p style=\"text-align: justify;\">Transparentes y verdeoliva, estas peque\u00f1as perlas son capaces de contar un desastre de dimensiones globales. Fueron formadas a partir del impacto del Chicxulub (de 10 km de di\u00e1metro) contra la plataforma continental. <strong>La roca fundida (cuya composici\u00f3n es mezcla tanto del asteroide como del fondo marino), producto de la violenta fricci\u00f3n, ascendi\u00f3 hasta el espacio exterior<\/strong> donde se solidific\u00f3. Las tectitas reentraron en la atm\u00f3sfera incandescentes &#8216;lloviendo&#8217; alrededor del planeta, pero s\u00f3lo en esta zona se conservaron intactas.<\/p>\n<p style=\"text-align: justify;\">El hallazgo es relevante por muchos otros aspectos. Las esf\u00e9rulas de impacto <strong>viajaron 2.000 kil\u00f3metros hasta depositarse en el fondo de un oc\u00e9ano a m\u00e1s de 2 kil\u00f3metros de profundidad<\/strong>, lejos de cualquier continente. Estas profundidades se sit\u00faan por debajo del denominado nivel de compensaci\u00f3n de la calcita, una barrera geoqu\u00edmica que marca el l\u00edmite donde el agua tiene la suficiente acidez como para disolver las conchas de los foramin\u00edferos planct\u00f3nicos (organismos que utilizados como indicadores paleoecol\u00f3gicos).<\/p>\n<div><img decoding=\"async\" src=\"https:\/\/e00-elmundo.uecdn.es\/assets\/multimedia\/imagenes\/2018\/05\/10\/15259672859109.jpg\" alt=\"\" \/><\/div>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">Detalle de la capa de tectitas de Gorgonilla. HERMANN BERM\u00daDEZ<\/p>\n<p style=\"text-align: justify;\">Por este motivo no hay presencia de estos microf\u00f3siles en la mayor parte de los 40 metros de rocas estudiados, excepto en el primer metro de roca situado sobre la capa de tectitas. Lo que sugiere, seg\u00fan los investigadores, que debido al impacto del asteroide la superficie marina se elev\u00f3, provocando tambi\u00e9n la aparici\u00f3n de islotes. Hip\u00f3tesis confirmada por un an\u00e1lisis sedimentol\u00f3gico llevado a cabo por los investigadores, en donde la existencia de rastros de comunidades pioneras de helechos que debieron colonizar las islas surgidas alrededor de Gorgonilla demuestra la magnitud de los terremotos que asolaron la zona.<\/p>\n<h3 style=\"text-align: justify;\">Extinci\u00f3n en cadena<\/h3>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" src=\"http:\/\/sophimania.pe\/media\/images\/articulos\/07-14\/1exdinohome.jpg\" alt=\"Resultado de imagen de Extinci\u00c3\u00b3n en cadena causada por el meteorito que mat\u00c3\u00b3 a los dinosaurtios\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Aunque parezca contradictorio, aquella cat\u00e1strofe natural abri\u00f3 la puerta para que, 65 millones de a\u00f1os m\u00e1s tarde, peque\u00f1os mam\u00edferos pudieran evolucionar hasta llegar a la especie que hoy representamos.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">El hallazgo ha arrojado<strong> nuevos datos sobre la extinci\u00f3n masiva que sufri\u00f3 la Tierra<\/strong>. La palin\u00f3loga Vivi Vajda (coautora tambi\u00e9n del estudio) del Museo de Historia Natural de Suecia ha demostrado por vez primera que la vegetaci\u00f3n sufri\u00f3 una mortandad masiva en el l\u00edmite K\/T incluso en los tr\u00f3picos. Anteriormente s\u00f3lo se hab\u00eda encontrado sobreabundancia de esporas de helechos en altas latitudes como Jap\u00f3n o Nueva Zelanda. Siendo un buen indicativo debido a su resistencia y tendencia a colonizar ambientes catastr\u00f3ficos, es la primera vez que se hallan en latitudes templadas y tropicales.<\/p>\n<p style=\"text-align: justify;\">&#8220;El impacto produjo una serie de<strong> perturbaciones medioambientales en cadena<\/strong>&#8220;, relata Jos\u00e9 Antonio Arz. Se produjo un pulso de calor de hasta 80 grados cent\u00edgrados de media por lo que muchos bosques ardieron espont\u00e1neamente. A esto hay que sumarle la lluvia de rocas incandescentes (tectitas) mencionada anteriormente. &#8220;Los terremotos provocados por el impacto (que dej\u00f3 un cr\u00e1ter de 200 kil\u00f3metros de di\u00e1metro enterrado bajo cientos de metros de sedimentos) llegaron a ser de intensidad 13 en la <a href=\"#\" onclick=\"referencia('richter escala de',event); return false;\">escala de Richter<\/a>, algo casi inimaginable hoy en d\u00eda&#8221;, a\u00f1ade el paleont\u00f3logo.<\/p>\n<p style=\"text-align: justify;\"><img decoding=\"async\" src=\"http:\/\/www.lamordida.com\/web\/wp-content\/uploads\/2016\/08\/El-crater-del-Yucat%C3%A1n-La-Mordida1.jpg\" alt=\"Resultado de imagen de El asteroide que acab\u00c3\u00b3 con los Dinosaurios\" \/><\/p>\n<p style=\"text-align: justify;\">Hace dos a\u00f1os en un estudio publicado en <a href=\"http:\/\/www.sciencemag.org\/news\/2015\/10\/volcano-asteroid-combo-may-have-done-dinosaurs\" target=\"_blank\"><em>Science<\/em><\/a>, un equipo internacional de ge\u00f3logos hall\u00f3 nuevas pruebas de que<strong> el impacto del asteroide aceler\u00f3 las erupciones volc\u00e1nicas en todo el globo<\/strong>, especialmente en la meseta del Dec\u00e1n en India, donde en la actualidad se registran las mayores formaciones volc\u00e1nicas del planeta.<\/p>\n<p style=\"text-align: justify;\">Otro <a href=\"http:\/\/www.elmundo.es\/ciencia-y-salud\/ciencia\/2017\/08\/22\/599985b6e5fdeaa4758b457b.html\">estudio<\/a> publicado el a\u00f1o pasado en <em>Proceedings of the National Academy of Sciences<\/em> (<a href=\"http:\/\/www.pnas.org\/\" target=\"_blank\">PNAS<\/a>), describi\u00f3 el panorama desolador del planeta tras el impacto, una <strong>noche invernal perpetua<\/strong> resultado de la brutal transformaci\u00f3n tanto en el clima como en la superficie terrestre. El cataclismo que tristemente acab\u00f3 con los dinosaurios dej\u00f3 v\u00eda libre a peque\u00f1os animales, como los mam\u00edferos, que se resguardaron de tan terribles consecuencias.<\/p>\n<p style=\"text-align: justify;\">Incendios espont\u00e1neos, tsunamis, erupciones volc\u00e1nicas y bloqueo de la luz solar; la Tierra se convirti\u00f3 en un infierno para la mayor\u00eda de los animales y la fauna, pero nosotros mismos somos el testigo de que &#8220;la vida se abre camino&#8221; y que muchos animales lograron sobrevivir &#8216;al fin del mundo&#8217;.<\/p>\n<div><img decoding=\"async\" src=\"https:\/\/e00-elmundo.uecdn.es\/assets\/multimedia\/imagenes\/2018\/05\/10\/15259720490384.jpg\" alt=\"\" \/><\/div>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">Ilustraci\u00f3n del Chicxulub impactando sobre los mares tropicales y poco profundos de la pen\u00ednsula de Yucat\u00e1n. DONALD E. DAVID \/ NASA<\/p>\n<p style=\"text-align: justify;\">Reportaje de Prensa<\/p>\n<p>&nbsp;<\/p>\n<div class='bookmark'>\r\n\t\t<table align='left' border='0' cellpadding='0' width='100%'>\r\n\t\t<tr><td><span class='pushbutton'><a href='http:\/\/delicious.com\/post?url=http%3A%2F%2Fwww.emiliosilveravazquez.com%2Fblog%2F2018%2F05%2F15%2Fhace-65-millones-de-anos%2F&amp;title=Hace+65+millones+de+a%C3%B1os' title='Delicious' target='_blank' rel='nofollow'><img src='http:\/\/www.emiliosilveravazquez.com\/blog\/wp-content\/plugins\/knxdt-bookmarks-wordpress-plugin\/images\/delicious.png'  alt='' class='book_img' border='none' style='margin:1px; padding: 0;'  \/><\/a><\/span><span class='pushbutton'><a href='http:\/\/digg.com\/submit?url=http%3A%2F%2Fwww.emiliosilveravazquez.com%2Fblog%2F2018%2F05%2F15%2Fhace-65-millones-de-anos%2F&amp;title=Hace+65+millones+de+a%C3%B1os' title='Digg' target='_blank' rel='nofollow'><img src='http:\/\/www.emiliosilveravazquez.com\/blog\/wp-content\/plugins\/knxdt-bookmarks-wordpress-plugin\/images\/digg.png'  alt='' class='book_img' border='none' style='margin:1px; padding: 0;'  \/><\/a><\/span><span class='pushbutton'><a href='http:\/\/www.google.com\/bookmarks\/mark?op=edit&amp;bkmk=http%3A%2F%2Fwww.emiliosilveravazquez.com%2Fblog%2F2018%2F05%2F15%2Fhace-65-millones-de-anos%2F&amp;title=Hace+65+millones+de+a%C3%B1os' title='Google' target='_blank' rel='nofollow'><img src='http:\/\/www.emiliosilveravazquez.com\/blog\/wp-content\/plugins\/knxdt-bookmarks-wordpress-plugin\/images\/google.png'   alt='' class='book_img' border='none' style='margin:1px; padding: 0;'  \/><\/a><\/span><span class='pushbutton'><a href='http:\/\/myweb2.search.yahoo.com\/myresults\/bookmarklet?u=http%3A%2F%2Fwww.emiliosilveravazquez.com%2Fblog%2F2018%2F05%2F15%2Fhace-65-millones-de-anos%2F&amp;t=Hace+65+millones+de+a%C3%B1os' title='Yahoo' target='_blank' rel='nofollow'><img src='http:\/\/www.emiliosilveravazquez.com\/blog\/wp-content\/plugins\/knxdt-bookmarks-wordpress-plugin\/images\/yahoo.png'  alt='' class='book_img' border='none' style='margin:1px; padding: 0;'  \/><\/a><\/span><span class='pushbutton'><a href='http:\/\/www.technorati.com\/faves?add=http%3A%2F%2Fwww.emiliosilveravazquez.com%2Fblog%2F2018%2F05%2F15%2Fhace-65-millones-de-anos%2F' title='Technorati' target='_blank' rel='nofollow'><img src='http:\/\/www.emiliosilveravazquez.com\/blog\/wp-content\/plugins\/knxdt-bookmarks-wordpress-plugin\/images\/technorati.png'  alt='' class='book_img' border='none' style='margin:1px; padding: 0;'  \/><\/a><\/span><span class='pushbutton'><a href='http:\/\/meneame.net\/submit.php?url=http%3A%2F%2Fwww.emiliosilveravazquez.com%2Fblog%2F2018%2F05%2F15%2Fhace-65-millones-de-anos%2F' title='Meneame' target='_blank' rel='nofollow'><img src='http:\/\/www.emiliosilveravazquez.com\/blog\/wp-content\/plugins\/knxdt-bookmarks-wordpress-plugin\/images\/meneame.png'  alt='' class='book_img' border='none' style='margin:1px; padding: 0;'  \/><\/a><\/span><span class='pushbutton'><a href='http:\/\/enchilame.com\/submit.php?url=http:\/\/www.emiliosilveravazquez.com\/blog\/2018\/05\/15\/hace-65-millones-de-anos\/' target='_blank' rel='nofollow'><img title='Enchilame' src='http:\/\/www.emiliosilveravazquez.com\/blog\/wp-content\/plugins\/knxdt-bookmarks-wordpress-plugin\/images\/enchilame.png'  alt='' class='book_img' border='none' style='margin:1px; padding: 0;'  \/><\/a><\/span><span class='pushbutton'><a href='http:\/\/www.blinklist.com\/index.php?Action=Blink\/addblink.php&amp;Description=&amp;Url=http%3A%2F%2Fwww.emiliosilveravazquez.com%2Fblog%2F2018%2F05%2F15%2Fhace-65-millones-de-anos%2F&amp;title=Hace+65+millones+de+a%C3%B1os' title='BlinkList' target='_blank' rel='nofollow'><img src='http:\/\/www.emiliosilveravazquez.com\/blog\/wp-content\/plugins\/knxdt-bookmarks-wordpress-plugin\/images\/blinklist.png'  alt='' class='book_img' border='none' style='margin:1px; padding: 0;'  \/><\/a><\/span><span class='pushbutton'><a href='http:\/\/reddit.com\/submit?url=http%3A%2F%2Fwww.emiliosilveravazquez.com%2Fblog%2F2018%2F05%2F15%2Fhace-65-millones-de-anos%2F&amp;title=Hace+65+millones+de+a%C3%B1os' title='Reddit' target='_blank' rel='nofollow'><img src='http:\/\/www.emiliosilveravazquez.com\/blog\/wp-content\/plugins\/knxdt-bookmarks-wordpress-plugin\/images\/reddit.png'  alt='' class='book_img' border='none' style='margin:1px; padding: 0;'  \/><\/a><\/span><span class='pushbutton'><a href='http:\/\/www.tecnologiadiaria.com\/2009\/07\/abrir-com-hotmail-correo.html' target='_blank' title='hotmail'><img src='http:\/\/www.emiliosilveravazquez.com\/blog\/wp-content\/plugins\/knxdt-bookmarks-wordpress-plugin\/images\/linklove.png' alt='hotmail correo' class='book_img' border='none' style='margin:1px; padding: 0;' \/><\/a><\/span><span class='pushbutton'><a href='http:\/\/bitacoras.com\/votar\/anotacion\/externo\/mini\/www.emiliosilveravazquez.com\/blog\/2018\/05\/15\/hace-65-millones-de-anos\/' title='Bitacoras.com' target='_blank' rel='nofollow'><img src='http:\/\/www.emiliosilveravazquez.com\/blog\/wp-content\/plugins\/knxdt-bookmarks-wordpress-plugin\/images\/bitacoras.png'  alt='' class='book_img' border='none' style='margin:1px; padding: 0;'  \/><\/a><\/span><span class='pushbutton'><a href='http:\/\/www.wikio.es\/vote?url=http%3A%2F%2Fwww.emiliosilveravazquez.com%2Fblog%2F2018%2F05%2F15%2Fhace-65-millones-de-anos%2F' title='Wikio' target='_blank' rel='nofollow'><img src='http:\/\/www.emiliosilveravazquez.com\/blog\/wp-content\/plugins\/knxdt-bookmarks-wordpress-plugin\/images\/wikio.png'   alt='' class='book_img' border='none' style='margin:1px; padding: 0;'   \/><\/a><\/span><span class='pushbutton'><a href='http:\/\/friendfeed.com\/?url=http%3A%2F%2Fwww.emiliosilveravazquez.com%2Fblog%2F2018%2F05%2F15%2Fhace-65-millones-de-anos%2F&amp;title=Hace+65+millones+de+a%C3%B1os' title='Friend Feed' target='_blank' rel='nofollow'><img src='http:\/\/www.emiliosilveravazquez.com\/blog\/wp-content\/plugins\/knxdt-bookmarks-wordpress-plugin\/images\/friendfeed.png'  alt='' class='book_img' border='none' style='margin:1px; padding: 0;'  \/><\/a><\/span><span class='pushbutton'><a href='http:\/\/www.facebook.com\/share.php?u=http%3A%2F%2Fwww.emiliosilveravazquez.com%2Fblog%2F2018%2F05%2F15%2Fhace-65-millones-de-anos%2F&amp;t=Hace+65+millones+de+a%C3%B1os' title='Facebook' target='_blank' rel='nofollow'><img src='http:\/\/www.emiliosilveravazquez.com\/blog\/wp-content\/plugins\/knxdt-bookmarks-wordpress-plugin\/images\/facebook.png'  alt='' class='book_img' border='none' style='margin:1px; padding: 0;'  \/><\/a><\/span><span class='pushbutton'><a href='http:\/\/twitter.com\/home?status=Hace+65+millones+de+a%C3%B1os: http%3A%2F%2Fwww.emiliosilveravazquez.com%2Fblog%2F2018%2F05%2F15%2Fhace-65-millones-de-anos%2F' title='Twitter' target='_blank' rel='nofollow'><img src='http:\/\/www.emiliosilveravazquez.com\/blog\/wp-content\/plugins\/knxdt-bookmarks-wordpress-plugin\/images\/twitter.png'  alt='' class='book_img' border='none' style='margin:1px; padding: 0;'  \/><\/a><\/span><span class='pushbutton'><a href='http:\/\/www.feedburner.com\/fb\/a\/emailFlare?itemTitle=Hace+65+millones+de+a%C3%B1os&amp;uri=http%3A%2F%2Fwww.emiliosilveravazquez.com%2Fblog%2F2018%2F05%2F15%2Fhace-65-millones-de-anos%2F' title='Enviar por Email' target='_blank' rel='nofollow'><img src='http:\/\/www.emiliosilveravazquez.com\/blog\/wp-content\/plugins\/knxdt-bookmarks-wordpress-plugin\/images\/email.png'  alt='' class='book_img' border='none' style='margin:1px; padding: 0;'  \/><\/a><\/span><span style='font-weight:bold; padding-left: 5px;'><a href='http:\/\/wordpress.org\/extend\/plugins\/knxdt-bookmarks-wordpress-plugin\/' title='Plugin' rel='nofollow' target='_blank'>[?]<\/a><\/span><\/td><\/tr><\/table><br\/><br\/><\/div>","protected":false},"excerpt":{"rendered":"<p>Hallan los fragmentos mejor conservados del mundo del asteroide que acab\u00f3 con los dinosaurios &nbsp; GEOLOG\u00cdA &nbsp; Los fragmentos desprendidos del impacto llegaron hasta el espacio exterior &nbsp; &nbsp; &nbsp; &nbsp; Recreaci\u00f3n de la colisi\u00f3n del meteorito de Chicxulub y la expulsi\u00f3n de las tectitas. P. VON KNORRING\/V. VAJDA &nbsp; El asteroide que acab\u00f3 con [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_s2mail":"yes","footnotes":""},"categories":[142],"tags":[],"_links":{"self":[{"href":"http:\/\/www.emiliosilveravazquez.com\/blog\/wp-json\/wp\/v2\/posts\/21072"}],"collection":[{"href":"http:\/\/www.emiliosilveravazquez.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.emiliosilveravazquez.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.emiliosilveravazquez.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/www.emiliosilveravazquez.com\/blog\/wp-json\/wp\/v2\/comments?post=21072"}],"version-history":[{"count":0,"href":"http:\/\/www.emiliosilveravazquez.com\/blog\/wp-json\/wp\/v2\/posts\/21072\/revisions"}],"wp:attachment":[{"href":"http:\/\/www.emiliosilveravazquez.com\/blog\/wp-json\/wp\/v2\/media?parent=21072"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.emiliosilveravazquez.com\/blog\/wp-json\/wp\/v2\/categories?post=21072"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.emiliosilveravazquez.com\/blog\/wp-json\/wp\/v2\/tags?post=21072"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}