{"id":17279,"date":"2017-03-01T07:28:22","date_gmt":"2017-03-01T06:28:22","guid":{"rendered":"http:\/\/www.emiliosilveravazquez.com\/blog\/?p=17279"},"modified":"2017-03-01T07:28:22","modified_gmt":"2017-03-01T06:28:22","slug":"si-%c2%a1todo-es-universo-4","status":"publish","type":"post","link":"http:\/\/www.emiliosilveravazquez.com\/blog\/2017\/03\/01\/si-%c2%a1todo-es-universo-4\/","title":{"rendered":"S\u00ed, \u00a1todo es Universo!"},"content":{"rendered":"<div style=\"text-align: justify;\">\u00a0<img decoding=\"async\" loading=\"lazy\" id=\"irc_mi\" src=\"http:\/\/necesitodetodos.org\/wp-content\/uploads\/2013\/03\/clarke.jpg\" alt=\"\" width=\"560\" height=\"420\" \/><\/div>\n<div>\n<div style=\"text-align: justify;\">\n<h2>\u00a0<a href=\"http:\/\/www.emiliosilveravazquez.com\/blog\/2014\/04\/21\/la-necesidad-agudiza-la-imaginacion-2\/\" rel=\"prev\">La necesidad agudiza la imaginaci\u00f3n<\/a><\/h2>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" loading=\"lazy\" id=\"irc_mi\" src=\"http:\/\/4.bp.blogspot.com\/_w1kycNNBkOE\/TGFY3jtGWsI\/AAAAAAAAEFs\/BCL1_6fsOTk\/s640\/estrella-neutrones-quarks2.jpg\" alt=\"\" width=\"400\" height=\"284\" \/><\/p>\n<p>Si existen las estrellas de Quarks, tendr\u00edan una densidad intermedia entre las estrellas de Neutrones y los Agujeros Negros<\/p>\n<p>Si bien no se han observado objetos que puedan ser asociados a estrellas compuestas completamente de <a href=\"http:\/\/www.emiliosilveravazquez.com\/blog\/2014\/04\/22\/%c2%a1estrellas-de-quarks-materia-extrana-3\/#\">quarks<\/a>, la existencia de <a href=\"http:\/\/www.emiliosilveravazquez.com\/blog\/2014\/04\/22\/%c2%a1estrellas-de-quarks-materia-extrana-3\/#\">quarks<\/a> desconfinados en el interior de estrellas de <a href=\"http:\/\/www.emiliosilveravazquez.com\/blog\/2014\/04\/22\/%c2%a1estrellas-de-quarks-materia-extrana-3\/#\">neutrones<\/a> no est\u00e1 descartada, ya que la composici\u00f3n de la materia a esas densidades (\u03c1 ~ 10<sup>15<\/sup> g\/cm<sup>3<\/sup>) es a\u00fan incierta.<\/p>\n<p>&nbsp;<\/p>\n<\/div>\n<div style=\"text-align: justify;\">\n<div><a href=\"http:\/\/www.emiliosilveravazquez.com\/blog\/2014\/04\/22\/%c2%a1estrellas-de-quarks-materia-extrana-3\/\" rel=\"next\">\u00a1Estrellas de Quarks! Materia extra\u00f1a<\/a><\/div>\n<\/div>\n<p style=\"text-align: justify;\"><img decoding=\"async\" loading=\"lazy\" id=\"irc_mi\" src=\"http:\/\/creationwiki.org\/pool\/images\/e\/ec\/Space_molecules.jpg\" alt=\"\" width=\"510\" height=\"293\" \/><\/p>\n<div>\n<div style=\"text-align: justify;\">\n<h2>\u00a0\u00ab <a href=\"http:\/\/www.emiliosilveravazquez.com\/blog\/2013\/09\/23\/%c2%bf%c2%a1panspermia\/\" rel=\"prev\">\u00bf\u00a1Panspermia!?<\/a><\/h2>\n<\/div>\n<div style=\"text-align: justify;\">\n<div><a href=\"http:\/\/www.emiliosilveravazquez.com\/blog\/2013\/09\/23\/un-rumor-del-saber\/\" rel=\"next\">\u00a1La Humanidad! sus creencias, su complejidad<\/a> \u00bb<\/div>\n<\/div>\n<div style=\"text-align: justify;\"><img decoding=\"async\" loading=\"lazy\" src=\"http:\/\/farm6.static.flickr.com\/5021\/5668873139_5053186464_z.jpg\" alt=\"foto\" width=\"640\" height=\"609\" \/><\/div>\n<div style=\"text-align: justify;\">\n<p>&nbsp;<\/p>\n<div><strong>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0 \u00a0 \u00a0\u00a0 \u00a0\u00a0\u00a0\u00a0 \u00a1La Naturaleza! \u00bfCu\u00e1ndo dejar\u00e1 de sorprendernos?<\/strong><\/div>\n<\/div>\n<div style=\"text-align: justify;\">\n<div><strong><br \/>\n<\/strong><\/div>\n<p>La Naturaleza y nosotros, una simbiosis de perfecta armonia que nuestra condici\u00f3n, podr\u00eda llegar a romper si el proceso de humanizaci\u00f3n ae eterniza y no tomamos conciencia de lo importante que es, todo lo que nos rodea en su estado natural.\u00a0 No tenemos conciencia de que otros seres que, con nostros, pueblan el planeta necesitan de nosotros para poder evolucionar sin que, nuestras actividades nosivas, contaminen el mundo. Todas las formas de vida tienen la misma fuente, el mismo origen.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<\/div>\n<div style=\"text-align: justify;\">\n<p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 <img decoding=\"async\" loading=\"lazy\" id=\"irc_mi\" src=\"http:\/\/www.mjcmjc.com\/media\/catalog\/product\/cache\/1\/image\/9df78eab33525d08d6e5fb8d27136e95\/1\/0\/107339.jpg_1.jpg\" alt=\"\" width=\"378\" height=\"270\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Los seres vivos que han poblado nuestro mundo, desde el origen de la vida que no ha dejado de evolucionar nunca. Todas las formas de vida, sin excepci\u00f3n, est\u00e1n basadas en el Carbono. Sabemos que actualmente existen s\u00f3lo el 1% de todas las especies que poblaron nuestro planeta y, seguimos descubriendo especies nuevas mientras que otras desaparecen al no saberse adaptar al entorno. Estar atentos a los mensajes que la Naturaleza nos env\u00eda, ser consciente de su grandeza, cuidar nuestro mundo.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" loading=\"lazy\" src=\"http:\/\/www.canalred.info\/Galeria-de-imagenes\/Montanas\/Cerro%20de%20la%20silla.jpg\" alt=\"http:\/\/www.canalred.info\/Galeria-de-imagenes\/Montanas\/Cerro%20de%20la%20silla.jpg\" width=\"682\" height=\"512\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>La monta\u00f1a que, curiosa, se asoma por encima de las nubes mientras el Sol la contempla y la ba\u00f1a con su resplandor. El privilegio de poder contemplar la Naturaleza y ver como el Sol ti\u00f1e de rojo el paisaje al final del d\u00eda. La Tierra nos habla, \u00a1De t\u00e1ntas maneras! Nunca supimos administrar de manera adecuada todo lo que el planeta nos ofrec\u00eda para nuestro sustento, y, ambiciosos, esquilmamos bosques y debastamos el medio natural para obtener m\u00e1s de lo que, en realidad, necesitamos.<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/4.bp.blogspot.com\/-ghHhZ5KJ4JU\/WAZHe8EbbUI\/AAAAAAAACEI\/_GV4IF5k4_4Ov-u8hF4dSPib7TuPTEXzwCLcB\/s1600\/IMG_8401.JPG\" alt=\"Resultado de imagen de la imaginaci\u00f3n que te transporta a otro mundo sin salir de este\" width=\"304\" height=\"228\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<\/div>\n<div style=\"text-align: justify;\">\u00bfQue es la Belleza? \u00a1Est\u00e1 configurada de tantas formas, movimientos, colores y sabores! Tambi\u00e9n de sensaciones y rumores que te pueden transportar\u2026 simplemente imaginando, a otros mundos sin salir de nuestro que nos muestra \u00a1t\u00e1ntos escenarios! Los rincones que podemos contemplar en nuestro planeta son el exponente de lo que en otros mundos podr\u00edamos encontrar. Aqu\u00ed encontramos lugares imposibles y paisajes yermos, y, de la misma manera, podemos viajar a lugares que, con su nextrema belleza natural nos deja sin respiraci\u00f3n. Claro que, en todo esto, hay algo que no funciona y que, seg\u00fan creo, fue el peor invento que pudimos hacer: \u00a1El dinero!<\/div>\n<div style=\"text-align: justify;\"><img decoding=\"async\" src=\"http:\/\/comps.fotosearch.com\/bigcomps\/IMP\/IMP003\/INGSAHE1623.jpg\" alt=\"\" \/><\/div>\n<div style=\"text-align: justify;\">\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Arriba: El M<strong>AL del MUNDO<\/strong><\/div>\n<div style=\"text-align: justify;\"><strong><br \/>\n<\/strong><\/div>\n<div style=\"text-align: justify;\"><img decoding=\"async\" src=\"http:\/\/comps.fotosearch.com\/bigcomps\/IGS\/IGS115\/EV018-018.jpg\" alt=\"\" \/><\/div>\n<div style=\"text-align: justify;\">Sin embargo, escenas \u00e9sta, nos hacen olvidar la maldad. Estamos contemplando la mejor y m\u00e1s pura im\u00e1gen del ser humano..lo que nos hace mejor.<\/div>\n<div style=\"text-align: justify;\">Me encantar\u00eda explicaros todas las im\u00e1genes que siguen a continuaci\u00f3n pero no tenemos el tiempo necesario ni es aqu\u00ed d\u00f3nde procede hacer ese que reuerir\u00eda un extenso libro. De todas las maneras, os dejo escrito algunos pensamientos relacionados con ellas y con nosotros. Pero, de todas las maneras ve\u00e1moslas.<\/div>\n<p style=\"text-align: justify;\"><img decoding=\"async\" src=\"http:\/\/www.hola.com\/imagenes\/actualidad\/2010060414523\/imagenes\/universo\/nasa\/0-35-284\/02sol--a.jpg\" alt=\"\" \/><\/p>\n<div style=\"text-align: justify;\"><img decoding=\"async\" src=\"http:\/\/www.hola.com\/imagenes\/actualidad\/2010060414523\/imagenes\/universo\/nasa\/0-35-293\/11mariposa--a.jpg\" alt=\"\" \/><img decoding=\"async\" src=\"http:\/\/www.hola.com\/imagenes\/actualidad\/2010060414523\/imagenes\/universo\/nasa\/0-35-290\/08andromeda--a.jpg\" alt=\"\" \/><img decoding=\"async\" src=\"http:\/\/www.hola.com\/imagenes\/actualidad\/2010060414523\/imagenes\/universo\/nasa\/0-35-283\/01estrella--a.jpg\" alt=\"\" \/><img decoding=\"async\" src=\"http:\/\/www.hola.com\/imagenes\/actualidad\/2010060414523\/imagenes\/universo\/nasa\/0-35-292\/10agujeros--a.jpg\" alt=\"\" \/><img decoding=\"async\" src=\"http:\/\/www.hola.com\/imagenes\/actualidad\/2010060414523\/imagenes\/universo\/nasa\/0-35-286\/04cassiopeia--a.jpg\" alt=\"\" \/><img decoding=\"async\" src=\"http:\/\/www.hola.com\/imagenes\/actualidad\/2010060414523\/imagenes\/universo\/nasa\/0-35-289\/07nebulosa---a.jpg\" alt=\"La Galaxia Remolino se localiza en la constelaci\u00f3n del perro cazador. Descubierta en 1773, es una de las galaxias espirales m\u00e1s conocidas del firmamento\" \/><img decoding=\"async\" src=\"http:\/\/www.hola.com\/imagenes\/actualidad\/2010060414523\/imagenes\/universo\/nasa\/0-35-295\/13sombrero--a.jpg\" alt=\"\" \/><img decoding=\"async\" src=\"http:\/\/www.hola.com\/imagenes\/actualidad\/2010060414523\/imagenes\/universo\/nasa\/0-35-296\/14galaxia--a.jpg\" alt=\"\" \/><img decoding=\"async\" src=\"http:\/\/www.hola.com\/imagenes\/actualidad\/2010060414523\/imagenes\/universo\/nasa\/0-35-297\/15starburst--a.jpg\" alt=\"\" \/><img decoding=\"async\" src=\"http:\/\/www.hola.com\/imagenes\/actualidad\/2010060414523\/imagenes\/universo\/nasa\/0-35-805\/12jetcarina--a.jpg\" alt=\"\" \/><img decoding=\"async\" src=\"http:\/\/www.hola.com\/imagenes\/actualidad\/2010060414523\/imagenes\/universo\/nasa\/0-35-683\/17formacion--a.jpg\" alt=\"\" \/><img decoding=\"async\" src=\"http:\/\/upload.wikimedia.org\/wikipedia\/commons\/thumb\/6\/69\/MarsSunset.jpg\/779px-MarsSunset.jpg\" alt=\"Archivo:MarsSunset.jpg\" \/><\/div>\n<div style=\"text-align: justify;\">\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00bf Desde qu\u00e9 planeta estamos viendo el Sol?<\/div>\n<div>\n<div>\n<div>\n<p style=\"text-align: justify;\">Hay quien cree que la Tierra podr\u00eda ser tragada por <a href=\"http:\/\/www.emiliosilveravazquez.com\/blog\/2014\/08\/06\/#\"><a href=\"#\" onclick=\"referencia('agujero negro',event); return false;\">agujero negro<\/a><\/a>. Sin embargo, la posibilidad es muy escasa, dir\u00eda que casi nula por completo. Treinta mil a\u00f1os-luz nos separan del Centro Gal\u00e1ctico donde reside un Agunero negro que se traga todo lo que por all\u00ed pase, pero que su fuerza de atracci\u00f3n nos afecte\u2026 Va a ser que no.<\/p>\n<div>\n<p style=\"text-align: justify;\"><img decoding=\"async\" loading=\"lazy\" id=\"irc_mi\" src=\"http:\/\/www.surastronomico.com\/imagenes\/i_noticias_2009\/Chandra_20091002_2.jpg\" alt=\"\" width=\"515\" height=\"393\" \/><\/p>\n<p style=\"text-align: justify;\">Los rayos Gamma son los <a href=\"http:\/\/www.emiliosilveravazquez.com\/blog\/2014\/08\/06\/#\"><a href=\"#\" onclick=\"referencia('foton',event); return false;\">fotones<\/a><\/a> m\u00e1s energ\u00e9ticos conocidos, \u00bfSer\u00e1 ese nuestro final? \u00a1Convertirnos en pura energ\u00eda! Bueno, sabemos que aparecen en las explosiones de supernovas y en otros sucesos similares. \u00bfSeremos nosotros alg\u00fan d\u00eda fuentes de luz conscientes?<\/p>\n<div>\n<p style=\"text-align: justify;\"><img decoding=\"async\" loading=\"lazy\" src=\"http:\/\/image.slidesharecdn.com\/tema3nuestrolugareneluniversoii-120214160444-phpapp02\/95\/tema-3-nuestro-lugar-en-el-universo-ii-11-728.jpg?cb=1329236647\" alt=\"Resultado de imagen de \u00bfSabremos alguna vez comprender d\u00f3nde estamos y para qu\u00e9?\" width=\"304\" height=\"228\" \/><\/p>\n<p style=\"text-align: justify;\">\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00bfSabremos alguna vez comprender d\u00f3nde estamos y para qu\u00e9?<\/p>\n<div>\n<p style=\"text-align: justify;\">\u00a1Es tan grande el Universo! \u00bfPodremos comprenderlo alguna vez? Sabemos que el Universo es todo lo que existe incluyendo la materia y el Espaciotiempo. Sin embargo, lo que no podemos saber (con plena certeza) es empez\u00f3 todo ni c\u00f3mo terminar\u00e1. Tampoco podemos dar una explicaci\u00f3n de si el universo est\u00e1 s\u00f3lo o, por el contrario, deambula acompa\u00f1ado por otros universos por un inmenso Metacosmos que engloba m\u00faltiples universos.<\/p>\n<p style=\"text-align: justify;\">Hemos puesto una serie de im\u00e1genes ah\u00ed arriba que quiere significar la diversidad que en el Universo existe, y, ni se pueden incluir todos los ejemplos que nos gustar\u00eda ni tampoco los tenemos a mano, ya que, la mayor\u00eda de los que podr\u00edamos poner, no est\u00e1n a nuestro alcance ni al alcance de nuestras tecnolog\u00edas.<\/p>\n<p style=\"text-align: justify;\">El Universo contin\u00faa, en muchos aspectos, siendo un gran misterio que pretendemos desvelar, pero como nos dec\u00eda hace unos d\u00edas Max Planck, el problema est\u00e1 en que nosotros, en \u00faltimo t\u00e9rmino, formamos parte de ese misterio que pretendemos .<\/p>\n<p style=\"text-align: justify;\">Por ah\u00ed arriba podemos contemplar im\u00e1genes de bonitos paisajes de la Tierra cambiante, del Sol y de Nebulosas y galaxias. Tambi\u00e9n de algunos seres humanos a los que el Universo, les ha otorgado el don de pensar (aunque no siempre lo demostremos). Algunas im\u00e1genes son de explosiones luminosos que nos ense\u00f1an y muestran las mayores energ\u00edas que en el Universo se pueden generar, a trav\u00e9s de explosiones de supernovas que son fuentes de potentes <a href=\"http:\/\/www.emiliosilveravazquez.com\/blog\/2014\/08\/06\/#\"><a href=\"#\" onclick=\"referencia('gamma rayos',event); return false;\">rayos gamma<\/a><\/a>.<\/p>\n<p style=\"text-align: justify;\"><img decoding=\"async\" id=\"irc_mi\" src=\"http:\/\/1.bp.blogspot.com\/-3zEiyaVvEqU\/UBXQE1aqEUI\/AAAAAAAAATY\/RhXR07sGPys\/s1600\/%3Ca%20href=\" alt=\"\" \/><\/p>\n<p style=\"text-align: justify;\">\u00a0 \u00a0 \u00a0 \u00a0 \u00bfPlasma de Quarks-Gluones? No cejamos en nuestro empe\u00f1o de saber que es\u2026 \u00a1la materia!<\/p>\n<p style=\"text-align: justify;\">La Materia y sus componentes han sido y son el objeto de muchos investigadores y pensadores que quieren profundizar y saber el por qu\u00e9, a partir de lo que llamamos materia inerte, pudo surgir, mediante cambios producidos en muy especiales\u2026\u00a1La Vida!<\/p>\n<p style=\"text-align: justify;\">Nos encontramos con el problema de la posible existencia de eso que llaman \u201c<a href=\"http:\/\/www.emiliosilveravazquez.com\/blog\/2014\/08\/06\/#\"><a href=\"#\" onclick=\"referencia('materia oscura',event); return false;\">materia oscura<\/a><\/a>\u201d, y, a primera vista, puede parecer que la <a href=\"http:\/\/www.emiliosilveravazquez.com\/blog\/2014\/08\/06\/#\"><a href=\"#\" onclick=\"referencia('materia oscura',event); return false;\">materia oscura<\/a><\/a> es s\u00f3lo una peque\u00f1a pieza del enorme rompecabezas que resulta ser nuestro universo, un par\u00e1metro m\u00e1s, ni m\u00e1s ni menos importante que tantas otras. Claro que, este ser\u00eda un punto de vista razonable si la <a href=\"http:\/\/www.emiliosilveravazquez.com\/blog\/2014\/08\/06\/#\"><a href=\"#\" onclick=\"referencia('materia oscura',event); return false;\">materia oscura<\/a><\/a> s\u00f3lo formase una peque\u00f1a del Universo. En ese caso, la podr\u00edamos considerar como poco m\u00e1s que una nota a pie de p\u00e1gina de la materia luminosa, m\u00e1s importante, ya que, de ella, estamos hecho nosotros. Adem\u00e1s, es mucho m\u00e1s f\u00e1cil detectar la materia Bari\u00f3nica hecha de Quarks y Leptones que esa otra que, ni sabemos de qu\u00e9 estar\u00e1 hecha.<\/p>\n<p style=\"text-align: justify;\">Sin embargo, ese punto de vista estar\u00eda equivocado, toda vez que, seg\u00fan todos los indicios, esa \u201c<a href=\"http:\/\/www.emiliosilveravazquez.com\/blog\/2014\/08\/06\/#\"><a href=\"#\" onclick=\"referencia('materia oscura',event); return false;\">materia oscura<\/a><\/a>\u201d supone casi el total del Universo junto con la \u201cenerg\u00eda Oscura\u201d, es decir, m\u00e1s del 90% de la materia-energ\u00eda del universo, es oscura. Puede que las brillantes espirales de las Galaxias sirvan simplemente marcadores pasivos, testimonios mudos de fuerzas que operan en un nivel invisible para nosotros.<\/p>\n<p style=\"text-align: justify;\"><img decoding=\"async\" src=\"http:\/\/2.bp.blogspot.com\/-3ANtOkdgUQw\/UFYqwpdLG2I\/AAAAAAAACDU\/DS_n2mZoDeU\/s1600\/Tiempo.jpg\" alt=\"\" \/><\/p>\n<p style=\"text-align: justify;\">\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 El Universo y la Vida\u2026 El Tiempo que inexorable pasa\u2026<\/p>\n<p style=\"text-align: justify;\">Es posible que, cuando sepamos m\u00e1s sobre nuestro Universo reconozcamos que nuestros conocimientos del universo visible, tan dif\u00edcilmente obtenidos, son poco m\u00e1s que el primer paso en el camino hacia la comprensi\u00f3n de c\u00f3mo son en realidad las cosas. Muchas de las nuevas teor\u00edas tratan de buscar nuevos caminos que divergen de los que seguimos y, buscando por otros lugares no explorados, es posible, s\u00f3lo posible que, podamos encontrar algunas respuestas que nos son negadas en las teor\u00edas actuales.<\/p>\n<p style=\"text-align: justify;\">Es inquietante que, a estas alturas, con seguridad, ning\u00fan Astr\u00f3nomo sepa darnos una respuesta fiel de c\u00f3mo se pudieron formar las Galaxias, y, todos, sin excepci\u00f3n, nos responden con hip\u00f3tesis y conjeturas que, de ninguna manera, podemos asimilar a la realidad de como fueron las cosas en aquellos comienzos del Universo.<\/p>\n<p style=\"text-align: justify;\">\u00bfQu\u00e9 fuerzas ocultas estaban ah\u00ed presentes para posible que las galaxias se pudieran conformar, y formarse los c\u00famulos de galaxias antes de que, la materia recien creada, se dispersara por todo el universo sin m\u00e1s? Seguramente, esa fuerza no podr\u00eda ser otra que la generada por la Materia Oscura que, a decir verdad, podr\u00eda ser la materia primaria que permea todo el Universo y, a partir de la cual, se puede estar formando (al evolucionar) la materia que s\u00ed podemos ver.<\/p>\n<p style=\"text-align: justify;\"><img decoding=\"async\" loading=\"lazy\" id=\"irc_mi\" src=\"http:\/\/3.bp.blogspot.com\/-vKr597DqLXs\/T38hTOjhIVI\/AAAAAAAAANY\/FpUF1Eunep4\/s1600\/429965_233747843387085_100002556147242_453316_305818471_n.jpg\" alt=\"\" width=\"524\" height=\"393\" \/><\/p>\n<p style=\"text-align: justify;\">A m\u00ed todo esto me sobrepasa, y, \u201cconociendo\u201d de qu\u00e9 est\u00e1 formada la materia de la que est\u00e1n hechas las estrellas y las monta\u00f1as, los r\u00edos y los oc\u00e9anos, o los delfines y tambi\u00e9n nosotros, no deja de sorprenderme (m\u00e1s bien maravillarme) que, de esa materia pudieran surgir seres vivos y que, algunos, como nosotros mismos, podamos pensar y ser conscientes de toda esta grandeza.<\/p>\n<p style=\"text-align: justify;\">Alguna vez, hemos podido sentirnos en un estado de euforia al sentirnos los \u201camos\u201d del universo, nuestros conocimientos nos hacen grandes y, posiblemente, nada se resistir\u00e1 ante tanta sabidur\u00eda. Sin embargo, ese estado de \u201cgracia\u201d suele durarnos muy poco. De inmediato caemos en la de que, la realidad, es muy distinta y recordamos lo que nos dijeron aquellos grandes pensadores como S\u00f3crates. Plat\u00f3n y m\u00e1s cercano a nosotros Popper: \u201cNuestro conocimiento es limitado, nuestra ignorancia infinita\u201d. Y, lo malo de dicha conclusi\u00f3n, es que era, y, sigue siendo cierta.<\/p>\n<p style=\"text-align: justify;\">As\u00ed que, amigos m\u00edos, procuremos aprender, enterarnos de las cosas, ser conscientes de lo que no sabemos y, sobre todo, procurar entender lo que en la Naturaleza ocurre, ella siempre nos marca el camino a seguir pero, nosotros, no siempre prestamos la debida atenci\u00f3n.<\/p>\n<p style=\"text-align: justify;\">emilio silvera<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class='bookmark'>\r\n\t\t<table align='left' border='0' cellpadding='0' width='100%'>\r\n\t\t<tr><td><span class='pushbutton'><a href='http:\/\/delicious.com\/post?url=http%3A%2F%2Fwww.emiliosilveravazquez.com%2Fblog%2F2017%2F03%2F01%2Fsi-%25c2%25a1todo-es-universo-4%2F&amp;title=S%C3%AD%2C+%C2%A1todo+es+Universo%21' title='Delicious' target='_blank' rel='nofollow'><img src='http:\/\/www.emiliosilveravazquez.com\/blog\/wp-content\/plugins\/knxdt-bookmarks-wordpress-plugin\/images\/delicious.png'  alt='' class='book_img' border='none' style='margin:1px; padding: 0;'  \/><\/a><\/span><span class='pushbutton'><a href='http:\/\/digg.com\/submit?url=http%3A%2F%2Fwww.emiliosilveravazquez.com%2Fblog%2F2017%2F03%2F01%2Fsi-%25c2%25a1todo-es-universo-4%2F&amp;title=S%C3%AD%2C+%C2%A1todo+es+Universo%21' title='Digg' target='_blank' rel='nofollow'><img src='http:\/\/www.emiliosilveravazquez.com\/blog\/wp-content\/plugins\/knxdt-bookmarks-wordpress-plugin\/images\/digg.png'  alt='' class='book_img' border='none' style='margin:1px; padding: 0;'  \/><\/a><\/span><span class='pushbutton'><a href='http:\/\/www.google.com\/bookmarks\/mark?op=edit&amp;bkmk=http%3A%2F%2Fwww.emiliosilveravazquez.com%2Fblog%2F2017%2F03%2F01%2Fsi-%25c2%25a1todo-es-universo-4%2F&amp;title=S%C3%AD%2C+%C2%A1todo+es+Universo%21' title='Google' target='_blank' rel='nofollow'><img src='http:\/\/www.emiliosilveravazquez.com\/blog\/wp-content\/plugins\/knxdt-bookmarks-wordpress-plugin\/images\/google.png'   alt='' class='book_img' border='none' style='margin:1px; padding: 0;'  \/><\/a><\/span><span class='pushbutton'><a href='http:\/\/myweb2.search.yahoo.com\/myresults\/bookmarklet?u=http%3A%2F%2Fwww.emiliosilveravazquez.com%2Fblog%2F2017%2F03%2F01%2Fsi-%25c2%25a1todo-es-universo-4%2F&amp;t=S%C3%AD%2C+%C2%A1todo+es+Universo%21' title='Yahoo' target='_blank' rel='nofollow'><img src='http:\/\/www.emiliosilveravazquez.com\/blog\/wp-content\/plugins\/knxdt-bookmarks-wordpress-plugin\/images\/yahoo.png'  alt='' class='book_img' border='none' style='margin:1px; padding: 0;'  \/><\/a><\/span><span class='pushbutton'><a href='http:\/\/www.technorati.com\/faves?add=http%3A%2F%2Fwww.emiliosilveravazquez.com%2Fblog%2F2017%2F03%2F01%2Fsi-%25c2%25a1todo-es-universo-4%2F' title='Technorati' target='_blank' rel='nofollow'><img src='http:\/\/www.emiliosilveravazquez.com\/blog\/wp-content\/plugins\/knxdt-bookmarks-wordpress-plugin\/images\/technorati.png'  alt='' class='book_img' border='none' style='margin:1px; padding: 0;'  \/><\/a><\/span><span class='pushbutton'><a href='http:\/\/meneame.net\/submit.php?url=http%3A%2F%2Fwww.emiliosilveravazquez.com%2Fblog%2F2017%2F03%2F01%2Fsi-%25c2%25a1todo-es-universo-4%2F' title='Meneame' target='_blank' rel='nofollow'><img src='http:\/\/www.emiliosilveravazquez.com\/blog\/wp-content\/plugins\/knxdt-bookmarks-wordpress-plugin\/images\/meneame.png'  alt='' class='book_img' border='none' style='margin:1px; padding: 0;'  \/><\/a><\/span><span class='pushbutton'><a href='http:\/\/enchilame.com\/submit.php?url=http:\/\/www.emiliosilveravazquez.com\/blog\/2017\/03\/01\/si-%c2%a1todo-es-universo-4\/' target='_blank' rel='nofollow'><img title='Enchilame' src='http:\/\/www.emiliosilveravazquez.com\/blog\/wp-content\/plugins\/knxdt-bookmarks-wordpress-plugin\/images\/enchilame.png'  alt='' class='book_img' border='none' style='margin:1px; padding: 0;'  \/><\/a><\/span><span class='pushbutton'><a href='http:\/\/www.blinklist.com\/index.php?Action=Blink\/addblink.php&amp;Description=&amp;Url=http%3A%2F%2Fwww.emiliosilveravazquez.com%2Fblog%2F2017%2F03%2F01%2Fsi-%25c2%25a1todo-es-universo-4%2F&amp;title=S%C3%AD%2C+%C2%A1todo+es+Universo%21' title='BlinkList' target='_blank' rel='nofollow'><img src='http:\/\/www.emiliosilveravazquez.com\/blog\/wp-content\/plugins\/knxdt-bookmarks-wordpress-plugin\/images\/blinklist.png'  alt='' class='book_img' border='none' style='margin:1px; padding: 0;'  \/><\/a><\/span><span class='pushbutton'><a href='http:\/\/reddit.com\/submit?url=http%3A%2F%2Fwww.emiliosilveravazquez.com%2Fblog%2F2017%2F03%2F01%2Fsi-%25c2%25a1todo-es-universo-4%2F&amp;title=S%C3%AD%2C+%C2%A1todo+es+Universo%21' title='Reddit' target='_blank' rel='nofollow'><img src='http:\/\/www.emiliosilveravazquez.com\/blog\/wp-content\/plugins\/knxdt-bookmarks-wordpress-plugin\/images\/reddit.png'  alt='' class='book_img' border='none' style='margin:1px; padding: 0;'  \/><\/a><\/span><span class='pushbutton'><a href='http:\/\/www.tecnologiadiaria.com\/2009\/07\/abrir-com-hotmail-correo.html' target='_blank' title='hotmail'><img src='http:\/\/www.emiliosilveravazquez.com\/blog\/wp-content\/plugins\/knxdt-bookmarks-wordpress-plugin\/images\/linklove.png' alt='hotmail correo' class='book_img' border='none' style='margin:1px; padding: 0;' \/><\/a><\/span><span class='pushbutton'><a href='http:\/\/bitacoras.com\/votar\/anotacion\/externo\/mini\/www.emiliosilveravazquez.com\/blog\/2017\/03\/01\/si-%c2%a1todo-es-universo-4\/' title='Bitacoras.com' target='_blank' rel='nofollow'><img src='http:\/\/www.emiliosilveravazquez.com\/blog\/wp-content\/plugins\/knxdt-bookmarks-wordpress-plugin\/images\/bitacoras.png'  alt='' class='book_img' border='none' style='margin:1px; padding: 0;'  \/><\/a><\/span><span class='pushbutton'><a href='http:\/\/www.wikio.es\/vote?url=http%3A%2F%2Fwww.emiliosilveravazquez.com%2Fblog%2F2017%2F03%2F01%2Fsi-%25c2%25a1todo-es-universo-4%2F' title='Wikio' target='_blank' rel='nofollow'><img src='http:\/\/www.emiliosilveravazquez.com\/blog\/wp-content\/plugins\/knxdt-bookmarks-wordpress-plugin\/images\/wikio.png'   alt='' class='book_img' border='none' style='margin:1px; padding: 0;'   \/><\/a><\/span><span class='pushbutton'><a href='http:\/\/friendfeed.com\/?url=http%3A%2F%2Fwww.emiliosilveravazquez.com%2Fblog%2F2017%2F03%2F01%2Fsi-%25c2%25a1todo-es-universo-4%2F&amp;title=S%C3%AD%2C+%C2%A1todo+es+Universo%21' title='Friend Feed' target='_blank' rel='nofollow'><img src='http:\/\/www.emiliosilveravazquez.com\/blog\/wp-content\/plugins\/knxdt-bookmarks-wordpress-plugin\/images\/friendfeed.png'  alt='' class='book_img' border='none' style='margin:1px; padding: 0;'  \/><\/a><\/span><span class='pushbutton'><a href='http:\/\/www.facebook.com\/share.php?u=http%3A%2F%2Fwww.emiliosilveravazquez.com%2Fblog%2F2017%2F03%2F01%2Fsi-%25c2%25a1todo-es-universo-4%2F&amp;t=S%C3%AD%2C+%C2%A1todo+es+Universo%21' title='Facebook' target='_blank' rel='nofollow'><img src='http:\/\/www.emiliosilveravazquez.com\/blog\/wp-content\/plugins\/knxdt-bookmarks-wordpress-plugin\/images\/facebook.png'  alt='' class='book_img' border='none' style='margin:1px; padding: 0;'  \/><\/a><\/span><span class='pushbutton'><a href='http:\/\/twitter.com\/home?status=S%C3%AD%2C+%C2%A1todo+es+Universo%21: http%3A%2F%2Fwww.emiliosilveravazquez.com%2Fblog%2F2017%2F03%2F01%2Fsi-%25c2%25a1todo-es-universo-4%2F' title='Twitter' target='_blank' rel='nofollow'><img src='http:\/\/www.emiliosilveravazquez.com\/blog\/wp-content\/plugins\/knxdt-bookmarks-wordpress-plugin\/images\/twitter.png'  alt='' class='book_img' border='none' style='margin:1px; padding: 0;'  \/><\/a><\/span><span class='pushbutton'><a href='http:\/\/www.feedburner.com\/fb\/a\/emailFlare?itemTitle=S%C3%AD%2C+%C2%A1todo+es+Universo%21&amp;uri=http%3A%2F%2Fwww.emiliosilveravazquez.com%2Fblog%2F2017%2F03%2F01%2Fsi-%25c2%25a1todo-es-universo-4%2F' title='Enviar por Email' target='_blank' rel='nofollow'><img src='http:\/\/www.emiliosilveravazquez.com\/blog\/wp-content\/plugins\/knxdt-bookmarks-wordpress-plugin\/images\/email.png'  alt='' class='book_img' border='none' style='margin:1px; padding: 0;'  \/><\/a><\/span><span style='font-weight:bold; padding-left: 5px;'><a href='http:\/\/wordpress.org\/extend\/plugins\/knxdt-bookmarks-wordpress-plugin\/' title='Plugin' rel='nofollow' target='_blank'>[?]<\/a><\/span><\/td><\/tr><\/table><br\/><br\/><\/div>","protected":false},"excerpt":{"rendered":"<p>\u00a0 \u00a0La necesidad agudiza la imaginaci\u00f3n &nbsp; Si existen las estrellas de Quarks, tendr\u00edan una densidad intermedia entre las estrellas de Neutrones y los Agujeros Negros Si bien no se han observado objetos que puedan ser asociados a estrellas compuestas completamente de quarks, la existencia de quarks desconfinados en el interior de estrellas de neutrones [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_s2mail":"yes","footnotes":""},"categories":[49],"tags":[],"_links":{"self":[{"href":"http:\/\/www.emiliosilveravazquez.com\/blog\/wp-json\/wp\/v2\/posts\/17279"}],"collection":[{"href":"http:\/\/www.emiliosilveravazquez.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.emiliosilveravazquez.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.emiliosilveravazquez.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/www.emiliosilveravazquez.com\/blog\/wp-json\/wp\/v2\/comments?post=17279"}],"version-history":[{"count":0,"href":"http:\/\/www.emiliosilveravazquez.com\/blog\/wp-json\/wp\/v2\/posts\/17279\/revisions"}],"wp:attachment":[{"href":"http:\/\/www.emiliosilveravazquez.com\/blog\/wp-json\/wp\/v2\/media?parent=17279"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.emiliosilveravazquez.com\/blog\/wp-json\/wp\/v2\/categories?post=17279"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.emiliosilveravazquez.com\/blog\/wp-json\/wp\/v2\/tags?post=17279"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}